{"id":1454,"date":"2017-03-27T18:46:50","date_gmt":"2017-03-27T18:46:50","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1454"},"modified":"2017-03-27T18:46:50","modified_gmt":"2017-03-27T18:46:50","slug":"thank-to-solar-system","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/03\/27\/thank-to-solar-system\/","title":{"rendered":"THANK YOU FOR THIS INCREDIBLE SOLAR SYSTEM"},"content":{"rendered":"<p>Muchas gracias a la familia de Isabel, por el fabuloso Sistema Solar que han hecho para el Colegio, con \u00e9l va a ser m\u00e1s f\u00e1cil conocer el Universo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3573\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg\" alt=\"\" width=\"557\" height=\"418\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg 1296w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-768x576.jpg 768w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchas gracias a la familia de Isabel, por el fabuloso Sistema Solar que han hecho para el Colegio, con \u00e9l va a ser m\u00e1s f\u00e1cil conocer el Universo.<\/p>\n","protected":false},"author":3,"featured_media":3573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-1454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4-primaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",1296,972,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",1296,972,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",1296,972,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-300x225.jpg",300,225,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-1024x768.jpg",525,394,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",500,375,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",1296,972,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",1296,972,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",1296,972,false],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",360,270,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",320,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/03\/IMG-20170327-WA0016.jpg",1296,972,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/4-primaria\/\" rel=\"category tag\">4\u00ba Primaria<\/a>","rttpg_excerpt":"Muchas gracias a la familia de Isabel, por el fabuloso Sistema Solar que han hecho para el Colegio, con \u00e9l va a ser m\u00e1s f\u00e1cil conocer el Universo.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1454"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3573"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1454"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}