{"id":1547,"date":"2017-05-14T06:52:19","date_gmt":"2017-05-14T06:52:19","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1547"},"modified":"2017-05-14T06:52:19","modified_gmt":"2017-05-14T06:52:19","slug":"voluntariado-y-participacion-social","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/05\/14\/voluntariado-y-participacion-social\/","title":{"rendered":"NUESTRAS ACCIONES PUEDEN CAMBIAR EL ENTORNO: CHARLA SOBRE VOLUNTARIADO Y PARTICIPACI\u00d3N SOCIAL"},"content":{"rendered":"<p>La clase de 4\u00baA, participo el viernes 12 de mayo en las sesiones formativas sobre voluntariado y participaci\u00f3n social, de la Cruz Roja, que tiene como finalidad sensibilizar a la infancia y a la adolescencia sobre la necesidades de implicarse en los problemas del mundo y ejercer la solidaridad desde edades tempranas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3658\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg\" alt=\"\" width=\"314\" height=\"419\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg 972w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-300x400.jpg 300w\" sizes=\"auto, (max-width: 314px) 100vw, 314px\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3659\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0083.jpg\" alt=\"\" width=\"314\" height=\"419\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0083.jpg 972w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0083-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0083-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0083-300x400.jpg 300w\" sizes=\"auto, (max-width: 314px) 100vw, 314px\" \/><\/p>\n<p>B\u00e1rbara, de la Cruz\u00a0Roja Espa\u00f1ola, fue la encargada de dar esta charla informativa para sensibilizar a los ni\u00f1os y ni\u00f1as del significado del voluntariado y el valor de compromiso con los dem\u00e1s. En estas charlas se abordaron diversas \u00e1reas de actuaci\u00f3n donde se puede ejercer el voluntariado como son las relacionadas con discapacidad, infancia, pobreza, mayores o medio ambiente. Los alumnos\/as reflexionaron y analizaron las distintas necesidades sociales que surgen a nuestro alrededor cada d\u00eda, y c\u00f3mo podemos colaborar en la construcci\u00f3n de un mundo m\u00e1s humano.\u00a0<\/p>\n<p>La sesi\u00f3n comenz\u00f3 con una presentaci\u00f3n, a cargo de B\u00e1rbara (quienes somos y por qu\u00e9 estamos hoy aqu\u00ed), para dar paso luego al an\u00e1lisis de conceptos como Solidaridad, Participaci\u00f3n, Voluntariado, Humanidad, &#8230;., continuaron debatiendo c\u00f3mo se puede ser solidario a su edad y que c\u00f3mo podemos participar\/colaborar con la Cruz Roja y otras entidades locales y de la zona.<\/p>\n<p>Toda est\u00e1 sesi\u00f3n, dur\u00f3 80 minutos, y gir\u00f3 entorno a la idea de \u00abnuestras acciones, por peque\u00f1as que parezcan, pueden cambiar el entorno y mejorarlo y as\u00ed colaborar en la construcci\u00f3n de un mundo m\u00e1s humano. \u00a0<\/p>\n<p>Lo \u00faltimo que realizamos en este taller de voluntariado, fue un dibujo para poder transmitirle a las familias y amigos lo aprendido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La clase de 4\u00baA, participo el viernes 12 de mayo en las sesiones formativas sobre voluntariado y participaci\u00f3n social, de la Cruz Roja, que tiene como finalidad sensibilizar a la infancia y a la adolescencia sobre la necesidades de implicarse en los problemas del mundo y ejercer la solidaridad desde edades tempranas. B\u00e1rbara, de la &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/05\/14\/voluntariado-y-participacion-social\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNUESTRAS ACCIONES PUEDEN CAMBIAR EL ENTORNO: CHARLA SOBRE VOLUNTARIADO Y PARTICIPACI\u00d3N SOCIAL\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":3658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-1547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4-primaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",972,1296,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",972,1296,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",972,1296,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-225x300.jpg",225,300,true],"large":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-768x1024.jpg",525,700,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",375,500,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",972,1296,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",972,1296,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-972x1200.jpg",972,1200,true],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-100x100.jpg",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",357,476,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",180,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170512-WA0085.jpg",972,1296,false]},"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/4-primaria\/\" rel=\"category tag\">4\u00ba Primaria<\/a>","rttpg_excerpt":"La clase de 4\u00baA, participo el viernes 12 de mayo en las sesiones formativas sobre voluntariado y participaci\u00f3n social, de la Cruz Roja, que tiene como finalidad sensibilizar a la infancia y a la adolescencia sobre la necesidades de implicarse en los problemas del mundo y ejercer la solidaridad desde edades tempranas. B\u00e1rbara, de la&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1547"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media\/3658"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1547"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}