{"id":1551,"date":"2017-05-19T05:49:28","date_gmt":"2017-05-19T05:49:28","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1551"},"modified":"2017-05-19T05:49:28","modified_gmt":"2017-05-19T05:49:28","slug":"recta-final-para-el-viii-cross-carlos-iii","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/05\/19\/recta-final-para-el-viii-cross-carlos-iii\/","title":{"rendered":"RECTA FINAL PARA EL VIII CROSS CARLOS III"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/C_iUu3nXsAIYVsT.jpg:large\" alt=\"\" width=\"549\" height=\"309\" \/><\/p>\n<p>Este domingo celebramos, nuestro VIII Cross, ya estamos preparando las bolsas y los detalles que se le van a dar todos los participantes, los dorsales ya est\u00e1n repartidos por todos los centros educativos de la localidad, el Ayuntamiento ya nos ha tra\u00eddo las vallas, la polic\u00eda local ha colocado las se\u00f1ales de prohibido aparcar durante todo el recorrido, los ni\u00f1os y ni\u00f1as del Colegio, est\u00e1n preparando una peque\u00f1a sorpresa para los corredores m\u00e1s peque\u00f1os, los speakers est\u00e1n preparando sus discursos y canciones, los organizadores est\u00e1n revisando que no falte ning\u00fan detalle, para que el domingo sea una fiesta del Deporte.<\/p>\n<p>Este a\u00f1o incluimos dos novedades, hemos a\u00f1adido dos pruebas de Marcha N\u00f3rdica, una de adultos y otra infantil, adem\u00e1s durante toda la ma\u00f1ana, la Asociaci\u00f3n de Marcha N\u00f3rdica va estar explicando y mostrando su disciplina deportiva, en las calles cercanas al recorrido y la otra novedad, es que algunos patrocinadores nos han donado premios para un sorteo de regalos que se va a realizar durante la entrega de trofeos, una comida para dos personas y material de deportivo. \u00a0 \u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DAGLP_4UAAAuZrm.jpg:large\" alt=\"\" width=\"186\" height=\"186\" \/><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-3666\" src=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170518-WA0008.jpg\" alt=\"\" width=\"327\" height=\"184\" srcset=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170518-WA0008.jpg 1600w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170518-WA0008-300x169.jpg 300w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170518-WA0008-1024x575.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170518-WA0008-768x432.jpg 768w, https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/05\/IMG-20170518-WA0008-1536x863.jpg 1536w\" sizes=\"auto, (max-width: 327px) 100vw, 327px\" \/><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo celebramos, nuestro VIII Cross, ya estamos preparando las bolsas y los detalles que se le van a dar todos los participantes, los dorsales ya est\u00e1n repartidos por todos los centros educativos de la localidad, el Ayuntamiento ya nos ha tra\u00eddo las vallas, la polic\u00eda local ha colocado las se\u00f1ales de prohibido aparcar durante &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/05\/19\/recta-final-para-el-viii-cross-carlos-iii\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRECTA FINAL PARA EL VIII CROSS CARLOS III\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-1551","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Este domingo celebramos, nuestro VIII Cross, ya estamos preparando las bolsas y los detalles que se le van a dar todos los participantes, los dorsales ya est\u00e1n repartidos por todos los centros educativos de la localidad, el Ayuntamiento ya nos ha tra\u00eddo las vallas, la polic\u00eda local ha colocado las se\u00f1ales de prohibido aparcar durante&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1551"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1551\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1551"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}