{"id":1577,"date":"2017-06-05T11:47:04","date_gmt":"2017-06-05T11:47:04","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1577"},"modified":"2017-06-05T11:47:04","modified_gmt":"2017-06-05T11:47:04","slug":"convocatoria-15-asamblea-pitufos-2","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/06\/05\/convocatoria-15-asamblea-pitufos-2\/","title":{"rendered":"CONVOCATORIA 15\u00aa ASAMBLEA PITUFOS"},"content":{"rendered":"<p>FECHA: martes 6 de junio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 HORA: 12:00<\/p>\n<p>\u00a0<\/p>\n<ul>\n<li>ELECCI\u00d3N JURADO PREMIOS PROMOCI\u00d3N DE LA CONVIVENCIA<\/li>\n<\/ul>\n<p>Se ha creado un jurado para elegir a una persona y a una entidad que fomenta la convivencia dentro del Centro. El jurado tambi\u00e9n est\u00e1 compuesto por uno de los Pitufos, para ello vamos a proceder a la selecci\u00f3n\/votaci\u00f3n.<\/p>\n<ul>\n<li>Explicaci\u00f3n de los Premios de la Convivencia.<\/li>\n<li>Presentaci\u00f3n de los candidatos (explican porque deben ser elegidos por sus compa\u00f1eros para esta funci\u00f3n).<\/li>\n<li>Votaci\u00f3n si fuera necesario.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<ul>\n<li>RUEGOS, PROPUESTAS Y PREGUNTAS<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p><strong>NOTA: ES IMPORTANTE QUE LOS DELEGADOS\/AS Y REPRESENTANTES LLEVEN SUS APORTACIONES POR ESCRITO Y CONSULTE A SUS COMPA\u00d1ER@S LOS PUNTOS QUE SE VAN A TRATAR EN LA ASAMBLEA.<\/strong><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FECHA: martes 6 de junio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 HORA: 12:00 \u00a0 ELECCI\u00d3N JURADO PREMIOS PROMOCI\u00d3N DE LA CONVIVENCIA Se ha creado un jurado para elegir a una persona y a una entidad que fomenta la convivencia dentro del Centro. El jurado tambi\u00e9n est\u00e1 compuesto por uno de los Pitufos, para ello vamos a proceder a la selecci\u00f3n\/votaci\u00f3n. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/06\/05\/convocatoria-15-asamblea-pitufos-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCONVOCATORIA 15\u00aa ASAMBLEA PITUFOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"post_folder":[],"class_list":["post-1577","post","type-post","status-publish","format-standard","hentry","category-actas-y-convocatorias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/actas-y-convocatorias\/\" rel=\"category tag\">Actas y Convocatorias<\/a>","rttpg_excerpt":"FECHA: martes 6 de junio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 HORA: 12:00 \u00a0 ELECCI\u00d3N JURADO PREMIOS PROMOCI\u00d3N DE LA CONVIVENCIA Se ha creado un jurado para elegir a una persona y a una entidad que fomenta la convivencia dentro del Centro. El jurado tambi\u00e9n est\u00e1 compuesto por uno de los Pitufos, para ello vamos a proceder a la selecci\u00f3n\/votaci\u00f3n.&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1577"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1577\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1577"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}