{"id":1592,"date":"2017-06-10T05:30:30","date_gmt":"2017-06-10T05:30:30","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1592"},"modified":"2017-06-10T05:30:30","modified_gmt":"2017-06-10T05:30:30","slug":"graduacion-6-de-primaria","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/06\/10\/graduacion-6-de-primaria\/","title":{"rendered":"GRADUACI\u00d3N 6\u00ba DE PRIMARIA"},"content":{"rendered":"<p>Nuestros chicos y chicas de 6\u00ba Primaria finalizan su andadura en nuestro Centro y celebran su Acto de Graduaci\u00f3n el viernes 16 junio en el Colegio.<\/p>\n<p>Han llevado ya a casa 5 invitaciones por familia para ese d\u00eda. Los ni\u00f1os y ni\u00f1as de 6\u00ba Primaria no necesitan invitaci\u00f3n. Tendr\u00e1n que estar en el centro <strong>a las 18.30 h.<\/strong><\/p>\n<p>La puerta de entrada se abrir\u00e1 a los invitados <strong>a las 18.45 h.<\/strong> y la Ceremonia comenzar\u00e1 <strong>a las 19 h.<\/strong><\/p>\n<p>El programa ser\u00e1 el siguiente:<\/p>\n<ul>\n<li>Musical preparado por los alumnos y alumnas de 6\u00ba \u201c#Atrapad@s en la Red\u201d<\/li>\n<li>Ceremonia de Graduaci\u00f3n.<\/li>\n<li>Luego compartiremos un refrigerio para celebrar un d\u00eda tan importante.<\/li>\n<\/ul>\n<p>Hemos de recordar que <strong>los ni\u00f1os y ni\u00f1as de 6\u00ba de Primaria vendr\u00e1n a la ceremonia con el uniforme, no en ropa de calle.<\/strong><\/p>\n<p>Os rogamos que el lunes traigan dos imperdibles para poner en las becas, los colocaremos aqu\u00ed pues no se van a llevar las becas a casa con antelaci\u00f3n. Se la llevar\u00e1n despu\u00e9s de la ceremonia.<\/p>\n<p>Si surgiera cualquier otra duda estamos a vuestra disposici\u00f3n.<\/p>\n<p>Gracias por todo, un saludo afectuoso.<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Las tutoras de 6\u00ba de Primaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros chicos y chicas de 6\u00ba Primaria finalizan su andadura en nuestro Centro y celebran su Acto de Graduaci\u00f3n el viernes 16 junio en el Colegio. Han llevado ya a casa 5 invitaciones por familia para ese d\u00eda. Los ni\u00f1os y ni\u00f1as de 6\u00ba Primaria no necesitan invitaci\u00f3n. Tendr\u00e1n que estar en el centro a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/06\/10\/graduacion-6-de-primaria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abGRADUACI\u00d3N 6\u00ba DE PRIMARIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-1592","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Nuestros chicos y chicas de 6\u00ba Primaria finalizan su andadura en nuestro Centro y celebran su Acto de Graduaci\u00f3n el viernes 16 junio en el Colegio. Han llevado ya a casa 5 invitaciones por familia para ese d\u00eda. Los ni\u00f1os y ni\u00f1as de 6\u00ba Primaria no necesitan invitaci\u00f3n. Tendr\u00e1n que estar en el centro a&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1592"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}