{"id":1605,"date":"2017-06-18T05:19:54","date_gmt":"2017-06-18T05:19:54","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1605"},"modified":"2017-06-18T05:19:54","modified_gmt":"2017-06-18T05:19:54","slug":"exposicion-lupa-lo-que-la-mirada-adulta-no-ve","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/06\/18\/exposicion-lupa-lo-que-la-mirada-adulta-no-ve\/","title":{"rendered":"EXPOSICI\u00d3N LUPA: LO QUE LA MIRADA ADULTA NO VE."},"content":{"rendered":"<p>Los alumnos\/as de 4\u00baC han estado elaborando un proyecto fotogr\u00e1fico durante los \u00faltimos meses y el martes 20 de junio van a realizar una exposici\u00f3n de sus trabajos en el aula de m\u00fasica, el horario de visitas para las clases es de 09:00 a 13:00 y para las familias de 13:00 a 15:00. Os esperamos.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DCde1amXoAQy8iW.jpg\" alt=\"\" width=\"670\" height=\"339\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos\/as de 4\u00baC han estado elaborando un proyecto fotogr\u00e1fico durante los \u00faltimos meses y el martes 20 de junio van a realizar una exposici\u00f3n de sus trabajos en el aula de m\u00fasica, el horario de visitas para las clases es de 09:00 a 13:00 y para las familias de 13:00 a 15:00. Os esperamos.\u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-1605","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Los alumnos\/as de 4\u00baC han estado elaborando un proyecto fotogr\u00e1fico durante los \u00faltimos meses y el martes 20 de junio van a realizar una exposici\u00f3n de sus trabajos en el aula de m\u00fasica, el horario de visitas para las clases es de 09:00 a 13:00 y para las familias de 13:00 a 15:00. Os esperamos.\u00a0","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1605"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1605\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1605"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}