{"id":1622,"date":"2017-06-27T05:48:27","date_gmt":"2017-06-27T05:48:27","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1622"},"modified":"2017-06-27T05:48:27","modified_gmt":"2017-06-27T05:48:27","slug":"pautas-para-el-verano-5-anos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/06\/27\/pautas-para-el-verano-5-anos\/","title":{"rendered":"PAUTAS PARA EL VERANO (5 A\u00d1OS)"},"content":{"rendered":"<p>Ya llegan las vacaciones y os vamos a dar unas pautas para el verano.<\/p>\n<p>\u00a0 \u00a0Lo m\u00e1s importante es que lean todos los d\u00edas algo. Un poquito, si se cansan podemos leer un poco pap\u00e1 o mam\u00e1 y luego vuestros hijos. Es importante que de vez en cuando les preguntemos sobre lo que leen para que comprendan.<\/p>\n<p>\u00a0 \u00a0Como no hemos terminado el libro de lectoescritura 6, que lo terminen en casa. As\u00ed practican la escritura y la comprensi\u00f3n.<\/p>\n<p>\u00a0 \u00a0Hacer alguna suma y resta.<\/p>\n<p>\u00a0 \u00a0Jugar a juegos de mesa con los que trabajamos muchas cosas: el bingo, el parch\u00eds, la oca, el domin\u00f3, juegos de hundir la flota, conecta 4, qui\u00e9n es qui\u00e9n,&#8230; les encanta.<\/p>\n<p>\u00a0 \u00a0Un verano sin cartas no es verano. Con las cartas pod\u00e9is jugar a muchos juegos: el reloj, las parejas, cinquillo, &#8230; Con ellos trabajamos la serie num\u00e9rica, conteo, atenci\u00f3n &#8230; y encima con los amigos, abuelos, familia, &#8230;<\/p>\n<p>\u00a0 \u00a0Dibujar en folio en blanco, recortar cosas y crear sus propias creaciones.<\/p>\n<p>\u00a0 \u00a0Que escriban de forma espont\u00e1nea y dediquen sus dibujos a alguien o hacerles alg\u00fan dictado de una frase.<\/p>\n<p>\u00a0 \u00a0Pod\u00e9is comprar alg\u00fan cuadernillo de actividades de verano que trabajan todos los contenidos trabajados.<\/p>\n<p>\u00a0 \u00a0Ver dibujos o pelis en ingl\u00e9s.<\/p>\n<p>\u00a0 \u00a0Y sobre todo, disfrutar a tope de vuestros hijos que crecen rapid\u00edsimo.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a1FELIZ VERANO! \u00a0 AURORA, ISA Y BEATRIZ (TUTORAS DE 5 A\u00d1OS)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya llegan las vacaciones y os vamos a dar unas pautas para el verano. \u00a0 \u00a0Lo m\u00e1s importante es que lean todos los d\u00edas algo. Un poquito, si se cansan podemos leer un poco pap\u00e1 o mam\u00e1 y luego vuestros hijos. Es importante que de vez en cuando les preguntemos sobre lo que leen para &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/06\/27\/pautas-para-el-verano-5-anos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPAUTAS PARA EL VERANO (5 A\u00d1OS)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-1622","post","type-post","status-publish","format-standard","hentry","category-5-anos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/5-anos\/\" rel=\"category tag\">5 A\u00f1os<\/a>","rttpg_excerpt":"Ya llegan las vacaciones y os vamos a dar unas pautas para el verano. \u00a0 \u00a0Lo m\u00e1s importante es que lean todos los d\u00edas algo. Un poquito, si se cansan podemos leer un poco pap\u00e1 o mam\u00e1 y luego vuestros hijos. Es importante que de vez en cuando les preguntemos sobre lo que leen para&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1622"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}