{"id":1635,"date":"2017-09-06T05:40:02","date_gmt":"2017-09-06T05:40:02","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1635"},"modified":"2017-09-06T05:40:02","modified_gmt":"2017-09-06T05:40:02","slug":"convocatoria-de-ayudas-para-alumnos-as-con-necesidad-especifica-de-apoyo-2017-2018","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/09\/06\/convocatoria-de-ayudas-para-alumnos-as-con-necesidad-especifica-de-apoyo-2017-2018\/","title":{"rendered":"CONVOCATORIA DE AYUDAS PARA ALUMNOS\/AS CON NECESIDAD ESPEC\u00cdFICA DE APOYO 2017-2018"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>\u00a0<\/p>\n<p>Os informamos a continuaci\u00f3n de la CONVOCATORIA DE AYUDAS PARA ALUMNOS CON NECESIDAD ESPEC\u00cdFICA DE APOYO EDUCATIVO PARA EL CURSO 2017\/2018.<\/p>\n<p>\u00a0<\/p>\n<p>El pasado d\u00eda 12 de agosto se public\u00f3 en el BOE el extracto de la Resoluci\u00f3n de 03 de agosto de 2017 de la Secretar\u00eda de Estado, Formaci\u00f3n Profesional y Universidades, por la que se convocan ayudas para alumnos con necesidad espec\u00edfica de apoyo educativo para el curso 2017\/2018. El texto \u00edntegro de la convocatoria puede consultarse en la Base de Datos Nacional de Subvenciones (http:\/\/www.pap.minhap.gob.es\/bdnstans, identificador 358870)<\/p>\n<p>\u00a0<\/p>\n<p>El plazo de presentaci\u00f3n de solicitudes finaliza el 28 de septiembre de 2017 inclusive.<\/p>\n<p>Tal y como establece el art\u00edculo 9 de la Convocatoria, las solicitudes deben cumplimentarse a trav\u00e9s del formulario accesible en la Sede Electr\u00f3nica del Ministerio de Educaci\u00f3n, Cultura y Deporte, en la direcci\u00f3n https:\/\/sede.educacion.gob.es , en el apartado correspondiente a \u201cTr\u00e1mites y Servicios\u201d. Para poder acceder a dicho formulario, se requiere que el alumno solicitante est\u00e9 previamente registrado. En el caso de alumnos menores que carecen de DNI o NIE, puede registrarse el padre o la madre del alumno aunque despu\u00e9s tendr\u00e1n que indicar (se lo preguntan al iniciar el proceso de cumplimentar la solicitud) que el DNI o NIE del registro no corresponde al alumno.<\/p>\n<p>En aquellos casos en que las familias, estando el alumno o los padres registrados, no recuerdan la contrase\u00f1a de acceso o la misma se encuentre bloqueada, disponen en la Sede Electr\u00f3nica de un bot\u00f3n de ayuda con varias opciones para solicitar la recepci\u00f3n de un correo electr\u00f3nico y determinar una nueva contrase\u00f1a.<\/p>\n<p>\u00a0<\/p>\n<p>Una vez cumplimentado y generado el impreso de solicitud, la presentaci\u00f3n definitiva se podr\u00e1 realizar de alguna de las dos siguientes maneras:<\/p>\n<p>\u00a0<\/p>\n<p>1\u00aa. Imprimir la solicitud y presentarla en el centro donde vaya a cursar estudios durante el curso 2017\/2018, adjuntando la documentaci\u00f3n necesaria y recabando previamente las certificaciones que se necesiten en el impreso, seg\u00fan el tipo de ayuda solicitada. (Esta ser\u00e1 la opci\u00f3n m\u00e1s habitual) .<\/p>\n<p>\u00a0<\/p>\n<p>2\u00aa Presentar de forma totalmente telem\u00e1tica la solicitud. Para ello el solicitante deber\u00e1 disponer de certificado electr\u00f3nico, debiendo adem\u00e1s escanear la documentaci\u00f3n necesaria y las certificaciones, tal y como les van a ir indicando en la Sede Electr\u00f3nica.<\/p>\n<p>\u00a0<\/p>\n<p>En los casos en que no cuenten con los medios t\u00e9cnicos necesarios o tengan especiales dificultades a lo largo del proceso, acudan al centro para poder llevar a cabo las gestiones de las tareas de registro y cumplimentaci\u00f3n de la solicitud en la Sede Electr\u00f3nica.<\/p>\n<p>\u00a0<\/p>\n<p>Aranjuez, 06 de septiembre de 2017.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 EQUIPO DIRECTIVO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias:<\/p>\n<p>\u00a0<\/p>\n<p>Os informamos a continuaci\u00f3n de la CONVOCATORIA DE AYUDAS PARA ALUMNOS CON NECESIDAD ESPEC\u00cdFICA DE APOYO EDUCATIVO PARA EL CURSO 2017\/2018.<\/p>\n<p>\u00a0<\/p>\n<p>El pasado d\u00eda 12 de agosto se public\u00f3 en el BOE el extracto de la Resoluci\u00f3n de 03 de agosto de 2017 de la Secretar\u00eda de Estado, Formaci\u00f3n Profesional y Universidades, por la que se convocan ayudas para alumnos con necesidad espec\u00edfica de apoyo educativo para el curso 2017\/2018. El texto \u00edntegro de la convocatoria puede consultarse en la Base de Datos Nacional de Subvenciones (http:\/\/www.pap.minhap.gob.es\/bdnstans, identificador 358870)<\/p>\n<p>\u00a0<\/p>\n<p>El plazo de presentaci\u00f3n de solicitudes finaliza el 28 de septiembre de 2017 inclusive.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"post_folder":[],"class_list":["post-1635","post","type-post","status-publish","format-standard","hentry","category-becas-y-ayudas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/becas-y-ayudas\/\" rel=\"category tag\">Becas y ayudas<\/a>","rttpg_excerpt":"Estimadas familias: \u00a0 Os informamos a continuaci\u00f3n de la CONVOCATORIA DE AYUDAS PARA ALUMNOS CON NECESIDAD ESPEC\u00cdFICA DE APOYO EDUCATIVO PARA EL CURSO 2017\/2018. \u00a0 El pasado d\u00eda 12 de agosto se public\u00f3 en el BOE el extracto de la Resoluci\u00f3n de 03 de agosto de 2017 de la Secretar\u00eda de Estado, Formaci\u00f3n Profesional y&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1635"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1635\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1635"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}