{"id":1658,"date":"2017-09-27T05:33:50","date_gmt":"2017-09-27T05:33:50","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1658"},"modified":"2017-09-27T05:33:50","modified_gmt":"2017-09-27T05:33:50","slug":"comite-organizador-charlie-s-league-22-de-septiembre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/09\/27\/comite-organizador-charlie-s-league-22-de-septiembre\/","title":{"rendered":"COMIT\u00c9 ORGANIZADOR CHARLIE\u00b4S LEAGUE. 22 DE SEPTIEMBRE"},"content":{"rendered":"<p>Las Charlie\u00b4s League es una idea de los Pitufos (Asamblea de Representantes de Alumnos\/as del 2\u00ba Tramo de Primaria), cuya finalidad es proponer\u00a0 actividades para el tiempo de recreo.<\/p>\n<p>Para la organizaci\u00f3n de esta competici\u00f3n se crea un Comit\u00e9 compuesto por un alumno\/a de cada clase, el Comit\u00e9 se reuni\u00f3n el 22 de septiembre y acord\u00f3 los siguientes puntos:<\/p>\n<ul>\n<li>Finalidad: Jugamos para divertirnos, todos los que quieran participar en la liga, deben firmar un compromiso de buenas pr\u00e1cticas deportivas, respeto a los dem\u00e1s (compa\u00f1eros, rivales, \u00e1rbitros) y a las normas y de convivencia (estilo juramento ol\u00edmpico).<\/li>\n<li>N\u00famero de jugadores (<strong>f\u00fatbol, baloncesto, balontiro, voleyball, balonmano y kickball = b\u00e9isbol con el pie<\/strong>): el n\u00famero de jugadores viene determinado por la clase que el d\u00eda del partido presente a menos alumnos\/as. Pero siempre en un n\u00famero superior a 7. Con el fin de que puedan jugar el mayor n\u00famero de personas y evitar problemas con los cambios, convocatorias, etc.<\/li>\n<li>Para jugar a los deportes individuales, <strong>pin-pong<\/strong>, habr\u00e1 que apuntarse en una lista y el torneo se desarrollar\u00e1 los <strong>lunes<\/strong>, d\u00eda de no pista para los alumnos\/as del 2\u00ba tramo (4\u00ba, 5\u00ba y 6\u00ba de Primaria).<\/li>\n<li>Cada curso juega con otras clases del mismo curso y en los juegos colectivos ser\u00e1 el d\u00eda que les toca la pista, salvo en pinpong (tenis de mesa) que se realzair\u00e1 todos mezclados.<\/li>\n<li>Habr\u00e1 dos \u00e1rbitros por partido, que ser\u00e1n designados por los organizadores de cada actividad, cuando elaboren el calendario de enfrentamientos. Puede que sean los mismos organizadores o no.<\/li>\n<li>Los partidos s\u00f3lo se aplazar\u00e1n, por las siguientes causas, excursi\u00f3n\/o imposibilidad de utilizar la zona de juego.<\/li>\n<li>Los organizadores de cada deporte, cuando les toque recoger\u00e1n de conserjer\u00eda la <strong>mochila de la Charlie\u00b4s League<\/strong>, que tendr\u00e1 petos, balones, silbatos, cron\u00f3metro, palas; al terminar los partidos ellos ser\u00e1n los encargados de recoger el material utilizado y dejarlo en su sitio.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<ul>\n<li>Se seguir\u00e1n las reglas b\u00e1sicas de cada deporte.<\/li>\n<li>Se premiar\u00e1 a los equipos que jueguen con deportividad (no haya ning\u00fan conflicto durante el partido) 3 puntos.<\/li>\n<li>Si hay empate, se otorgar\u00e1 un punto a cada equipo; en caso de victoria dar\u00e1 3 puntos al equipo ganador.<\/li>\n<li>Por cada gol (f\u00fatbol y balonmano), jugador eliminado (balontiro), carrera (kickball, b\u00e9isbol con el pie), punto (voleyball), canasta (baloncesto) se suma un punto al equipo.<\/li>\n<li>El torneo de pinpong se jugar\u00e1 a 10 tantos, cada jugador realizara 5 saques seguidos. Al terminar los diez tantos se acaba el partido.<\/li>\n<li>Por cada partido ganado en pinpong son 2 puntos para la clase, en caso de empate es un punto para cada jugador. Por cada punto anotado durante el partido se dar\u00e1 0\u00b45 puntos a la clase.<\/li>\n<li>En cada deporte se va sumando puntos y la clase ganadora ser\u00e1 la que m\u00e1s puntos tenga con la suma de todas las actividades. Todos los deportes tienen m\u00e1s o menos el mismo valor y se premia tanto la habilidad como la buena conducta del equipo.<\/li>\n<li>No hay partido de vuelta. En cada deporte colectivo cada clase jugar\u00e1 dos partidos.<\/li>\n<li>Te puedes apuntar a todos los deportes que quieras.<\/li>\n<li>Insulto o agresi\u00f3n es expulsi\u00f3n, del partido, del deporte o de toda la liga.<\/li>\n<li><strong>Duraci\u00f3n de los partidos: 8 minutos<\/strong> cada partido a reloj corrido, no se para; el \u00e1rbitros ser\u00e1 encargado de controlar y pitar cuando se cumpla, para ello se le entregar\u00e1 un cron\u00f3metro y un silbato. Tambi\u00e9n se guardar\u00e1 en la bolsa de material, con los petos y el bal\u00f3n.<\/li>\n<li>Para inscribirse: cada clase tiene que dar una lista con los que quieren participar, nombre del equipo, escudo (dibujo que lo represente) y quien es la persona que va a arbitrar cada deporte.<\/li>\n<li><strong>Fecha tope para entregar los equipos: el viernes 6 de octubre a las 12:00<\/strong>, se debe entregar a un miembro del Comit\u00e9 Organizador de la Charlie\u00b4s League.<\/li>\n<li><strong>Martes 10 de octubre: sorteo de los partidos<\/strong>, en la zona acolchada, se har\u00e1 el sorteo con las letras de las 3 clases, las dos primeras que salgan, ser\u00e1n las primeras en enfrentarse y la primera en salir, jugar\u00e1 tambi\u00e9n el tercer partido.<\/li>\n<li><strong>La Charlie\u00b4s League comienza el lunes 16 de octubre.<\/strong><\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>El orden de los torneos es el siguiente:<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>1\u00ba VOLEYBOL<\/p>\n<p>2\u00ba BALONTIRO<\/p>\n<p>3\u00ba BALONCESTO<\/p>\n<p>4\u00ba BALONMANO<\/p>\n<p>5\u00ba B\u00c9ISBOL CON EL PIE<\/p>\n<p>6\u00ba F\u00daTBOL<\/p>\n<p>Los lunes torneo de pin-pong<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Charlie\u00b4s League es una idea de los Pitufos (Asamblea de Representantes de Alumnos\/as del 2\u00ba Tramo de Primaria), cuya finalidad es proponer\u00a0 actividades para el tiempo de recreo.<\/p>\n<p>Para la organizaci\u00f3n de esta competici\u00f3n se crea un Comit\u00e9 compuesto por un alumno\/a de cada clase, el Comit\u00e9 se reuni\u00f3n el 22 de septiembre y acord\u00f3 los siguientes puntos:<\/p>\n<ul>\n<li>Finalidad: Jugamos para divertirnos, todos los que quieran participar en la liga, deben firmar un compromiso de buenas pr\u00e1cticas deportivas, respeto a los dem\u00e1s (compa\u00f1eros, rivales, \u00e1rbitros) y a las normas y de convivencia (estilo juramento ol\u00edmpico).<\/li>\n<li>N\u00famero de jugadores (<strong>f\u00fatbol, baloncesto, balontiro, voleyball, balonmano y kickball = b\u00e9isbol con el pie<\/strong>): el n\u00famero de jugadores viene determinado por la clase que el d\u00eda del partido presente a menos alumnos\/as. Pero siempre en un n\u00famero superior a 7. Con el fin de que puedan jugar el mayor n\u00famero de personas y evitar problemas con los cambios, convocatorias, etc.<\/li>\n<li>Para jugar a los deportes individuales, <strong>pin-pong<\/strong>, habr\u00e1 que apuntarse en una lista y el torneo se desarrollar\u00e1 los <strong>lunes<\/strong>, d\u00eda de no pista para los alumnos\/as del 2\u00ba tramo (4\u00ba, 5\u00ba y 6\u00ba de Primaria).<\/li>\n<li>Cada curso juega con otras clases del mismo curso y en los juegos colectivos ser\u00e1 el d\u00eda que les toca la pista, salvo en pinpong (tenis de mesa) que se realzair\u00e1 todos mezclados.<\/li>\n<li>Habr\u00e1 dos \u00e1rbitros por partido, que ser\u00e1n designados por los organizadores de cada actividad, cuando elaboren el calendario de enfrentamientos. Puede que sean los mismos organizadores o no.<\/li>\n<li>Los partidos s\u00f3lo se aplazar\u00e1n, por las siguientes causas, excursi\u00f3n\/o imposibilidad de utilizar la zona de juego.<\/li>\n<li>Los organizadores de cada deporte, cuando les toque recoger\u00e1n de conserjer\u00eda la <strong>mochila de la Charlie\u00b4s League<\/strong>, que tendr\u00e1 petos, balones, silbatos, cron\u00f3metro, palas; al terminar los partidos ellos ser\u00e1n los encargados de recoger el material utilizado y dejarlo en su sitio.<\/li>\n<\/ul>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"post_folder":[],"class_list":["post-1658","post","type-post","status-publish","format-standard","hentry","category-otras-iniciativas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/otras-iniciativas\/\" rel=\"category tag\">Otras iniciativas<\/a>","rttpg_excerpt":"Las Charlie\u00b4s League es una idea de los Pitufos (Asamblea de Representantes de Alumnos\/as del 2\u00ba Tramo de Primaria), cuya finalidad es proponer\u00a0 actividades para el tiempo de recreo. Para la organizaci\u00f3n de esta competici\u00f3n se crea un Comit\u00e9 compuesto por un alumno\/a de cada clase, el Comit\u00e9 se reuni\u00f3n el 22 de septiembre y&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1658"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1658\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1658"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}