{"id":1659,"date":"2017-09-27T11:01:32","date_gmt":"2017-09-27T11:01:32","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1659"},"modified":"2017-09-27T11:01:32","modified_gmt":"2017-09-27T11:01:32","slug":"the-carlos-iii-rock-and-roll-band-curso-2017-2018","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/09\/27\/the-carlos-iii-rock-and-roll-band-curso-2017-2018\/","title":{"rendered":"THE CARLOS III ROCK AND ROLL BAND. CURSO 2017-2018"},"content":{"rendered":"<p>El 27 de septiembre del 2017, mi\u00e9rcoles, ha habido una convocatoria para saber quien estaba en la Banda de Rock, las normas, qu\u00e9 hab\u00eda que hacer, qu\u00e9 d\u00edas se ensayaban, &#8230;&#8230; Carlos, nuestro profesor de m\u00fasica y director de la banda nos ha explicado todo lo que hac\u00eda falta saber para formar parte de la Banda de Rock del Colegio.<\/p>\n<p>&#8211; Es necesario saber tocar alg\u00fan instrumento o saber cantar.<\/p>\n<p>&#8211; Hace falta compromiso, ir a los ensayos, los d\u00edas que sean necesarios. La \u00fanica causa para faltar es estar enfermo o que te coincida con una Asamblea de Pitufos.<\/p>\n<p>\u00a0<\/p>\n<p>El viernes, la banda cantar\u00e1 el himno del Colegio a los assitants como bienvenida.<\/p>\n<p>Los instrumentos que hay son bater\u00eda, guitarra el\u00e9ctrica, bongos, piano, tri\u00e1ngulo, campanas, bajo, las maracas, &#8230;.<\/p>\n<p>Como somos muchos los interesados habr\u00e1 3 \u00f3 4 bandas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DKuLDG2W4AAP5Rl.jpg:large\" alt=\"\" width=\"1528\" height=\"860\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 27 de septiembre del 2017, mi\u00e9rcoles, ha habido una convocatoria para saber quien estaba en la Banda de Rock, las normas, qu\u00e9 hab\u00eda que hacer, qu\u00e9 d\u00edas se ensayaban, &#8230;&#8230; Carlos, nuestro profesor de m\u00fasica y director de la banda nos ha explicado todo lo que hac\u00eda falta saber para formar parte de la &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/09\/27\/the-carlos-iii-rock-and-roll-band-curso-2017-2018\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abTHE CARLOS III ROCK AND ROLL BAND. CURSO 2017-2018\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"post_folder":[],"class_list":["post-1659","post","type-post","status-publish","format-standard","hentry","category-experiencias-educativas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/experiencias-educativas\/\" rel=\"category tag\">Proyectos Educativos<\/a>","rttpg_excerpt":"El 27 de septiembre del 2017, mi\u00e9rcoles, ha habido una convocatoria para saber quien estaba en la Banda de Rock, las normas, qu\u00e9 hab\u00eda que hacer, qu\u00e9 d\u00edas se ensayaban, &#8230;&#8230; Carlos, nuestro profesor de m\u00fasica y director de la banda nos ha explicado todo lo que hac\u00eda falta saber para formar parte de la&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1659"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1659\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1659"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}