{"id":1707,"date":"2017-10-30T12:30:56","date_gmt":"2017-10-30T12:30:56","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1707"},"modified":"2017-10-30T12:30:56","modified_gmt":"2017-10-30T12:30:56","slug":"himno-colegio-carlos-iii","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/10\/30\/himno-colegio-carlos-iii\/","title":{"rendered":"HIMNO COLEGIO CARLOS III"},"content":{"rendered":"<p>El lunes 30 de octubre hemos celebrado el acto de Clausura de Bienvenida de Inicio del Curso, con una actividad todos juntos en el patio, el resultado ha sido el siguiente.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/fcYOeTj7t7M\" width=\"425\" height=\"350\"><\/iframe><\/p>\n<p>\u00abJUNTOS APRENDEMOS, JUNTOS DISFRUTAMOS. WE ARE JUSTA CARLOS III\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cYOU\u00a0 ARE\u00a0 ALWAYS ON MY MIND\u201d\u00a0 \u00a0 <\/strong><strong>(HIMNO COLEGIO CARLOS III)<\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><em>Llevamos aqu\u00ed muchos a\u00f1os<\/em><\/p>\n<p><em>Disfrutando a\u00fan cuando \u00e9ramos peque\u00f1os y extra\u00f1os<\/em><\/p>\n<p><em>Pas\u00e1ndolo bien y subiendo cursos como pelda\u00f1os Hey yo! Hey yo!<\/em><\/p>\n<p><em>Y qui\u00e9n pensar\u00eda que llegar\u00edamos tan lejos<\/em><\/p>\n<p><em>Escalando problemas que parecen ser reflejos<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>You Are Always On My Mind <\/em><\/p>\n<p><em>You Are Always On My Heart<\/em><\/p>\n<p><em>\u00a0<\/em><em>siento en lo m\u00e1s hondo cuando canto este rap<\/em><\/p>\n<p><em>cientos de chavales recordar\u00e1n el cole<\/em><\/p>\n<p><em>y\u00a0 que somos diferentes y a la vez iguales<\/em><\/p>\n<p><em>cada abrazo cada beso que se graba en la retina<\/em><\/p>\n<p><em>recicla la tristeza y se convierte en vitamina<\/em><\/p>\n<p><em>aqu\u00ed estamos empu\u00f1ando nuestro micro<\/em><\/p>\n<p><em>somos una familia con un \u00fanico destino<\/em><\/p>\n<p><em>llorando de alegr\u00eda riendo en un mal d\u00eda<\/em><\/p>\n<p><em>nuestro lema es \u201cnada es imposible con la fantas\u00eda\u201d<\/em><\/p>\n<p><em>agarra las ra\u00edces de la cruda realidad<\/em><\/p>\n<p><em>riega las semillas nuestra flores de Amistad.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Somos diferentes y al a vez iguales<\/p>\n<p>juntos aprendemos juntos disfrutamos<\/p>\n<p>pret\u00e9rito perfecto, presente y futuro<\/p>\n<p>m\u00e1s all\u00e1 del tiempo somos compa\u00f1eros<\/p>\n<p>amigos leales unidos de la mano<\/p>\n<p>tantos recuerdos grabados para siempre<em>\u00a0<\/em><\/p>\n<p><em>s\u00famate a nosotros siempre hay soluci\u00f3n en Carlos III por un mundo mejor<\/em><\/p>\n<p><em>You Are Always On My Mind x 8<\/em><\/p>\n<p>somos diferentes y al a vez iguales<\/p>\n<p>juntos aprendemos juntos disfrutamos<\/p>\n<p>pret\u00e9rito perfecto, presente y futuro<\/p>\n<p>m\u00e1s all\u00e1 del tiempo somos compa\u00f1eros<\/p>\n<p>amigos leales unidos de la mano<\/p>\n<p>&nbsp;<\/p>\n<p>we are the power the magical generation<\/p>\n<p>a garden made of love and imagination<\/p>\n<p>we are the future the rainbow in the rain<\/p>\n<p>we don\u00b4t say goodbye<\/p>\n<p>you are always on my mind (BIS)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/\/wp-content\/uploads\/cp.carlostercero.aranjuez\/2017\/10\/HIMNO-COLEGIO-CARLOS-III.pdf\">HIMNO COLEGIO CARLOS III<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 30 de octubre hemos celebrado el acto de Clausura de Bienvenida de Inicio del Curso, con una actividad todos juntos en el patio, el resultado ha sido el siguiente. \u00abJUNTOS APRENDEMOS, JUNTOS DISFRUTAMOS. WE ARE JUSTA CARLOS III\u00bb &nbsp; \u201cYOU\u00a0 ARE\u00a0 ALWAYS ON MY MIND\u201d\u00a0 \u00a0 (HIMNO COLEGIO CARLOS III) \u00a0Llevamos aqu\u00ed muchos &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/10\/30\/himno-colegio-carlos-iii\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abHIMNO COLEGIO CARLOS III\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"post_folder":[],"class_list":["post-1707","post","type-post","status-publish","format-standard","hentry","category-centro"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/centro\/\" rel=\"category tag\">Centro<\/a>","rttpg_excerpt":"El lunes 30 de octubre hemos celebrado el acto de Clausura de Bienvenida de Inicio del Curso, con una actividad todos juntos en el patio, el resultado ha sido el siguiente. \u00abJUNTOS APRENDEMOS, JUNTOS DISFRUTAMOS. WE ARE JUSTA CARLOS III\u00bb &nbsp; \u201cYOU\u00a0 ARE\u00a0 ALWAYS ON MY MIND\u201d\u00a0 \u00a0 (HIMNO COLEGIO CARLOS III) \u00a0Llevamos aqu\u00ed muchos&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1707"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1707\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1707"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}