{"id":175,"date":"2014-03-06T07:44:11","date_gmt":"2014-03-06T07:44:11","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=175"},"modified":"2014-03-06T07:44:11","modified_gmt":"2014-03-06T07:44:11","slug":"convocatoria-de-inmersion-lingueistica","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2014\/03\/06\/convocatoria-de-inmersion-lingueistica\/","title":{"rendered":"Convocatoria de inmersi\u00f3n ling\u00fc\u00edstica"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>Os enviamos en archivo adjunto la convocatoria de inmersi\u00f3n ling\u00fc\u00edstica en Verano para alumnos de 5\u00ba y 6\u00ba que hemos recibido por si fuera de vuestro inter\u00e9s.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre las estancias de inmersi\u00f3n ling\u00fc\u00edstica puedes pinchar <a href=\"http:\/\/www.midletonschool.com\/navidad2013\/news\/NL_MS0214vB1.html\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Os enviamos en archivo adjunto la convocatoria de inmersi\u00f3n ling\u00fc\u00edstica en Verano para alumnos de 5\u00ba y 6\u00ba que hemos recibido por si fuera de vuestro inter\u00e9s. Para obtener m\u00e1s informaci\u00f3n sobre las estancias de inmersi\u00f3n ling\u00fc\u00edstica puedes pinchar aqu\u00ed<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"post_folder":[],"class_list":["post-175","post","type-post","status-publish","format-standard","hentry","category-3o-ciclo"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/3o-ciclo\/\" rel=\"category tag\">3\u00ba Ciclo<\/a>","rttpg_excerpt":"Estimadas familias: Os enviamos en archivo adjunto la convocatoria de inmersi\u00f3n ling\u00fc\u00edstica en Verano para alumnos de 5\u00ba y 6\u00ba que hemos recibido por si fuera de vuestro inter\u00e9s. Para obtener m\u00e1s informaci\u00f3n sobre las estancias de inmersi\u00f3n ling\u00fc\u00edstica puedes pinchar aqu\u00ed","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=175"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/175\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=175"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}