{"id":1754,"date":"2017-11-22T13:12:44","date_gmt":"2017-11-22T13:12:44","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1754"},"modified":"2017-11-22T13:12:44","modified_gmt":"2017-11-22T13:12:44","slug":"we-love-painting-i4anos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2017\/11\/22\/we-love-painting-i4anos\/","title":{"rendered":"WE LOVE PAINTING (I4A\u00d1OS)"},"content":{"rendered":"<p>Las clases de 4 a\u00f1os est\u00e1n \u00abdando\u00bb la prehistoria, desde Kindervilla\u00a0nos hemos sumado al proyecto trabajando el cuento \u00abCave Baby\u00bb.<\/p>\n<p>Hemos comenzado cont\u00e1ndoles el libro, una vez le\u00eddo, han pintado como si fueran los protagonistas del cuento y entre todos hemos hecho una cueva para exponer todos los dibujos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DOlJ-bXWkAAGkv5.jpg\" alt=\"\" width=\"619\" height=\"314\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DOlKDTTWkAAz1Pf.jpg\" alt=\"\" width=\"391\" height=\"292\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DOlL-30WAAA6mMz.jpg\" alt=\"\" width=\"222\" height=\"292\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las clases de 4 a\u00f1os est\u00e1n \u00abdando\u00bb la prehistoria, desde Kindervilla\u00a0nos hemos sumado al proyecto trabajando el cuento \u00abCave Baby\u00bb. Hemos comenzado cont\u00e1ndoles el libro, una vez le\u00eddo, han pintado como si fueran los protagonistas del cuento y entre todos hemos hecho una cueva para exponer todos los dibujos.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"post_folder":[],"class_list":["post-1754","post","type-post","status-publish","format-standard","hentry","category-kindervilla"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/kindervilla\/\" rel=\"category tag\">KINDERVILLA<\/a>","rttpg_excerpt":"Las clases de 4 a\u00f1os est\u00e1n \u00abdando\u00bb la prehistoria, desde Kindervilla\u00a0nos hemos sumado al proyecto trabajando el cuento \u00abCave Baby\u00bb. Hemos comenzado cont\u00e1ndoles el libro, una vez le\u00eddo, han pintado como si fueran los protagonistas del cuento y entre todos hemos hecho una cueva para exponer todos los dibujos.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1754"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1754\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1754"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}