{"id":1822,"date":"2018-01-16T10:09:25","date_gmt":"2018-01-16T10:09:25","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1822"},"modified":"2018-01-16T10:09:25","modified_gmt":"2018-01-16T10:09:25","slug":"comunicado-carnaval-2018-1","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/01\/16\/comunicado-carnaval-2018-1\/","title":{"rendered":"COMUNICADO CARNAVAL 2018 (1)"},"content":{"rendered":"<p style=\"text-align: right;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Aranjuez, 16 de enero de 2018.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0Estimadas familias:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\"><strong>El pr\u00f3ximo viernes d\u00eda 09 de febrero de 2018, celebraremos en el Centro la fiesta de Carnaval que este a\u00f1o se centra en el tema \u201cNUEVA ZELANDA\u201d coincidiendo con la Fiesta Anglosajona de Centro.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong>Como preparaci\u00f3n y fundamentaci\u00f3n del objetivo principal de esta celebraci\u00f3n y enmarcado en el desarrollo de la competencia de conciencia y expresi\u00f3n cultural para el fomento del conocimiento, comprensi\u00f3n y respeto por las diferentes culturas, se van a desarrollar durante los d\u00edas previos a la fecha del 09 de febrero, una serie de talleres con la totalidad del alumnado del Centro, por parte de sus Tutores y\/o especialistas, incluyendo en algunos de ellos a las familias en el caso de los talleres de realizaci\u00f3n de disfraces, adornos y abalorios fomentando as\u00ed la convivencia de la comunidad educativa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Igualmente se llevar\u00e1n a cabo Talleres que ser\u00e1n realizados por monitores biling\u00fces pertenecientes a NATURENGLISH, desplazados al colegio para llevar a cabo con cada ciclo, tramo y\/o nivel actividades que profundicen en el desarrollo del conocimiento de la cultura de Nueva Zelanda y de los Maories, sus costumbres y se\u00f1as de identidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Estos talleres ascienden a la cantidad de \/\/5,-\u20ac\/\/ por alumno\/a. En el caso de los socios del AMPA, este importe ser\u00e1 sufragado por la asociaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Desde las reuniones de padres que se llevan a cabo en estos d\u00edas, se ir\u00e1 informando del disfraz, de los Talleres a realizar,,, y se enviar\u00e1 el impreso para el pago de los talleres desde las Tutor\u00edas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En breve lanzaremos la planificaci\u00f3n del d\u00eda del desfile que est\u00e1 ultim\u00e1ndose desde las propuestas presentadas en la Comisi\u00f3n de Festividades del Centro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Os recordamos igualmente que el AMPA, ha organizado la participaci\u00f3n del Centro en la fiesta de carnaval de la localidad para el s\u00e1bado 10 de febrero de 2018. La informaci\u00f3n figurar\u00e1 en su Tabl\u00f3n de Anuncios. Os animamos una vez m\u00e1s a participar en el pasacalle, dando muestra de lo trabajado en el Centro y a colaborar en la organizaci\u00f3n del mismo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 EQUIPO DIRECTIVO.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 16 de enero de 2018. \u00a0 \u00a0Estimadas familias: \u00a0 El pr\u00f3ximo viernes d\u00eda 09 de febrero de 2018, celebraremos en el Centro la fiesta de Carnaval que este a\u00f1o se centra en el tema \u201cNUEVA ZELANDA\u201d coincidiendo con la Fiesta Anglosajona de Centro. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Como preparaci\u00f3n y fundamentaci\u00f3n del objetivo principal de esta celebraci\u00f3n y &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/01\/16\/comunicado-carnaval-2018-1\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO CARNAVAL 2018 (1)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"post_folder":[],"class_list":["post-1822","post","type-post","status-publish","format-standard","hentry","category-menu"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/menu\/\" rel=\"category tag\">Menu Superior Central<\/a>","rttpg_excerpt":"Aranjuez, 16 de enero de 2018. \u00a0 \u00a0Estimadas familias: \u00a0 El pr\u00f3ximo viernes d\u00eda 09 de febrero de 2018, celebraremos en el Centro la fiesta de Carnaval que este a\u00f1o se centra en el tema \u201cNUEVA ZELANDA\u201d coincidiendo con la Fiesta Anglosajona de Centro. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Como preparaci\u00f3n y fundamentaci\u00f3n del objetivo principal de esta celebraci\u00f3n y&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1822"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1822\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1822"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}