{"id":1834,"date":"2018-01-25T16:08:56","date_gmt":"2018-01-25T16:08:56","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1834"},"modified":"2018-01-25T16:08:56","modified_gmt":"2018-01-25T16:08:56","slug":"convocatoria-x-asamblea-pitufos-curso-2017-18","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/01\/25\/convocatoria-x-asamblea-pitufos-curso-2017-18\/","title":{"rendered":"CONVOCATORIA X ASAMBLEA PITUFOS CURSO 2017\/18"},"content":{"rendered":"<p><strong>FECHA: lunes 29 enero<\/strong><\/p>\n<p><strong>HORA: 12:00<\/strong><\/p>\n<p><strong>LUGAR: sala de profesores de Primaria<\/strong><\/p>\n<p><strong>ORDEN DEL D\u00cdA<\/strong><\/p>\n<ol>\n<li>An\u00e1lisis de los conflictos de la Charlie League, deporte f\u00fatbol.<\/li>\n<li>Entrega de la lista de canciones carnaval, listado de nombres de pitufos del primer y segundo trimestre.<\/li>\n<li>Propuestas para la actividad: igualdad de g\u00e9nero, d\u00eda del libro, semana deportiva, \u2026<\/li>\n<li>Selecci\u00f3n de fechas concurso fotogr\u00e1fico de Charlie por clases.<\/li>\n<li>Avisos, ruegos y preguntas.<\/li>\n<\/ol>\n<p><strong>NOTA: ES IMPORTANTE QUE LOS DELEGADOS\/AS Y REPRESENTANTES LLEVEN SUS APORTACIONES POR ESCRITO Y CONSULTE A SUS COMPA\u00d1ER@S LOS PUNTOS QUE SE VAN A TRATAR EN LA ASAMBLEA.<\/strong><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FECHA: lunes 29 enero HORA: 12:00 LUGAR: sala de profesores de Primaria ORDEN DEL D\u00cdA An\u00e1lisis de los conflictos de la Charlie League, deporte f\u00fatbol. Entrega de la lista de canciones carnaval, listado de nombres de pitufos del primer y segundo trimestre. Propuestas para la actividad: igualdad de g\u00e9nero, d\u00eda del libro, semana deportiva, \u2026 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/01\/25\/convocatoria-x-asamblea-pitufos-curso-2017-18\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCONVOCATORIA X ASAMBLEA PITUFOS CURSO 2017\/18\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"post_folder":[],"class_list":["post-1834","post","type-post","status-publish","format-standard","hentry","category-actas-y-convocatorias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/actas-y-convocatorias\/\" rel=\"category tag\">Actas y Convocatorias<\/a>","rttpg_excerpt":"FECHA: lunes 29 enero HORA: 12:00 LUGAR: sala de profesores de Primaria ORDEN DEL D\u00cdA An\u00e1lisis de los conflictos de la Charlie League, deporte f\u00fatbol. Entrega de la lista de canciones carnaval, listado de nombres de pitufos del primer y segundo trimestre. Propuestas para la actividad: igualdad de g\u00e9nero, d\u00eda del libro, semana deportiva, \u2026&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1834"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1834\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1834"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}