{"id":1913,"date":"2018-03-07T12:07:47","date_gmt":"2018-03-07T12:07:47","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1913"},"modified":"2018-03-07T12:07:47","modified_gmt":"2018-03-07T12:07:47","slug":"actualizacion-jornada-de-huelga-8-de-marzo-2018","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/03\/07\/actualizacion-jornada-de-huelga-8-de-marzo-2018\/","title":{"rendered":"ACTUALIZACI\u00d3N JORNADA DE HUELGA 8 DE MARZO 2018"},"content":{"rendered":"<p style=\"text-align: right;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Aranjuez, 07 de marzo de 2018.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Estimadas familias:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Por la presente os comunicamos las \u00faltimas noticias recibidas acerca de la huelga convocada para el d\u00eda 08 de marzo de 2018, desde la Direcci\u00f3n de \u00c1rea Territorial Madrid-Sur y que se encuentran publicadas en el BOCM n\u00fam. 56 de hoy 07 de Marzo de 2018 ACUERDO de 6 de marzo de 2018, del Consejo de Gobierno, por el que se fijan los servicios m\u00ednimos con ocasi\u00f3n de la huelga convocada para el d\u00eda 8 de marzo de 2018.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u00abComo continuaci\u00f3n al correo remitido ayer con los servicios esenciales de la convocatoria de huelga del 8 de marzo y seg\u00fan informaci\u00f3n facilitada por la Direcci\u00f3n General de RR.HH. de la Consejer\u00eda de Educaci\u00f3n e Investigaci\u00f3n, \u00a0se comunica que las \u00fanicas huelgas convocadas en tiempo y forma son las siguientes:<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La Confederaci\u00f3n Sindical de Comisiones Obreras y la Confederaci\u00f3n Sindical de la Uni\u00f3n General de Trabajadores han convocado una huelga general que afectar\u00e1, entre otros, seg\u00fan exponen los convocantes, a todas las actividades laborales y funcionariales desempe\u00f1adas por los trabajadores y empleados p\u00fablicos de las empresas y organismos establecidos dentro del \u00e1mbito geogr\u00e1fico y jur\u00eddico del Estado espa\u00f1ol. Dicha convocatoria tendr\u00e1 lugar durante la jornada del d\u00eda 8 de marzo de 2018 y su duraci\u00f3n ser\u00e1 de dos horas para cada turno de trabajo, siendo para el personal del turno de ma\u00f1ana y con jornada partida en la franja horaria que transcurre de las 11:30 a 13:30 horas; para el personal del turno de tarde de 16:00 a 18:00 horas y para el personal del turno de noche en las dos primeras horas del turno que comienza el d\u00eda 8 de marzo.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Asimismo, la Uni\u00f3n Sindical Obrera (USO) con igual \u00e1mbito que las anteriores organizaciones sindicales, ha comunicado la convocatoria de huelga durante la jornada del d\u00eda 8 de marzo de 2018, comenzando a las 12:00 horas y terminando a las 16:00 horas del citado d\u00eda 8.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Por otra parte, la Confederaci\u00f3n General del Trabajo (CGT) y la Confederaci\u00f3n Nacional de Trabajo (CNT) con igual \u00e1mbito que las anteriores organizaciones sindicales, han convocado huelga para el citado d\u00eda 8 de marzo de 2018 abarcando desde las 0:00 horas hasta las 24:00 horas del mismo d\u00eda. Esta organizaci\u00f3n hace constar que para aquellos centros de trabajo en los que el mismo est\u00e9 organizado mediante sistema de turnos, la convocatoria de huelga comenzar\u00e1 en el \u00faltimo turno anterior a las 0:00 horas de dicho d\u00eda en que se realiza la convocatoria de huelga, abarcando, igualmente, al \u00faltimo turno que se inicie en el meritado d\u00eda y que terminar\u00e1 cuando finalice dicho tumo, al d\u00eda siguiente.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em><strong>No existe ninguna otra convocatoria de huelga realizada en tiempo y forma ante el Ministerio de Empleo y Seguridad Social o ante la Direcci\u00f3n General de Trabajo de la Comunidad de Madrid. \u00ab<br \/><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">Con estas \u00faltimas noticias, damos por actualizado el comunicado de ayer a las familias, dando por v\u00e1lidos los servicios m\u00ednimos establecidos seg\u00fan norma arriba indicada.<\/span><\/strong><em><strong><br \/><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-family: comic sans ms,sans-serif; font-size: 12pt;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 EQUIPO DIRECTIVO.<\/span><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 07 de marzo de 2018. \u00a0 Estimadas familias: Por la presente os comunicamos las \u00faltimas noticias recibidas acerca de la huelga convocada para el d\u00eda 08 de marzo de 2018, desde la Direcci\u00f3n de \u00c1rea Territorial Madrid-Sur y que se encuentran publicadas en el BOCM n\u00fam. 56 de hoy 07 de Marzo de 2018 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/03\/07\/actualizacion-jornada-de-huelga-8-de-marzo-2018\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abACTUALIZACI\u00d3N JORNADA DE HUELGA 8 DE MARZO 2018\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"post_folder":[],"class_list":["post-1913","post","type-post","status-publish","format-standard","hentry","category-menu"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/menu\/\" rel=\"category tag\">Menu Superior Central<\/a>","rttpg_excerpt":"Aranjuez, 07 de marzo de 2018. \u00a0 Estimadas familias: Por la presente os comunicamos las \u00faltimas noticias recibidas acerca de la huelga convocada para el d\u00eda 08 de marzo de 2018, desde la Direcci\u00f3n de \u00c1rea Territorial Madrid-Sur y que se encuentran publicadas en el BOCM n\u00fam. 56 de hoy 07 de Marzo de 2018&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1913"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1913\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1913"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}