{"id":1932,"date":"2018-03-13T14:03:21","date_gmt":"2018-03-13T14:03:21","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1932"},"modified":"2018-03-13T14:03:21","modified_gmt":"2018-03-13T14:03:21","slug":"vii-jornadas-deportivas","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/03\/13\/vii-jornadas-deportivas\/","title":{"rendered":"VII JORNADAS DEPORTIVAS"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>Os informamos que durante la semana del 19 al 22 de marzo de 2018, tendr\u00e1n lugar las VII Jornadas Deportivas, las cuales quedar\u00e1n organizadas de la siguiente manera:<\/p>\n<p><strong>Estadio \u201cEl Deleite\u201d:<\/strong><\/p>\n<p><strong>&#8211; Lunes 19 de marzo: 5 a\u00f1os y 1\u00ba de Primaria<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>&#8211; Mi\u00e9rcoles 21 de marzo: 2\u00ba y 3\u00ba de Primaria.<\/p>\n<p>&#8211; Jueves 22 de marzo: 4\u00ba, 5\u00ba y 6\u00ba de Primaria.<\/p>\n<p>Para su realizaci\u00f3n y desarrollo se contar\u00e1 con la colaboraci\u00f3n de dos familiares por clase, que habr\u00e1 de comunicarse al tutor.<\/p>\n<p>ASPECTOS A TENER EN CUENTA:<\/p>\n<ul>\n<li>Los objetivos de dichas jornadas ser\u00e1n: favorecer el esp\u00edritu de convivencia y deportividad, mejorar las habilidades b\u00e1sicas, conocer y respetar las reglas b\u00e1sicas de diferentes deportes de equipo, mejorar las habilidades sociales y reconocer y practicar las principales modalidades de atletismo.<\/li>\n<li><i>L<\/i>a entrega y recogida del alumnado ser\u00e1 responsabilidad de los padres, madres o tutores legales con <strong>la excepci\u00f3n<\/strong> del alumnado perteneciente a <strong>los primeros del cole y transporte escolar<\/strong> (que ir\u00e1n en autob\u00fas hasta las instalaciones deportivas) . Al finalizar las jornadas deportivas <strong>los alumnos de transporte y comedor escolar <\/strong>volver\u00e1n en autob\u00fas hasta el centro escolar con los profesores responsables.<\/li>\n<li>La recogida de alumnos por parte de los tutores ser\u00e1 en el estadio \u00ab\u00a0El Deleite\u00a0\u00bb, a las 9\u00a0:00.<\/li>\n<li>Por su parte la entrega de alumnos se producir\u00e1 de 13:00 a 14:00, igualmente en el \u00abDeleite\u00a0\u00bb, para facilitar a las familias la recogida de los mismos as\u00ed como otros posibles alumnos del centro.<\/li>\n<li>Ser\u00e1 necesario la ropa deportiva, agua, gorra, bolsa de aseo y el desayuno de costumbre.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Recibid un cordial saludo<\/p>\n<p>Los especialistas de E.F\u00edsica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Os informamos que durante la semana del 19 al 22 de marzo de 2018, tendr\u00e1n lugar las VII Jornadas Deportivas, las cuales quedar\u00e1n organizadas de la siguiente manera: Estadio \u201cEl Deleite\u201d: &#8211; Lunes 19 de marzo: 5 a\u00f1os y 1\u00ba de Primaria \u00a0 &#8211; Mi\u00e9rcoles 21 de marzo: 2\u00ba y 3\u00ba de Primaria. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/03\/13\/vii-jornadas-deportivas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVII JORNADAS DEPORTIVAS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-1932","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Estimadas familias: Os informamos que durante la semana del 19 al 22 de marzo de 2018, tendr\u00e1n lugar las VII Jornadas Deportivas, las cuales quedar\u00e1n organizadas de la siguiente manera: Estadio \u201cEl Deleite\u201d: &#8211; Lunes 19 de marzo: 5 a\u00f1os y 1\u00ba de Primaria \u00a0 &#8211; Mi\u00e9rcoles 21 de marzo: 2\u00ba y 3\u00ba de Primaria.&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1932"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1932\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1932"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}