{"id":1971,"date":"2018-03-24T09:48:56","date_gmt":"2018-03-24T09:48:56","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=1971"},"modified":"2018-03-24T09:48:56","modified_gmt":"2018-03-24T09:48:56","slug":"hasta-la-proxima-maestras","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/03\/24\/hasta-la-proxima-maestras\/","title":{"rendered":"HASTA LA PR\u00d3XIMA MAESTRAS"},"content":{"rendered":"<p><span style=\"color: #000000;\">Termina el trimestre y la estancia en el Cole, por ahora, de Nuria, maestra sustituta\u00a0<span style=\"text-decoration: underline;\">\u00a0de\u00a0<\/span><a class=\"twitter-hashtag pretty-link js-nav\" dir=\"ltr\" href=\"https:\/\/twitter.com\/hashtag\/5a%C3%B1os?src=hash\" data-query-source=\"hashtag_click\"><span style=\"color: #000000;\">5 a\u00f1os<\/span><\/a>; de Mar, maestra en pr\u00e1cticas en\u00a0<a class=\"twitter-hashtag pretty-link js-nav\" dir=\"ltr\" href=\"https:\/\/twitter.com\/hashtag\/5a%C3%B1os?src=hash\" data-query-source=\"hashtag_click\"><span style=\"color: #000000;\">5 a\u00f1os<\/span><\/a> y de Sonia, que ha sustituido todo el trimestre en <a class=\"twitter-hashtag pretty-link js-nav\" dir=\"ltr\" href=\"https:\/\/twitter.com\/hashtag\/3a%C3%B1os?src=hash\" data-query-source=\"hashtag_click\"><span style=\"color: #000000;\">3 a\u00f1os<\/span><\/a>, gracias <a class=\"twitter-hashtag pretty-link js-nav\" dir=\"ltr\" href=\"https:\/\/twitter.com\/hashtag\/Maestras?src=hash\" data-query-source=\"hashtag_click\"><span style=\"color: #000000;\">Maestras<\/span><\/a> por vuestra labor y dedicaci\u00f3n. Hasta la pr\u00f3xima. <a class=\"twitter-hashtag pretty-link js-nav\" dir=\"ltr\" href=\"https:\/\/twitter.com\/hashtag\/JuntosApredemos?src=hash\" data-query-source=\"hashtag_click\"><span style=\"color: #000000;\">Juntos Apredemos<\/span><\/a>.<\/span><\/p>\n<p><span style=\"color: #000000;\"><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DY-va9bW4AMq_PY.jpg\" alt=\"\" \/><\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DZFAV7HX4AEUMsA.jpg\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Termina el trimestre y la estancia en el Cole, por ahora, de Nuria, maestra sustituta\u00a0\u00a0de\u00a05 a\u00f1os; de Mar, maestra en pr\u00e1cticas en\u00a05 a\u00f1os y de Sonia, que ha sustituido todo el trimestre en 3 a\u00f1os, gracias Maestras por vuestra labor y dedicaci\u00f3n. Hasta la pr\u00f3xima. Juntos Apredemos.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"post_folder":[],"class_list":["post-1971","post","type-post","status-publish","format-standard","hentry","category-infantil"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/\" rel=\"category tag\">Infantil<\/a>","rttpg_excerpt":"Termina el trimestre y la estancia en el Cole, por ahora, de Nuria, maestra sustituta\u00a0\u00a0de\u00a05 a\u00f1os; de Mar, maestra en pr\u00e1cticas en\u00a05 a\u00f1os y de Sonia, que ha sustituido todo el trimestre en 3 a\u00f1os, gracias Maestras por vuestra labor y dedicaci\u00f3n. Hasta la pr\u00f3xima. Juntos Apredemos.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=1971"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/1971\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=1971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=1971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=1971"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=1971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}