{"id":2021,"date":"2018-04-14T15:22:32","date_gmt":"2018-04-14T15:22:32","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2021"},"modified":"2018-04-14T15:22:32","modified_gmt":"2018-04-14T15:22:32","slug":"peticion-de-familiares-dia-del-libro","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/04\/14\/peticion-de-familiares-dia-del-libro\/","title":{"rendered":"LOS PERSONAJES SALEN DEL LIBRO. PETICI\u00d3N DE VOLUNTARIOS\/AS D\u00cdA DEL LIBRO"},"content":{"rendered":"<table class=\"x_w600\" style=\"height: 698px;\" border=\"0\" width=\"1244\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td class=\"x_pict x_w540\" width=\"540\">\n<h2>\u00a0<\/h2>\n<p>Desde el Colegio, estamos organizando la actividad de Cebtro:<\/p>\n<p>El d\u00eda del Libro.<\/p>\n<p>Cuyos objetivos son:<\/p>\n<p>&#8211; Fomentar h\u00e1bitos de lectura para resaltar la importancia de conservar y transmitir la cultura.<\/p>\n<p>&#8211; Impulsar la lectura como actividad que permite el desarrollo del lenguaje y mejorar las relaciones humanas y nuestra expresi\u00f3n oral y escreita.<\/p>\n<p>&#8211; Concienciar y reflexionar sobre la importancia de aquirir actitudes responsables sobre el uso de la energ\u00eda y los materiales reciclados.<\/p>\n<p>&#8211; Mejorar la convivencia escolar a trav\u00e9s del trabajo cooperativo, compartiendo espacios, materiales, tiempo y actividades.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Da_qgzgXUAEcLTg.jpg\" alt=\"\" width=\"904\" height=\"645\" \/><\/p>\n<p>Ya os informamos hace una par de semanas, de los concursos literarios (infantil y Primaria sobre Cuyo tema este a\u00f1o era: \u00abSomos Sostenibles: Fuentes de Energ\u00eda Renovables\u00bb.<\/p>\n<p>Otra de las actividades que estamos preparando es \u00abLos personajes salen de los libros\u00bb, para la realizaci\u00f3n de la misma, una vez m\u00e1s, vamos a necesitar la colaboraci\u00f3n de madres, padres y tutores legales; para una mejor organizaci\u00f3n del Centro vamos a conmemorar esta actividad el viernes 20 de abril, en lugar del d\u00eda 23 de abril (D\u00eda Internacional del Libro).<\/p>\n<p>La colaboraci\u00f3n de los familias, consistir\u00e1 en una animaci\u00f3n a la lectura del libro que cada clase previamente ha elegido (vestido de uno de los personajes del libro). Para participar en esta actividad, es necesario apuntarse en la lista de secretar\u00eda (nombre, clase del familiar, tel\u00e9fono de contacto). Las clases que tengan varios colaboradores pueden a\u00f1adir varios personajes del libro o participar con otras clases si fuera necesario.<\/p>\n<p>Con el fin de que pod\u00edas buscar con m\u00e1s tiempo la ropa y los complementos adecuados para el personaje literario, os facilitamos la lista de libros elegidos por cada clase:<\/p>\n<p>3 a\u00f1os A: Los 3 Cerditos\u00a0 \u00a0 3 a\u00f1os B: Caperucita Roja\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 3 a\u00f1os C: La Casa de los Besos<\/p>\n<p>4 a\u00f1os A: El Rey Le\u00f3n\u00a0 \u00a0 \u00a0 \u00a04 a\u00f1os B: El Monstruo de los Colores\u00a0 4 a\u00f1os C: Los 3Cerditos<\/p>\n<p>5 a\u00f1os A: Garbancito\u00a0 \u00a0 \u00a0 \u00a0 \u00a05 a\u00f1os B: Cuando a Mat\u00edas le entraron &#8230;. 5 a\u00f1os C: Los 7 Cabritillos<\/p>\n<p>1\u00baA: Pets\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01\u00baB: \u00bfA qu\u00e9 sabe la luna?\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a01\u00baC: Abezoo<\/p>\n<p>2\u00baA: Once upon a time\u00a0 \u00a0 \u00a0 2\u00baB: La Princesa Bromista\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2\u00baC: Futbol\u00edsimos<\/p>\n<p>3\u00baA: Harry Potter\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 3\u00baB: Diario de Greg\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a03\u00baC: Jack y las habichuelas m\u00e1gicas<\/p>\n<p>4\u00baA: Harry Potter\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a04\u00baB: Heidi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a04\u00baC: El Pirata Garrapata<\/p>\n<p>5\u00baA: Los Futbol\u00edsimos\u00a0 \u00a0 \u00a0 \u00a05\u00baB: Geronimo Stilton\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 5\u00baC: Diario de Greg<\/p>\n<p>6\u00baA: 4 a\u00f1os para 32 segundos\u00a0 \u00a06\u00baB: El secreto de If\u00a0 \u00a0 6\u00baC: Diario de Greg<\/p>\n<p>Maestros: Quijote, Educar con el coraz\u00f3n, Un Libro (Hervue Tullet) y Brida\u00a0 \u00a0<\/p>\n<p>La animaci\u00f3n consistir\u00e1 en una peque\u00f1a escenificaci\u00f3n-presentaci\u00f3n del personaje y del libro o una actividad liga a la lectura para realizar con la clase . La actividad se desarrollar\u00e1 el viernes 20 de abril, de 12:00 a 13:30.\u00a0<\/p>\n<p>Gracias por vuestra colaboraci\u00f3n.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Desde el Colegio, estamos organizando la actividad de Cebtro: El d\u00eda del Libro. Cuyos objetivos son: &#8211; Fomentar h\u00e1bitos de lectura para resaltar la importancia de conservar y transmitir la cultura. &#8211; Impulsar la lectura como actividad que permite el desarrollo del lenguaje y mejorar las relaciones humanas y nuestra expresi\u00f3n oral y escreita. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/04\/14\/peticion-de-familiares-dia-del-libro\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLOS PERSONAJES SALEN DEL LIBRO. PETICI\u00d3N DE VOLUNTARIOS\/AS D\u00cdA DEL LIBRO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"post_folder":[],"class_list":["post-2021","post","type-post","status-publish","format-standard","hentry","category-centro"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/centro\/\" rel=\"category tag\">Centro<\/a>","rttpg_excerpt":"\u00a0 Desde el Colegio, estamos organizando la actividad de Cebtro: El d\u00eda del Libro. Cuyos objetivos son: &#8211; Fomentar h\u00e1bitos de lectura para resaltar la importancia de conservar y transmitir la cultura. &#8211; Impulsar la lectura como actividad que permite el desarrollo del lenguaje y mejorar las relaciones humanas y nuestra expresi\u00f3n oral y escreita.&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2021"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2021\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2021"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}