{"id":2031,"date":"2018-04-17T08:58:09","date_gmt":"2018-04-17T08:58:09","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2031"},"modified":"2018-04-17T08:58:09","modified_gmt":"2018-04-17T08:58:09","slug":"campeonas-baloncesto-benjamin","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/04\/17\/campeonas-baloncesto-benjamin\/","title":{"rendered":"CAMPEONAS BALONCESTO BENJAM\u00cdN"},"content":{"rendered":"<p>Felicidades a Iria, Cristina, Emma, Ichi, Basma, Sandra, Piedad y Alba campeonas de los Juegos Escolares <b>de Aranjuez, en Baloncesto categor\u00eda\u00a0<\/b>Benjam\u00edn Femenino y felicidades y muchas gracias a sus entrenadores Jacob y Emilio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DavPQuSW4AAi7nJ.jpg\" alt=\"\" width=\"446\" height=\"382\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DavPRyXW4AAHxuI.jpg\" alt=\"\" width=\"501\" height=\"381\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Felicidades a Iria, Cristina, Emma, Ichi, Basma, Sandra, Piedad y Alba campeonas de los Juegos Escolares de Aranjuez, en Baloncesto categor\u00eda\u00a0Benjam\u00edn Femenino y felicidades y muchas gracias a sus entrenadores Jacob y Emilio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-2031","post","type-post","status-publish","format-standard","hentry","category-deportes"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/deportes\/\" rel=\"category tag\">Deportes<\/a>","rttpg_excerpt":"Felicidades a Iria, Cristina, Emma, Ichi, Basma, Sandra, Piedad y Alba campeonas de los Juegos Escolares de Aranjuez, en Baloncesto categor\u00eda\u00a0Benjam\u00edn Femenino y felicidades y muchas gracias a sus entrenadores Jacob y Emilio.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2031"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2031\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2031"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}