{"id":2040,"date":"2018-04-18T10:15:49","date_gmt":"2018-04-18T10:15:49","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2040"},"modified":"2018-04-18T10:15:49","modified_gmt":"2018-04-18T10:15:49","slug":"concurso-infantil-de-chistes-18-y-19-de-abril","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/04\/18\/concurso-infantil-de-chistes-18-y-19-de-abril\/","title":{"rendered":"CONCURSO INFANTIL DE CHISTES. 18 Y 19 DE ABRIL."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Da994kXX0AAk6zJ.jpg\" alt=\"\" width=\"970\" height=\"753\" \/><\/p>\n<p>Un chiste por participante apto para todos los p\u00fablicos, los jurados Elisa y Gonzalo de quinto valorar\u00e1n la gracia de los chistes, todos los puntos contar\u00e1n para la Charlie Points.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un chiste por participante apto para todos los p\u00fablicos, los jurados Elisa y Gonzalo de quinto valorar\u00e1n la gracia de los chistes, todos los puntos contar\u00e1n para la Charlie Points.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"post_folder":[],"class_list":["post-2040","post","type-post","status-publish","format-standard","hentry","category-centro"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/centro\/\" rel=\"category tag\">Centro<\/a>","rttpg_excerpt":"Un chiste por participante apto para todos los p\u00fablicos, los jurados Elisa y Gonzalo de quinto valorar\u00e1n la gracia de los chistes, todos los puntos contar\u00e1n para la Charlie Points.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2040"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2040\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2040"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}