{"id":2212,"date":"2018-06-21T05:48:02","date_gmt":"2018-06-21T05:48:02","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2212"},"modified":"2018-06-21T05:48:02","modified_gmt":"2018-06-21T05:48:02","slug":"salvar-carlononia","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/06\/21\/salvar-carlononia\/","title":{"rendered":"SALVAR CARLONONIA"},"content":{"rendered":"<p>El martes 19 y mi\u00e9rcoles 20 los alumnos y alumnas de 5\u00ba y 6\u00ba de Primaria, disfrutaron de una aventura \u00abSalvar Carlononia\u00bb, en el siguiente v\u00eddeo os contamos cual era su misi\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/hQhqtIV8Z-E\" width=\"672\" height=\"553\"><\/iframe><\/p>\n<p>Todos los equipos consiguieron salir del Jard\u00edn del Pr\u00edncipe en menos de 90 minutos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DgDCLg3X4AE7J6n.jpg\" alt=\"\" width=\"673\" height=\"381\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes 19 y mi\u00e9rcoles 20 los alumnos y alumnas de 5\u00ba y 6\u00ba de Primaria, disfrutaron de una aventura \u00abSalvar Carlononia\u00bb, en el siguiente v\u00eddeo os contamos cual era su misi\u00f3n. Todos los equipos consiguieron salir del Jard\u00edn del Pr\u00edncipe en menos de 90 minutos.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"post_folder":[],"class_list":["post-2212","post","type-post","status-publish","format-standard","hentry","category-2-tramo"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/2-tramo\/\" rel=\"category tag\">2\u00ba Tramo<\/a>","rttpg_excerpt":"El martes 19 y mi\u00e9rcoles 20 los alumnos y alumnas de 5\u00ba y 6\u00ba de Primaria, disfrutaron de una aventura \u00abSalvar Carlononia\u00bb, en el siguiente v\u00eddeo os contamos cual era su misi\u00f3n. Todos los equipos consiguieron salir del Jard\u00edn del Pr\u00edncipe en menos de 90 minutos.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2212"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2212\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2212"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}