{"id":2230,"date":"2018-08-21T09:26:11","date_gmt":"2018-08-21T09:26:11","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2230"},"modified":"2018-08-21T09:26:11","modified_gmt":"2018-08-21T09:26:11","slug":"calendario-escolar-curso-2018-19","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/08\/21\/calendario-escolar-curso-2018-19\/","title":{"rendered":"CALENDARIO ESCOLAR CURSO 2018\/19"},"content":{"rendered":"<p><strong><span style=\"font-size: 14pt;\">Inicio del curso escolar viernes 7 de septiembre.<\/span><\/strong><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Horario durante el mes de septiembre:<\/span><\/strong><\/p>\n<p>Las Ma\u00f1anas de Mi Cole de 07:00 a 09:00. Pendiente de confirmaci\u00f3n del Ayuntamiento de Aranjuez.<\/p>\n<p>Horario lectivo de 09:00 a 13:00.<\/p>\n<p>Servicio de Comedor de 13:00 a 15:00.<\/p>\n<p>Las Tarde de Mi Cole de 15:00 a 17:00. Pendiente de confirmaci\u00f3n del Ayuntamiento de Aranjuez.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cppm.es\/wp-content\/uploads\/2018\/06\/calendario-escolar-comunidad-madrid-curso-2018-2019.jpg\" alt=\"\" \/><\/p>\n<p><strong>\u00a1ATENCI\u00d3N!\u00a0<\/strong>A este calendario, para el 2018, hay que a\u00f1adir los d\u00edas de fiesta de \u00e1mbito local que haya determinado cada municipio y as\u00ed aparezcan publicados en el BOCM. En el 2019, se a\u00f1ade, las festividades que determina la Comunidad Aut\u00f3noma de Madrid en el ejercicio de sus competencias, los d\u00edas de fiesta de \u00e1mbito nacional no trasladables que se establezcan y, en cada municipio, los d\u00edas de fiesta local que aparezcan publicados en el BOCM.<\/p>\n<p>\u00a0<\/p>\n<p><strong>ORDEN 2227\/2018, de 20 de junio, de la Consejer\u00eda de Educaci\u00f3n e Investigaci\u00f3n, por la que se establece el calendario escolar para el curso 2018-2019 en los centros educativos no universitarios sostenidos con fondos p\u00fablicos de la Comunidad de Madrid.<\/strong><\/p>\n<p>De acuerdo con lo establecido en la disposici\u00f3n adicional quinta de la Ley Org\u00e1nica 2\/2006 de Educaci\u00f3n, de 3 de mayo, la Administraci\u00f3n educativa debe establecer anualmente el calendario escolar, que comprender\u00e1\u00a0<strong>un m\u00ednimo de 175 d\u00edas lectivos para las ense\u00f1anzas obligatorias.<\/strong><\/p>\n<p>En el proceso de elaboraci\u00f3n de esta orden, han sido o\u00eddas las organizaciones representativas del profesorado y ha emitido dictamen el Consejo Escolar de la Comunidad de Madrid, de acuerdo con el art\u00edculo 2.1.b) de la Ley 12\/1999, de 29 de abril, de creaci\u00f3n del Consejo Escolar de la Comunidad de Madrid, modificado por el art\u00edculo 29 de la Ley 9\/2010, de 23 de diciembre. Asimismo, se ha tenido en cuenta el art\u00edculo 41.d) de la Ley 1\/1983, de 13 de diciembre, del Gobierno y la Administraci\u00f3n de la Comunidad de Madrid.<\/p>\n<p>En uso de las competencias atribuidas por el Decreto 127\/2017, de 24 de octubre, del Consejo de Gobierno, por el que se establece la estructura org\u00e1nica de la Consejer\u00eda de Educaci\u00f3n e Investigaci\u00f3n,<\/p>\n<p>DISPONGO<br \/><strong>Art\u00edculo 1. Objeto y \u00e1mbito de aplicaci\u00f3n<\/strong><br \/>La presente orden tiene por objeto establecer el calendario escolar para el curso 2018-2019. Su contenido ser\u00e1 de aplicaci\u00f3n en los centros sostenidos con fondos p\u00fablicos que impartan\u00a0<strong>ense\u00f1anzas de Educaci\u00f3n Infantil, Educaci\u00f3n Primaria, Educaci\u00f3n Especial, Educaci\u00f3n Secundaria Obligatoria, Bachillerato, Formaci\u00f3n Profesional, Ense\u00f1anzas de R\u00e9gimen Especial y Educaci\u00f3n de Personas Adultas en la Comunidad de Madrid.<\/strong><\/p>\n<p><strong>Art\u00edculo 2. Educaci\u00f3n Infantil, Educaci\u00f3n Primaria y Educaci\u00f3n Especial<\/strong><br \/>2.1. Actividades escolares: Las actividades escolares se desarrollar\u00e1n entre los d\u00edas 3 de septiembre de 2018 y 28 de junio de 2019, salvo en las Escuelas Infantiles, Casas de Ni\u00f1os y Escuelas Infantiles privadas sostenidas con fondos p\u00fablicos que desarrollar\u00e1n su actividad escolar entre los d\u00edas 3 de septiembre de 2018 y 31 de julio de 2019, con excepci\u00f3n, en todos los casos, de las correspondientes vacaciones y d\u00edas festivos.<\/p>\n<p><strong>2.2. Actividades lectivas:<\/strong><br \/>2.2.1.\u00a0<strong>En las Escuelas Infantiles, Casas de Ni\u00f1os y Escuelas Infantiles privadas sostenidas con fondos p\u00fablicos, las actividades lectivas comenzar\u00e1n el d\u00eda 6 de septiembre de 2018 y finalizar\u00e1n el d\u00eda 31 de julio de 2019.<\/strong><br \/>Los ni\u00f1os escolarizados en unidades de segundo ciclo de Educaci\u00f3n Infantil en Escuelas Infantiles, Casas de Ni\u00f1os y Escuelas Infantiles privadas sostenidas con fondos p\u00fablicos podr\u00e1n hacer uso del calendario de primer ciclo de Educaci\u00f3n Infantil en las condiciones que oportunamente establezca la Consejer\u00eda de Educaci\u00f3n e Investigaci\u00f3n.<br \/>2.2.2.\u00a0<strong>En los centros que imparten segundo ciclo de Educaci\u00f3n Infantil, Educaci\u00f3n Primaria o Educaci\u00f3n Especial, las actividades lectivas comenzar\u00e1n el d\u00eda 7 de septiembre de 2018 y finalizar\u00e1n el 21 de junio de 2019.<\/strong><\/p>\n<p><strong>Art\u00edculo 3.\u00a0Educaci\u00f3n Secundaria Obligatoria, Bachillerato, Formaci\u00f3n Profesional, Ense\u00f1anzas de R\u00e9gimen Especial y Educaci\u00f3n de Personas Adultas<\/strong><br \/>3.1. Actividades escolares: Las actividades escolares se desarrollar\u00e1n entre los d\u00edas 3 de septiembre de 2018 y 28 de junio de 2019, con excepci\u00f3n de las correspondientes vacaciones y d\u00edas festivos.<\/p>\n<p><strong>3.2. Actividades lectivas:<\/strong><br \/>3.2.1.\u00a0<strong>En los centros que imparten Educaci\u00f3n Secundaria Obligatoria, Bachillerato y Formaci\u00f3n Profesional, las actividades lectivas comenzar\u00e1n el d\u00eda 10 de septiembre de 2018 en Educaci\u00f3n Secundaria Obligatoria, Bachillerato, Programas Profesionales, Formaci\u00f3n Profesional B\u00e1sica y ciclos formativos de Formaci\u00f3n Profesional de Grado Medio y Superior.<\/strong>\u00a0Las actividades lectivas de los citados centros terminar\u00e1n el d\u00eda 21 de junio de 2019, excepto para los alumnos de segundo curso de Bachillerato que finalizar\u00e1n sus actividades lectivas en funci\u00f3n de las necesidades derivadas de la realizaci\u00f3n de la evaluaci\u00f3n final de Bachillerato y los procedimientos de admisi\u00f3n en la Universidad.<\/p>\n<p>Con car\u00e1cter general, en los centros citados anteriormente en este apartado 3.2.1, la evaluaci\u00f3n final ordinaria deber\u00e1 estar concluida antes del 7 de junio de 2019. Una vez realizada la evaluaci\u00f3n final ordinaria, el per\u00edodo comprendido hasta el 21 de junio de 2019, se destinar\u00e1, seg\u00fan corresponda en cada caso, a:<br \/>\u2014 Actividades de apoyo, refuerzo, tutorizaci\u00f3n y realizaci\u00f3n de las pruebas extraordinarias de evaluaci\u00f3n para alumnos con materias pendientes.<br \/>\u2014 Actividades de ampliaci\u00f3n para alumnos sin materias pendientes.<br \/>En el marco de la autonom\u00eda de los centros, las pruebas extraordinarias de evaluaci\u00f3n para alumnos con materias pendientes podr\u00e1n realizarse hasta el 25 de junio de 2019.<\/p>\n<p>3.2.2.\u00a0<strong>En los centros de Educaci\u00f3n de Personas Adultas las actividades lectivas comenzar\u00e1n el d\u00eda 17 de septiembre de 2018<\/strong>, excepto en el caso de los centros penitenciarios, que comenzar\u00e1n el 7 de septiembre de 2018. La finalizaci\u00f3n de las actividades lectivas ser\u00e1 el d\u00eda 21 de junio de 2019.<\/p>\n<p>3.2.3.\u00a0<strong>En los Conservatorios Profesionales de M\u00fasica y en los Conservatorios Profesionales de Danza las actividades lectivas comenzar\u00e1n el d\u00eda 10 de septiembre de 2018<\/strong>\u00a0y finalizar\u00e1n\u00a0el d\u00eda 21 de junio de 2019. La evaluaci\u00f3n final ordinaria se realizar\u00e1 antes del 24 de mayo de 2019. En el per\u00edodo comprendido desde la finalizaci\u00f3n de dicha evaluaci\u00f3n al 21 de junio de 2019 se realizar\u00e1n actividades de repaso y profundizaci\u00f3n, pruebas extraordinarias y evaluaci\u00f3n final extraordinaria. Los alumnos de 6.o curso de ense\u00f1anzas profesionales finalizar\u00e1n sus actividades lectivas en funci\u00f3n de las necesidades derivadas de la realizaci\u00f3n de la evaluaci\u00f3n final de Bachillerato y los procedimientos de admisi\u00f3n en la Universidad.<\/p>\n<p>3.2.4.\u00a0<strong>En las Escuelas de Arte las actividades lectivas comenzar\u00e1n el d\u00eda 17 de septiembre de 2018 para el segundo curso y el d\u00eda 24 de septiembre de 2018 para el primer curso de los ciclos de Artes Pl\u00e1sticas y Dise\u00f1o<\/strong>\u00a0y finalizar\u00e1n el d\u00eda 21 de junio de 2019. La evaluaci\u00f3n final ordinaria deber\u00e1 estar concluida antes del 7 de junio de 2019. Entre el 10 y el 21 de junio de 2019 se realizar\u00e1n actividades de repaso y profundizaci\u00f3n, pruebas extraordinarias y evaluaci\u00f3n final extraordinaria.<\/p>\n<p>3.2.5.\u00a0<strong>En las Escuelas Oficiales de Idiomas las actividades lectivas comenzar\u00e1n el d\u00eda 17 de septiembre de 2018.<\/strong>\u00a0La convocatori<br \/>\na ordinaria se realizar\u00e1 antes del 7 de junio de 2019. En el marco de la autonom\u00eda de los centros, las pruebas extraordinarias de evaluaci\u00f3n y de certificaci\u00f3n podr\u00e1n realizarse hasta el d\u00eda 25 de junio de 2019.<\/p>\n<p>3.2.6.\u00a0<strong>En los centros integrados de Ense\u00f1anzas Art\u00edsticas de M\u00fasica y de Educaci\u00f3n Primaria y\/o Secundaria:<\/strong><br \/>\u2014 Las ense\u00f1anzas de M\u00fasica que se imparten de forma no integrada en estos centros seguir\u00e1n el calendario establecido para los Conservatorios Profesionales de M\u00fasica.<br \/>\u2014 Las ense\u00f1anzas que se imparten de forma integrada en estos centros comenzar\u00e1n sus actividades lectivas el d\u00eda 7 de septiembre de 2018 y finalizar\u00e1n el d\u00eda 21 de junio de 2019 en la etapa de Educaci\u00f3n Primaria. En la etapa de Educaci\u00f3n Secundaria\u00a0Obligatoria ser\u00e1 de aplicaci\u00f3n lo establecido en el apartado 3.2.1 de la presente orden.<\/p>\n<p>3.2.7.\u00a0<strong>En los centros de Ense\u00f1anzas Art\u00edsticas Superiores: Real Conservatorio Superior de M\u00fasica, Escuela Superior de Canto, Real Escuela Superior de Arte Dram\u00e1tico, Conservatorio Superior de Danza, Conservatorio Superior de Danza \u201cMar\u00eda de \u00c1vila\u201d, Escuela Superior de Conservaci\u00f3n y Restauraci\u00f3n de Bienes Culturales y Escuela Superior de Dise\u00f1o; las actividades lectivas comenzar\u00e1n el d\u00eda 10 de septiembre de 2018<\/strong>. La evaluaci\u00f3n\u00a0final ordinaria deber\u00e1 estar concluida el 7 de junio de 2019. El per\u00edodo posterior comprendido hasta el 28 de junio se destinar\u00e1 a la realizaci\u00f3n de la convocatoria extraordinaria y al resto de actividades lectivas que correspondan.<\/p>\n<p><strong>Art\u00edculo 4. Vacaciones escolares y otros d\u00edas no lectivos para los centros educativos<\/strong><br \/><strong>4.1. Vacaciones:<\/strong><br \/>4.1.1.\u00a0<strong>De Navidad. Comprender\u00e1n desde el d\u00eda 22 de diciembre de 2018 hasta el d\u00eda 6 de enero de 2019<\/strong>, ambos inclusive, excepto en las Escuelas Infantiles y Escuelas Infantiles privadas sostenidas con fondos p\u00fablicos que comprender\u00e1n desde el 23 de diciembre de 2018 hasta el 1 de enero de 2019, ambos inclusive.<br \/>4.1.2.\u00a0<strong>De Semana Santa. Comprender\u00e1n desde el d\u00eda 13 al 21 de abril de 2019, ambos inclusive.<\/strong><br \/>4.1.3.\u00a0<strong>De verano. Se iniciar\u00e1n el d\u00eda 1 de julio de 2019 excepto en Escuelas Infantiles, Casas de Ni\u00f1os y Escuelas Infantiles privadas sostenidas con fondos p\u00fablicos en las que se iniciar\u00e1n el 1 de agosto de 2019.<\/strong>\u00a0En todos los centros terminar\u00e1n el d\u00eda anterior al comienzo\u00a0del curso 2019-2020.<br \/>4.2. Festividades y otros d\u00edas no lectivos: Las festividades y los otros d\u00edas no lectivos tendr\u00e1n los mismos efectos para los centros educativos que las vacaciones escolares.<br \/><strong>4.2.1. Festividades:<\/strong><br \/>\u2014 A\u00f1o 2018:<br \/>12 de Octubre.<br \/>1 de noviembre.<br \/>6 de diciembre.<br \/>Los d\u00edas de fiesta de \u00e1mbito local que haya determinado cada municipio para el a\u00f1o 2018 y as\u00ed aparezcan publicados en el BOLET\u00cdN OFICIAL DE LA COMUNIDAD DE MADRID.<br \/>\u2014 A\u00f1o 2019:<br \/>Los d\u00edas festivos para el a\u00f1o 2019, que ser\u00e1n establecidos con posterioridad a la firma y difusi\u00f3n de la presente orden, tendr\u00e1n efecto sobre el curso 2018-2019.<\/p>\n<p><strong>Dichos d\u00edas festivos ser\u00e1n los siguientes:<\/strong><br \/>Los que determine la Comunidad de Madrid para el a\u00f1o 2019 en el ejercicio de sus competencias.<br \/>Los d\u00edas de fiesta de \u00e1mbito nacional no trasladables que se establezcan para el a\u00f1o 2019.<br \/>Los d\u00edas de fiesta local que determine cada municipio para el a\u00f1o 2019 y as\u00ed aparezcan publicados en el BOLET\u00cdN OFICIAL DE LA COMUNIDAD DE MADRID.<\/p>\n<p>4.2.2. Otros d\u00edas no lectivos: A excepci\u00f3n de las Escuelas Infantiles y Escuelas infantiles privadas sostenidas con fondos p\u00fablicos, en las que \u00fanicamente ser\u00e1n de aplicaci\u00f3n el 7 de diciembre de 2018 y el 3 de mayo de 2019, tambi\u00e9n ser\u00e1n no lectivos para los centros educativos los siguientes d\u00edas:<br \/>\u2014 2 de noviembre de 2018.<br \/>\u2014 7 de diciembre de 2018.<br \/>\u2014 7 de enero de 2019.<br \/>\u2014 1 y 4 de marzo de 2019.<br \/>\u2014 12 y 22 de abril de 2019.<br \/>\u2014 3 de mayo de 2019.<br \/>Los centros privados sostenidos con fondos p\u00fablicos podr\u00e1n trasladar, previo acuerdo del consejo escolar y notificaci\u00f3n a la correspondiente Direcci\u00f3n de \u00c1rea Territorial, uno de los citados d\u00edas no lectivos para facilitar la celebraci\u00f3n del patrono del centro. Dichos traslados de fecha deben ser notificados con antelaci\u00f3n suficiente tanto a las familias como a las Direcciones de \u00c1rea Territorial.<\/p>\n<p><strong>Art\u00edculo 5. Especificaciones para la aplicaci\u00f3n del calendario escolar\u00a0en los centros educativos de titularidad p\u00fablica<\/strong><br \/>5.1. Inicio de la actividad en los centros: el profesorado comenzar\u00e1 las actividades escolares en sus centros el d\u00eda 3 de septiembre de 2018 (para tareas de preparaci\u00f3n, programaci\u00f3n, coordinaci\u00f3n, organizaci\u00f3n del curso, etc.) de conformidad con las horas semanales\u00a0reglamentariamente establecidas.<br \/>5.2. Comedor escolar en colegios de Educaci\u00f3n Infantil y Primaria y centros de Educaci\u00f3n Especial: conforme a lo dispuesto en el art\u00edculo primero de la Orden 3028\/2005, de 3 de junio, de la Consejer\u00eda de Educaci\u00f3n, por la que se modifica parcialmente la Orden 917\/2002, de 14 de marzo, por la que se regulan los comedores escolares en los centros p\u00fablicos no universitarios de la Comunidad de Madrid, el servicio de comedor escolar se prestar\u00e1, con car\u00e1cter general, durante todos los d\u00edas lectivos del curso.<br \/>5.3. En colegios de Educaci\u00f3n Infantil y Primaria y centros de Educaci\u00f3n Especial:<br \/>en los per\u00edodos comprendidos entre el 7 y 28 de septiembre de 2018 y entre el 3 y 21 de junio de 2019 las actividades lectivas podr\u00e1n desarrollarse durante la ma\u00f1ana, en jornada de cuatro horas. Asimismo, previo acuerdo del consejo escolar, el d\u00eda 21 de diciembre de 2018 podr\u00e1n desarrollarse las actividades lectivas durante la ma\u00f1ana, en jornada de cuatro horas.<\/p>\n<p>En todos los casos, el servicio de comedor deber\u00e1 permanecer abierto.<br \/>5.4. Evaluaciones y trabajos relacionados con la finalizaci\u00f3n del curso escolar: a partir de la fecha establecida para la finalizaci\u00f3n de las actividades lectivas, los d\u00edas h\u00e1biles restantes se dedicar\u00e1n a completar la evaluaci\u00f3n de alumnos, reuniones del claustro de profesores y del consejo escolar y dem\u00e1s actividades recogidas en las disposiciones normativas que regulan tales extremos, todo ello dentro de la autonom\u00eda organizativa de los centros que siempre debe ser ejercida para el mejor desempe\u00f1o de sus funciones.<\/p>\n<p>Asimismo, en los centros donde se impartan Ense\u00f1anzas de R\u00e9gimen Especial, a partir de la fecha de finalizaci\u00f3n de las actividades lectivas, los d\u00edas h\u00e1biles restantes se dedicar\u00e1n a las actividades acad\u00e9micas establecidas en la normativa vigente que regula dichas ense\u00f1anzas.<\/p>\n<p><strong>Art\u00edculo 6.\u00a0Especificaciones para la aplicaci\u00f3n del calendario escolar\u00a0<\/strong><strong>en centros privados sostenidos con fondos p\u00fablicos<\/strong><br \/>En los centros privados sostenidos con fondos p\u00fablicos de Educaci\u00f3n Infantil y Primaria: en los per\u00edodos comprendidos entre el 7 y el 28 de septiembre de 2018, el 21 de diciembre\u00a0de 2018 y entre el 1 y el 21 de junio de 2019, las actividades lectivas en dichos centros podr\u00e1n desarrollarse en jornada intensiva, si as\u00ed lo acuerda el titular del centro.<\/p>\n<p><strong>Art\u00edculo 7.\u00a0Cumplimiento y publicidad<\/strong><br \/>7.1. En los centros sostenidos con fondos p\u00fablicos, las fechas de inicio y final de curso para cada etapa o ense\u00f1anza tienen car\u00e1cter de m\u00ednimos obligatorios. El curso no podr\u00e1 iniciarse despu\u00e9s, ni finalizar antes, de las fechas se\u00f1aladas en cada caso.<br \/>7.2. El calendario escolar se expondr\u00e1 en cada centro docente de forma visible para todos los interesados y se entregar\u00e1 copia del mismo a los miembros del consejo escolar y a la Asociaci\u00f3n de Madres y Padres de Alumnos para conocimiento de toda la comunidad educativa.<br \/>7.3. Los directores de los centros educativos son los responsables del cumplimiento del presente calendario escolar.<br \/>7.4. El pres<br \/>\nente calendario escolar no podr\u00e1 ser modificado salvo en casos excepcionales que deber\u00e1n ser adecuadamente justificados y comunicados con la debida antelaci\u00f3n.<br \/>En todo caso, la modificaci\u00f3n deber\u00e1 ser previamente autorizada por la Viceconsejer\u00eda de Pol\u00edtica Educativa y Ciencia a propuesta de la Direcci\u00f3n de \u00c1rea Territorial o de la Direcci\u00f3n General correspondiente.<\/p>\n<p>Madrid, a 20 de junio de 2018.<\/p>\n<p>El Consejero de Educaci\u00f3n e Investigaci\u00f3n,<br \/>RAFAEL VAN GRIEKEN SALVADOR<\/p>\n<p><strong>INICIO\u00a0PERIODO LECTIVO:<br \/><\/strong><\/p>\n<p>\u2022\u00a0Escuelas<strong>\u00a0INFANTILES<\/strong>, casas de ni\u00f1os y EEII privadas sostenidas con fondos p\u00fablicos [<strong>\u00a06 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Centros de Educaci\u00f3n\u00a0<strong>INFANTIL y PRIMARIA<\/strong>\u00a0[\u00a0<strong>7 de septiembre<\/strong>\u00a02018]<br \/>\u2022 Centros de Educaci\u00f3n\u00a0<strong>ESPECIAL<\/strong>\u00a0[\u00a0<strong>7 de septiembre<\/strong>\u00a02018]<br \/>\u2022 Institutos Educaci\u00f3n\u00a0<strong>SECUNDARIA<\/strong>\u00a0[<strong>10 de septiembre<\/strong>\u00a02018]<br \/>\u2022\u00a0<strong>BACHILLERATO<\/strong>\u00a0[<strong>10 de septiembre<\/strong>\u00a02018]<br \/>\u2022\u00a0<strong>PROGRAMAS PROFESIONALES<\/strong>\u00a0[<strong>10<\/strong>\u00a0<strong>de septiembre<\/strong>\u00a02018]<br \/>\u2022 Ciclos de\u00a0<strong>FP. B\u00c1SICA<\/strong>\u00a0y Ciclos Formativos de\u00a0<strong>GRADO MEDIO<\/strong>\u00a0y SUPERIOR [<strong>10 de septiembre<\/strong>\u00a02018]<br \/>\u2022 Escuelas Oficiales de\u00a0<strong>IDIOMAS<\/strong>\u00a0[<strong>13 de septiembre<\/strong>\u00a02018]<br \/>\u2022 Educaci\u00f3n de Personas\u00a0<strong>ADULTAS<\/strong>\u00a0en Centros PENITENCIARIOS [\u00a0<strong>7\u00a0de septiembre<\/strong>\u00a02018]<br \/>\u2022 Centros de Educaci\u00f3n de Personas\u00a0<strong>ADULTAS<\/strong>\u00a0(excepto centros penitenciarios) [<strong>17 de septiembre<\/strong>\u00a02018]<br \/>\u2022\u00a0Centros Integrados de EE. Art\u00edsticas de\u00a0<strong>M\u00daSICA<\/strong>\u00a0y de Educaci\u00f3n\u00a0<strong>PRIMARIA<\/strong>\u00a0[<strong>\u00a07\u00a0de septiembre<\/strong>\u00a02018]<br \/>\u2022 Centros Integrados de EE. Art\u00edsticas de\u00a0<strong>M\u00daSICA<\/strong>\u00a0y de Educaci\u00f3n\u00a0<strong>SECUNDARIA\u00a0<\/strong>[\u00a0<strong>10 de septiembre<\/strong>\u00a02018]<br \/>\u2022\u00a0Institutos Educaci\u00f3n\u00a0<strong>SECUNDARIA<\/strong>\u00a0 [\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Conservatorios Profesionales\u00a0<strong>M\u00daSICA<\/strong>\u00a0[\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Conservatorios Profesionales\u00a0<strong>DANZA<\/strong>\u00a0[\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Escuelas de\u00a0<strong>ARTE\u00a0<\/strong>&#8211; 2\u00ba curso de los ciclos de Artes Pl\u00e1sticas y Dise\u00f1o [\u00a0<strong>24 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Escuelas de\u00a0<strong>ARTE<\/strong>\u00a0&#8211; 1er. Curso de los ciclos de Artes Pl\u00e1sticas y Dise\u00f1o [\u00a0<strong>17 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Centros de\u00a0<strong>EE. ART\u00cdSTICAS<\/strong>\u00a0Superior [\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Real Conservatorio Superior\u00a0<strong>M\u00daSICA<\/strong>\u00a0[\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Escuela Superior de\u00a0<strong>CANTO<\/strong>\u00a0[\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Escuela Superior\u00a0<strong>CONSERVACI\u00d3N<\/strong>\u00a0y Restauraci\u00f3n de Bienes Culturales [\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Escuela Superior de\u00a0<strong>DISE\u00d1O<\/strong>\u00a0[\u00a0<strong>10 de septiembre<\/strong>\u00a02018 ]<br \/>\u2022 Real Escuela Superior\u00a0<strong>ARTE DRAM\u00c1TICO<\/strong>\u00a0[\u00a0<strong>10 de septiembre<\/strong>\u00a02018]<br \/>\u2022 Conservatorio Superior de\u00a0<strong>DANZA<\/strong>\u00a0[\u00a0<strong>10 de septiembre<\/strong>\u00a02018]<br \/>\u2022 Conservatorio Superior de\u00a0<strong>DANZA<\/strong>\u00a0\u00abMar\u00eda de \u00c1vila\u00bb [\u00a0<strong>10 de septiembre<\/strong>\u00a02018]<\/p>\n<p><strong>FINALIZACI\u00d3N<\/strong><strong>\u00a0<\/strong><strong>DEL PERIODO LECTIVO:<br \/><\/strong><\/p>\n<p>\u2022 Escuelas\u00a0<strong>INFANTILES<\/strong>, casas de ni\u00f1os y EEII privadas sostenidas con fondos p\u00fablicos [<strong>31\u00a0de julio<\/strong>\u00a02019]<br \/>\u2022 Centros de Educaci\u00f3n<strong>\u00a0INFANTIL y PRIMARIA<\/strong>\u00a0[\u00a0<strong>21 de junio<\/strong>\u00a02019]<br \/>\u2022 Centros de Educaci\u00f3n\u00a0<strong>ESPECIAL<\/strong>\u00a0[<strong>22 de junio<\/strong>\u00a02019]<br \/>\u2022 Centros de Educaci\u00f3n Personas\u00a0<strong>ADULTAS<\/strong>\u00a0y Centros Penitenciarios [<strong>21 de junio<\/strong>\u00a02019]<br \/>\u2022 Institutos Educaci\u00f3n\u00a0<strong>SECUNDARIA<\/strong>\u00a0[excepto el alumnado de 2\u00ba de Bachillerato que\u00a0finalizar\u00e1 sus actividades lectivas en funci\u00f3n de las necesidades derivadas de la realizaci\u00f3n de la evaluaci\u00f3n final de Bachillerato y los procedimientos de admisi\u00f3n en la Universidad] [<strong>21 de junio<\/strong>\u00a02019]<br \/>\u2022 Escuelas de\u00a0<strong>ARTE<\/strong>\u00a0[<strong>21 de junio<\/strong>\u00a02019]<br \/>\u2022 Centros\u00a0<strong>Integrados<\/strong>\u00a0de EE. Art\u00edsticas de\u00a0<strong>M\u00daSICA<\/strong>\u00a0y Educaci\u00f3n\u00a0<strong>PRIMARIA\u00a0<\/strong>y\/o<strong>\u00a0SECUNDARIA<\/strong>\u00a0[<strong>21 de junio<\/strong>\u00a02019]<br \/>\u2022 Centros de\u00a0<strong>EE. ART\u00cdSTICAS<\/strong>\u00a0Superior [2<strong>8\u00a0de junio<\/strong>\u00a02019]<br \/>\u2022 Real Conservatorio Superior\u00a0<strong>M\u00daSICA<\/strong>\u00a0[2<strong>8\u00a0de junio<\/strong>\u00a02019]<br \/>\u2022 Escuela Superior\u00a0<strong>CANTO<\/strong>\u00a0[2<strong>8 de junio<\/strong>\u00a02019]<br \/>\u2022 Real Escuela Superior\u00a0<strong>ARTE DRAM\u00c1TICO<\/strong>\u00a0[<strong>8 de junio<\/strong>\u00a02019]<br \/>\u2022 Conservatorio Superior\u00a0<strong>DANZA<\/strong>\u00a0[2<strong>8 de junio<\/strong>\u00a02019]<br \/>\u2022 Escuela Sup.\u00a0<strong>CONSERVACI\u00d3N<\/strong>\u00a0y Restauraci\u00f3n\u00a0de Bienes Culturales [2<strong>8 de junio<\/strong>\u00a02019]<br \/>\u2022 Escuela Superior de\u00a0<strong>DISE\u00d1O<\/strong>\u00a0[2<strong>8 de junio<\/strong>\u00a02019]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong><span style=\"font-size: 14pt;\">Inicio del curso escolar viernes 7 de septiembre.<\/span><\/strong><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Horario durante el mes de septiembre:<\/span><\/strong><\/p>\n<p>Las Ma\u00f1anas de Mi Cole de 07:00 a 09:00. Pendiente de confirmaci\u00f3n del Ayuntamiento de Aranjuez.<\/p>\n<p>Horario lectivo de 09:00 a 13:00.<\/p>\n<p>Servicio de Comedor de 13:00 a 15:00.<\/p>\n<p>Las Tarde de Mi Cole de 15:00 a 17:00. Pendiente de confirmaci\u00f3n del Ayuntamiento de Aranjuez.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cppm.es\/wp-content\/uploads\/2018\/06\/calendario-escolar-comunidad-madrid-curso-2018-2019.jpg\" alt=\"\" \/><\/p>\n<p><strong>\u00a1ATENCI\u00d3N!\u00a0<\/strong>A este calendario, para el 2018, hay que a\u00f1adir los d\u00edas de fiesta de \u00e1mbito local que haya determinado cada municipio y as\u00ed aparezcan publicados en el BOCM. En el 2019, se a\u00f1ade, las festividades que determina la Comunidad Aut\u00f3noma de Madrid en el ejercicio de sus competencias, los d\u00edas de fiesta de \u00e1mbito nacional no trasladables que se establezcan y, en cada municipio, los d\u00edas de fiesta local que aparezcan publicados en el BOCM.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-2230","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Inicio del curso escolar viernes 7 de septiembre. Horario durante el mes de septiembre: Las Ma\u00f1anas de Mi Cole de 07:00 a 09:00. Pendiente de confirmaci\u00f3n del Ayuntamiento de Aranjuez. Horario lectivo de 09:00 a 13:00. Servicio de Comedor de 13:00 a 15:00. Las Tarde de Mi Cole de 15:00 a 17:00. Pendiente de confirmaci\u00f3n&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2230"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2230\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2230"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}