{"id":2263,"date":"2018-09-24T09:41:24","date_gmt":"2018-09-24T09:41:24","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2263"},"modified":"2018-09-24T09:41:24","modified_gmt":"2018-09-24T09:41:24","slug":"nominada-a-la-mejor-docente-de-espana-2018","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/09\/24\/nominada-a-la-mejor-docente-de-espana-2018\/","title":{"rendered":"NOMINADA A LA MEJOR DOCENTE DE ESPA\u00d1A 2018"},"content":{"rendered":"<div id=\"x_cc-m-11562473199\">\n<div id=\"x_cc-m-11562470699\">\n<div id=\"x_cc-m-11562469999\">\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/09\/cartel-nominado-MUJER.png\" alt=\"cartel nominado MUJER\" width=\"257\" height=\"257\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DovO61SWwAARur4.jpg\" alt=\"\" width=\"452\" height=\"257\" \/><\/p>\n<p>\u00a0<\/p>\n<div class=\"et_pb_text et_pb_module et_pb_bg_layout_light et_pb_text_align_justified  et_pb_text_0\">\n<div class=\"et_pb_text_inner\">\n<div id=\"resumen\">\n<p style=\"text-align: justify;\">La profesora del Colegio Carlos III de Aranjuez, Gema Caraballo Tarjuelo, ha sido nominada como finalista a mejor docente de Espa\u00f1a 2018, en los premios Educa Abanca, tal y como promueven estos galardones, por su calidad docente, por su praxis, por su trato con el alumnado, por su preocupaci\u00f3n por el futuro de sus alumnos\u2026<\/p>\n<p style=\"text-align: justify;\">Estos premios, como indica sus objetivos, tienen como fin reconocer p\u00fablicamente la labor de los grandes docentes que viven y disfrutan su trabajo cada d\u00eda, educan para la vida a su alumnado y se involucran al m\u00e1ximo en todo el proceso educativo de su alumnado, tanto dentro como fuera de las aulas.\u00a0<\/p>\n<p style=\"text-align: justify;\">Se trata de unos prestigiosos premios conocidos como los \u201cGoya de la Educaci\u00f3n\u201d que realzan la figura del buen docente y tienen como caracter\u00edstica principal que ning\u00fan profesor se puede presentar individualmente, deben ser sus alumnos o las familias quienes lo propongan. Dado que los nominados salen de las propuestas realizadas por el alumnado, ex alumnado o familiares del alumno, cualquier docente tiene derecho a ser propuesto.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"et_pb_text et_pb_module et_pb_bg_layout_light et_pb_text_align_justified  et_pb_text_2\">\n<div class=\"et_pb_text_inner\">\n<p style=\"text-align: justify;\">De entre las casi 2000 propuestas recibidas por el comit\u00e9 procedentes de todos los rincones de Espa\u00f1a, nuestra Coordinadora del Proyecto Biling\u00fce, Coordinadora de Escuelas Sostenibles,\u00a0 Coordinadora del Hierto Escolar, \u00abGemita\u00bb o Teacher Huerto (como la llaman muchos alumnos y alumnas del Colegio) ha sido seleccionada entre los finalistas de su categor\u00eda, Educaci\u00f3n Primaria.<\/p>\n<p style=\"text-align: justify;\">El colegio quiere dar la m\u00e1s sincera enhorabuena a Gema por este merecido reconocimiento, por la profesionalidad y pasi\u00f3n que muestra en su tarea docente y los valores que transmite a sus alumnos y alumnas, a sus compa\u00f1eros y compa\u00f1eras y a toda la Comunidad del Carlos III.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p><strong><em>Y gracias de parte de Gema \u00abGracias a las mamis y papis que han hecho posible todo esto, muchas gracias por proponerme como mejor docente; pero sobre todo gracias por el apoyo, cari\u00f1o y confianza que me transmitis cada d\u00eda, a m\u00ed , a todos mis compis. Todos juntos hacemos un trabajo estupendo, pero esto te da a\u00fan m\u00e1s energ\u00eda y alegr\u00eda para seguir trabajando como siempre por los ni\u00f1os\u00bb.\u00a0<\/em><\/strong><\/p>\n<p>Enlace a la web de los premios a Mejor docente de Espa\u00f1a 2018:\u00a0<a href=\"https:\/\/www.mundoeduca.org\/premios-educa-mejor-docente-de-espa%C3%B1a\/\">https:\/\/www.mundoeduca.org\/premios-educa-mejor-docente-de-espa%C3%B1a\/<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00bfQU\u00c9 SON LOS PREMIOS EDUCA?<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p style=\"text-align: justify;\">Objetivo de los Premios EDUCA ABANCA<\/p>\n<p style=\"text-align: justify;\">La educaci\u00f3n est\u00e1 actualmente experimentando un gran debate medi\u00e1tico entre profesorado, pol\u00edticos, familias y alumnado. Iniciativas individuales realizadas por docentes de diferentes centros educativos est\u00e1n creando semillas distribuidas por toda la geograf\u00eda espa\u00f1ola hacia un modelo educativo diferente, donde el alumnado mejore su comprensi\u00f3n de los contenidos abordados, su val\u00eda como integrante de una sociedad y destacando sus posibilidades de acci\u00f3n frente a aspectos negativos y dificultades para el aprendizaje. \u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Desde EDUCA se convocan por segunda vez los Premios EDUCA ABANCA 2018 a los Mejores Docentes de centros p\u00fablicos y privados de Espa\u00f1a con el fin de reconocer p\u00fablicamente la labor de los grandes docentes que viven y disfrutan su trabajo, educan para la vida a su alumnado y se involucran al m\u00e1ximo en todo el proceso educativo, tanto dentro como fuera del aula. La convocatoria pretende ser anual y establecerse como un referente dentro de la sociedad espa\u00f1ola.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Los Premios EDUCA ABANCA 2018 Mejor Docente de Espa\u00f1a tienen el objetivo de reconocer la labor desempe\u00f1ada por los mejores docentes durante el a\u00f1o 2018. Buscan realzar socialmente la figura del buen docente, su implicaci\u00f3n en el proceso de ense\u00f1anza de su alumnado as\u00ed como su importancia para la sociedad.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">El Certamen cuenta con la\u00a0co-organizaci\u00f3n de la plataforma\u00a0<a href=\"http:\/\/miaceduca.es\/\">MIAC. Maestros Innovadores Alumnos Competentes.<\/a>\u00a0y la colaboraci\u00f3n de\u00a0Afundaci\u00f3n. Obra Social ABANCA.<\/p>\n<h2 style=\"text-align: justify;\">Categor\u00edas<\/h2>\n<p style=\"text-align: justify;\">El certamen establece los siguientes premios y categor\u00edas:<\/p>\n<ol style=\"text-align: justify;\">\n<li>Mejor Docente de Educaci\u00f3n Infantil.<\/li>\n<li>Mejor Docente de Educaci\u00f3n Primaria.<\/li>\n<li>Mejor Docente de Educaci\u00f3n Secundaria\/Bachiller.<\/li>\n<li>Mejor Docente de Formaci\u00f3n Profesional.<\/li>\n<li>Mejor Docente de Universidad<\/li>\n<\/ol>\n<h2 style=\"text-align: justify;\" data-action=\"header\" data-name=\"header\">Qui\u00e9n puede\u00a0ser propuesto<\/h2>\n<p style=\"text-align: justify;\">Puede ser propuesto cualquier\u00a0<strong style=\"font-weight: 700 !important;\">docente en activo en el presente curso 2017\/18,<\/strong>\u00a0adscrito a un\u00a0<strong style=\"font-weight: 700 !important;\">centro p\u00fablico, concertado o privado<\/strong>\u00a0de Espa\u00f1a de\u00a0<strong style=\"font-weight: 700 !important;\">cualquier etapa educativa y ense\u00f1anzas regladas,<\/strong>\u00a0desde Educaci\u00f3n Infantil hasta la Universidad. Dado que los nominados saldr\u00e1n de las propuestas realizadas por el alumnado, ex alumnado o familiares del alumno, cualquier docente tendr\u00e1 derecho a ser propuesto, incluyendo tambi\u00e9n a docentes que puedan estar vinculados con las entidades organizadoras y colaboradoras del evento. Pero en ning\u00fan caso los docentes nominados podr\u00e1n estar dentro del Comit\u00e9 de Aplicaci\u00f3n de Puntuaci\u00f3n de su propia categor\u00eda.<\/p>\n<h2 style=\"text-align: justify;\" data-action=\"header\" data-name=\"header\">\u00a0<\/h2>\n<h2 style=\"text-align: justify;\" data-action=\"header\" data-name=\"header\">Qui\u00e9n puede proponer docentes<\/h2>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Los docentes aspirantes a los premios podr\u00e1n ser propuestos a trav\u00e9s de la cumplimentaci\u00f3n de un formulario online ubicado en la web www.mundoeduca.org.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En el proceso de propuesta pueden participar alumnado y\/o exalumnado del docente propuesto y\/o familiares del alumnado del profesor propuesto en el caso de Educaci\u00f3n Infantil y Primaria.\u00a0<\/p>\n<h2 style=\"text-align: justify;\">\u00bfC\u00f3mo se realizar\u00e1 la votaci\u00f3n?<\/h2>\n<p style=\"text-align: justify;\">Tras finalizar el proceso de env\u00edo de propuestas, la organizaci\u00f3n realizar\u00e1 una\u00a0<b><strong>primera selecci\u00f3n<\/strong><\/b>\u00a0en funci\u00f3n de los comentarios volcados por los proponentes y el n\u00famero de propuestas recibidas por cada docente, poni\u00e9ndose en\u00a0contacto posteriormente con todos los docentes que han pasado este primer filtro de selecci\u00f3n, para notificarles que han sido nominados para los Premios EDUCA ABANCA. Mejor Docente de Espa\u00f1a. En ning\u00fan caso se podr\u00e1 desvelar la informaci\u00f3n de los proponentes a los docentes nominados.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En ese mismo email se remitir\u00e1 a los docentes nominados la informaci\u00f3n necesaria para poder participar y presentar<br \/>\n sus m\u00e9ritos a fin de poder cotejar con los datos que volc\u00f3 el alumnado\/familiares del alumnado en el formulario de env\u00edo de propuestas, as\u00ed como indagar en su trayectoria docente y otros m\u00e9ritos baremables en el concurso.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Todo docente propuesto debe aceptar su participaci\u00f3n, a trav\u00e9s de ese mismo formulario que EDUCA le har\u00e1 llegar.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Posteriormente un equipo de miembros de la plataforma EDUCA revisar\u00e1 y puntuar\u00e1 cada uno de los criterios establecidos que previamente fueron aprobados y revisados por el Comit\u00e9 de Expertos de Elaboraci\u00f3n de Criterios, formado por 5 docentes de cada una de las etapas educativas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Con la aplicaci\u00f3n de estos criterios cada docente obtendr\u00e1n una puntuaci\u00f3n, elabor\u00e1ndose un ranking con todos los docentes. EDUCA es consciente de la complejidad de elegir al mejor docente, por eso manifiesta que la selecci\u00f3n de los mejores docentes es siempre atendiendo a estos criterios establecidos por el Comit\u00e9 de Expertos de Elaboraci\u00f3n de Criterios y la organizaci\u00f3n del concurso, a sabiendas que si se modifican los criterios el resultado de selecci\u00f3n de docentes puede no ser el mismo.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En la \u00faltima fase se elaborar\u00e1 un listado de\u00a0<b><strong>10 docentes finalistas<\/strong><\/b>\u00a0en cada una de las categor\u00edas en base a los m\u00e9ritos establecidos por los proponentes y cotejados por los enviados por el profesor.\u00a0Este listado ser\u00e1 p\u00fablico y se elaborar\u00e1 un ranking de docentes para cada categor\u00eda.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">EDUCA publicar\u00e1 los 10 finalistas con lo m\u00e1s destacado de su curriculum pero sin sus puntuaciones obtenidas, desvel\u00e1ndose esta informaci\u00f3n el d\u00eda\u00a0<b><strong>10 de enero<\/strong><\/b>. Los 10 finalistas recibir\u00e1n un diploma acreditativo y una estatuilla que ser\u00e1 entregada en una gala especial en el a\u00f1o 2019, durante la celebraci\u00f3n del II Congreso Mundial de Educaci\u00f3n. EDUCA 2019. En este mismo acto se har\u00e1 entrega al ganador de cada categor\u00eda el premio establecido.<\/p>\n<p style=\"text-align: justify;\">\u00a0 \u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">Ser\u00e1n puntuados los siguientes criterios:<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>N\u00famero de propuestas recibidas<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Se cuantificar\u00e1 el n\u00famero de personas que han propuesto al docente. \u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Comentarios volcados por los proponentes<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Se analizar\u00e1n los comentarios positivos que volcaron en la plataforma de inscripci\u00f3n los proponentes hacia el\u00a0docente propuesto.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Realizaci\u00f3n de actividades innovadoras en el aula<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Se tendr\u00e1n en cuenta las actividades con car\u00e1cter innovador desarrolladas por el docente en el aula.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Presencia del docente en redes sociales y plataformas<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Se valorar\u00e1 la presencia del docente en redes sociales y plataformas para la difusi\u00f3n del conocimiento: canal youtube, p\u00e1ginas de facebook, twitter, linkedin, edmodo, etc. Para confirmar su pasi\u00f3n por la educaci\u00f3n al seguir educando y transmitiendo conocimientos m\u00e1s all\u00e1 de las aulas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Web o Blog propio del docente<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Las webs y blogs son un medio muy importante para transformar una sociedad, los docentes que tengan web y blog con fines educativos obtendr\u00e1n puntuaci\u00f3n en este apartado dada su involucraci\u00f3n en la mejora de la educaci\u00f3n de la sociedad.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Participaci\u00f3n en acciones formativas de reciclaje de conocimientos<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Se valorar\u00e1 la participaci\u00f3n del docente en cursos, congresos y acciones formativas que sirvan para mejorar su praxis docente y enriquecer sus conocimientos.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Presencia en medios de comunicaci\u00f3n<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Se tendr\u00e1 en cuenta las aportaciones a la sociedad a trav\u00e9s de art\u00edculos en prensa, entrevistas, reportajes, etc. que fueron publicados por diferentes medios de comunicaci\u00f3n locales y nacionales.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Publicaci\u00f3n de libros y art\u00edculos en revistas<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">La difusi\u00f3n del conocimiento a trav\u00e9s de libros y revistas ser\u00e1 puntuada tambi\u00e9n como un aspecto importante para la mejora de la docencia.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Participaci\u00f3n en actividades solidarias con fines educativos<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">La participaci\u00f3n en actividades educativas solidarias ser\u00e1n motivo tambi\u00e9n de puntuaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Organizaci\u00f3n de jornadas de formaci\u00f3n en el \u00e1mbito educativo<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">La pertenencia a comit\u00e9s organizadores de jornadas de actualizaci\u00f3n y reciclaje de conocimientos tambi\u00e9n puntuar\u00e1 para los premios a los mejores docentes, as\u00ed como la organizaci\u00f3n de jornadas de formaci\u00f3n destinadas a alumnado.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Participaci\u00f3n en investigaciones realizadas en el \u00e1mbito educativo<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Los docentes que participen en proyectos de investigaci\u00f3n vinculados a la mejora de la calidad educativa obtendr\u00e1n tambi\u00e9n puntuaci\u00f3n extra.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><b><strong>Hechos significativos para el alumnado<\/strong><\/b><\/p>\n<p style=\"text-align: justify;\">Hay profesores que se involucran m\u00e1s all\u00e1 de lo formal y dedicaron su tiempo a algo significativo que pudo marcar el cambio de rumbo del alumnado. Estos hechos registrados por los participantes en el formulario de propuestas puntuar\u00e1n tambi\u00e9n.<\/p>\n<p style=\"text-align: justify;\">Criterios que se tienen en cuenta para realizar la puntuaci\u00f3n de los profesores nominados<\/p>\n<p style=\"text-align: justify;\">Criterios p\u00fablicos para baremaci\u00f3n nomin<\/p>\n<p style=\"text-align: justify;\">Documento Adobe Acrobat\u00a0135.9 KB<\/p>\n<p style=\"text-align: justify;\"><a style=\"font-weight: 400;\" href=\"https:\/\/www.mundoeduca.org\/app\/download\/12129288299\/Criterios+p%C3%BAblicos+para+baremaci%C3%B3n+nominados+2018.pdf?t=1537029191\">Descarga<\/a><\/p>\n<h2 style=\"text-align: justify;\">Comit\u00e9 de Expertos ajenos a EDUCA<\/h2>\n<p style=\"text-align: justify;\">El Comit\u00e9 de Expertos es un comit\u00e9 encargado de aprobar y proponer criterios para puntuar cada uno de los apartados que componen la baremaci\u00f3n de los Premios Educa ABANCA Mejor Docente de Espa\u00f1a. Est\u00e1 formado por profesionales de la educaci\u00f3n de diferentes etapas educativas, distintas especialidades y diversas Comunidades Aut\u00f3nomas de Espa\u00f1a. Los docentes, que conforman este comit\u00e9, han sido elegidos al azar a trav\u00e9s de una b\u00fasqueda en google, siendo todos ellos ajenos a EDUCA. EDUCA agradece p\u00fablicamente la colaboraci\u00f3n altruista y desinteresada de estos docentes.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Profa. D\u00aa. Lourdes Li\u00e9banas Torres. Profesora Centro Infantil Nanos. Ja\u00e9n.<\/p>\n<p style=\"text-align: justify;\">Profa. D\u00aa. Eva Ciordia F<br \/>\nillat. Profesora Educaci\u00f3n Primaria. Departamento de Educaci\u00f3n del Gobierno de Navarra.<\/p>\n<p style=\"text-align: justify;\">Prof. D. Santiago Moll Vaquer. Profesor en el Instituto de Educaci\u00f3n Secundaria de Badalona. Autor del Blog\u00a0<a href=\"http:\/\/justificaturespuesta.com\/\">Justifica tu respuesta<\/a><\/p>\n<p style=\"text-align: justify;\">Profa. D\u00aa. Iria Mart\u00ednez Garc\u00eda. Profesora CPR L\u00f3pez y Vicu\u00f1a. Formaci\u00f3n Profesional. A Coru\u00f1a.\u00a0<\/p>\n<p style=\"text-align: justify;\">Prof. Dr. Marcos Mec\u00edas Calvo. Profesor en la Universidad Europea del Atl\u00e1ntico. Santander.<\/p>\n<h2 style=\"text-align: justify;\">Comit\u00e9 de baremaci\u00f3n de m\u00e9ritos<\/h2>\n<p style=\"text-align: justify;\">El Comit\u00e9 de baremaci\u00f3n de m\u00e9ritos es un comit\u00e9 compuesto por profesionales de la educaci\u00f3n de diferentes etapas educativas. Se encarga de puntuar cada uno de los m\u00e9ritos volcados en la aplicaci\u00f3n por los docentes nominados. La puntuaci\u00f3n se obtiene a trav\u00e9s del documento revisado y aprobado por el Comit\u00e9 de Expertos ajenos a EDUCA. En dicho documento se explica detalladamente en qu\u00e9 consiste cada m\u00e9rito y los puntos m\u00e1ximos que se pueden otorgar. Educa agradece p\u00fablicamente la colaboraci\u00f3n altruista y desinteresada de estos docentes.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Profa. Eva Nieto-Caama\u00f1o Calvi\u00f1o. Presidenta del Comit\u00e9<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Prof. Javier N\u00fa\u00f1ez Mart\u00ednez. Secretario del Comit\u00e9<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Vocales<\/p>\n<p style=\"text-align: justify;\">Profa. Alba Iglesias Ya\u00f1ez<\/p>\n<p style=\"text-align: justify;\">Prof. Sergio Carro Berm\u00fadez<\/p>\n<p style=\"text-align: justify;\">Prof. Juan Cotarelo Gonz\u00e1lez<\/p>\n<p style=\"text-align: justify;\">Profa. Rebeca Fern\u00e1ndez Facal<\/p>\n<p style=\"text-align: justify;\">Prof. Fabi\u00e1n Canosa Pasantes<\/p>\n<p style=\"text-align: justify;\">Prof. Jos\u00e9 Manuel Nant\u00f3n Blanco<\/p>\n<p style=\"text-align: justify;\">Profa. Zhais M. \u00c1lvarez Montenegro<\/p>\n<p style=\"text-align: justify;\">Prof. Sergio P\u00e9rez Celada<\/p>\n<p style=\"text-align: justify;\">Profa. Natalia Abalde Amoedo\u00a0<\/p>\n<h2 style=\"text-align: justify;\">Fallo del jurado<\/h2>\n<p style=\"text-align: justify;\">El fallo del jurado ser\u00e1 inapelable y se publicar\u00e1 el\u00a0<b><strong>10 de enero del 2019\u00a0<\/strong><\/b>a trav\u00e9s de redes sociales, web y nota de prensa. Los 10 finalistas y los ganadores ser\u00e1n comunicados personalmente para su asistencia a la entrega de Premios que tendr\u00e1 lugar paralelamente a la celebraci\u00f3n del II Congreso Mundial de Educaci\u00f3n. EDUCA 2019. Innovaci\u00f3n e Investigaci\u00f3n Educativa. a celebrar en una localidad espa\u00f1ola.<\/p>\n<h2 style=\"text-align: justify;\">Cronograma<\/h2>\n<p style=\"text-align: justify;\">La organizaci\u00f3n de los Premios EDUCA ABANCA establece el siguiente cronograma, las fechas de las publicaciones indican el d\u00eda tope de publicaci\u00f3n de los datos:<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"288\">\n<p><b><strong>Fecha<\/strong><\/b><\/p>\n<\/td>\n<td width=\"288\">\n<p><b><strong>Actividad<\/strong><\/b><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">\n<p><b><strong>30 de junio\u00a02018<\/strong><\/b><\/p>\n<\/td>\n<td width=\"288\">\n<p>Fecha tope para recibir propuestas de docentes.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">\n<p><b><strong>30 de septiembre 2018<\/strong><\/b><\/p>\n<\/td>\n<td width=\"288\">\n<p>Publicaci\u00f3n de los 50 docentes nominados en cada categor\u00eda<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">\n<p><b><strong>5 de diciembre\u00a02018<\/strong><\/b><\/p>\n<\/td>\n<td width=\"288\">\n<p>Publicaci\u00f3n de los 10 finalistas en cada categor\u00eda<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">\n<p><b><strong>10 de enero\u00a02019<\/strong><\/b><\/p>\n<\/td>\n<td width=\"288\">\n<p>Publicaci\u00f3n de las puntuaciones de los 10 finalistas de cada categor\u00eda y menci\u00f3n del ganador.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"288\">\n<p><b><strong>23 febrero\u00a02019<\/strong><\/b><\/p>\n<\/td>\n<td width=\"288\">\n<p>Entrega de los premios EDUCA<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 style=\"text-align: justify;\">Premios<\/h2>\n<p style=\"text-align: justify;\">Los premiados recibir\u00e1n un galard\u00f3n, un diploma conmemorativo del certamen y un premio econ\u00f3mico de 1.000 euros\u00a0(sujeto a retenciones). Los 10 finalistas de cada categor\u00eda recibir\u00e1n un diploma acreditativo y una estatuilla de finalista. Para la recepci\u00f3n de estos premios se deber\u00e1 asistir a la Gala de los Premios, en caso de no asistir perder\u00e1 el derecho a los mismos, salvo casos de enfermedad.<\/p>\n<h2 style=\"text-align: justify;\">Otras consideraciones<\/h2>\n<p style=\"text-align: justify;\">Todo lo no contemplado en esta normativa ser\u00e1 resuelto\u00a0por el Comit\u00e9 de Baremaci\u00f3n de M\u00e9ritos. Los profesores que acepten su participaci\u00f3n en el certamen no podr\u00e1n presentar reclamaci\u00f3n alguna una vez publicadas las puntuaciones finales. El fallo del jurado es inapelable.\u00a0<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<div id=\"x_cc-m-11562473199\">\n<div id=\"x_cc-m-11562470699\">\n<div id=\"x_cc-m-11562469999\">\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/valenciasjb.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2018\/09\/cartel-nominado-MUJER.png\" alt=\"cartel nominado MUJER\" width=\"257\" height=\"257\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DovO61SWwAARur4.jpg\" alt=\"\" width=\"452\" height=\"257\" \/><\/p>\n<p>\u00a0<\/p>\n<div class=\"et_pb_text et_pb_module et_pb_bg_layout_light et_pb_text_align_justified  et_pb_text_0\">\n<div class=\"et_pb_text_inner\">\n<div id=\"resumen\">\n<p style=\"text-align: justify;\">La profesora del Colegio Carlos III de Aranjuez, Gema Caraballo Tarjuelo, ha sido nominada como finalista a mejor docente de Espa\u00f1a 2018, en los premios Educa Abanca, tal y como promueven estos galardones, por su calidad docente, por su praxis, por su trato con el alumnado, por su preocupaci\u00f3n por el futuro de sus alumnos\u2026<\/p>\n<p style=\"text-align: justify;\">Estos premios, como indica sus objetivos, tienen como fin reconocer p\u00fablicamente la labor de los grandes docentes que viven y disfrutan su trabajo cada d\u00eda, educan para la vida a su alumnado y se involucran al m\u00e1ximo en todo el proceso educativo de su alumnado, tanto dentro como fuera de las aulas.\u00a0<\/p>\n<p style=\"text-align: justify;\">Se trata de unos prestigiosos premios conocidos como los \u201cGoya de la Educaci\u00f3n\u201d que realzan la figura del buen docente y tienen como caracter\u00edstica principal que ning\u00fan profesor se puede presentar individualmente, deben ser sus alumnos o las familias quienes lo propongan. Dado que los nominados salen de las propuestas realizadas por el alumnado, ex alumnado o familiares del alumno, cualquier docente tiene derecho a ser propuesto.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"et_pb_text et_pb_module et_pb_bg_layout_light et_pb_text_align_justified  et_pb_text_2\">\n<div class=\"et_pb_text_inner\">\n<p style=\"text-align: justify;\">De entre las casi 2000 propuestas recibidas por el comit\u00e9 procedentes de todos los rincones de Espa\u00f1a, nuestra Coordinadora del Proyecto Biling\u00fce, Coordinadora de Escuelas Sostenibles,\u00a0 Coordinadora del Hierto Escolar, \u00abGemita\u00bb o Teacher Huerto (como la llaman muchos alumnos y alumnas del Colegio) ha sido seleccionada entre los finalistas de su categor\u00eda, Educaci\u00f3n Primaria.<\/p>\n<p style=\"text-align: justify;\">El colegio quiere dar la m\u00e1s sincera enhorabuena a Gema por este merecido reconocimiento, por la profesionalidad y pasi\u00f3n que muestra en su tarea docente y los valores que transmite a sus alumnos y alumnas, a sus compa\u00f1eros y compa\u00f1eras y a toda la Comunidad del Carlos III.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p><strong><em>Y gracias de parte de Gema \u00abGracias a las mamis y papis que han hecho posible todo esto, muchas gracias por proponerme como mejor docente; pero sobre todo gracias por el apoyo, cari\u00f1o y confianza que me transmitis cada d\u00eda, a m\u00ed , a todos mis compis. Todos juntos hacemos un trabajo estupendo, pero esto te da a\u00fan m\u00e1s energ\u00eda y alegr\u00eda para seguir trabajando como siempre por los ni\u00f1os\u00bb.\u00a0<\/em><\/strong><\/p>\n<p>Enlace a la web de los premios a Mejor docente de Espa\u00f1a 2018:\u00a0<a href=\"https:\/\/www.mundoeduca.org\/premios-educa-mejor-docente-de-espa%C3%B1a\/\">https:\/\/www.mundoeduca.org\/premios-educa-mejor-docente-de-espa%C3%B1a\/<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-2263","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"\u00a0 \u00a0 La profesora del Colegio Carlos III de Aranjuez, Gema Caraballo Tarjuelo, ha sido nominada como finalista a mejor docente de Espa\u00f1a 2018, en los premios Educa Abanca, tal y como promueven estos galardones, por su calidad docente, por su praxis, por su trato con el alumnado, por su preocupaci\u00f3n por el futuro de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2263"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2263\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2263"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}