{"id":2267,"date":"2018-09-25T09:03:24","date_gmt":"2018-09-25T09:03:24","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2267"},"modified":"2018-09-25T09:03:24","modified_gmt":"2018-09-25T09:03:24","slug":"preparamos-la-amistad-que-queremos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/09\/25\/preparamos-la-amistad-que-queremos\/","title":{"rendered":"PREPARAMOS LA AMISTAD QUE QUEREMOS"},"content":{"rendered":"<p>Todas las clases del Colegio\u00a0est\u00e1n aprendiendo la canci\u00f3n \u00abLa amistad que quiero\u00bb, como parte del proyecto de Bienvenida del Curso Escolar. Todos juntos la cantaremos y bailaremos el viernes 5 de octubre, en el acto de \u00abClausura de la Bienvenida del Curso Escolar\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DnSOpIGX4AAxg95.jpg\" alt=\"\" width=\"260\" height=\"389\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DnSOqQlXoAACWRs.jpg\" alt=\"\" width=\"691\" height=\"390\" \/><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todas las clases del Colegio\u00a0est\u00e1n aprendiendo la canci\u00f3n \u00abLa amistad que quiero\u00bb, como parte del proyecto de Bienvenida del Curso Escolar. Todos juntos la cantaremos y bailaremos el viernes 5 de octubre, en el acto de \u00abClausura de la Bienvenida del Curso Escolar\u00bb. \u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-2267","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Todas las clases del Colegio\u00a0est\u00e1n aprendiendo la canci\u00f3n \u00abLa amistad que quiero\u00bb, como parte del proyecto de Bienvenida del Curso Escolar. Todos juntos la cantaremos y bailaremos el viernes 5 de octubre, en el acto de \u00abClausura de la Bienvenida del Curso Escolar\u00bb. \u00a0","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2267"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2267\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2267"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}