{"id":2278,"date":"2018-10-01T09:01:17","date_gmt":"2018-10-01T09:01:17","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2278"},"modified":"2018-10-01T09:01:17","modified_gmt":"2018-10-01T09:01:17","slug":"aprendemos-ingles-con-naturenglish","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/10\/01\/aprendemos-ingles-con-naturenglish\/","title":{"rendered":"APRENDEMOS INGL\u00c9S CON NATURENGLISH"},"content":{"rendered":"<p>El pasado martes de septiembre las clases de 4 y 5 a\u00f1os a\u00a0trav\u00e9s de juegos, canciones y talleres en ingl\u00e9s realziados por la empresa NaturEnglish repasaron los animales, los n\u00fameros, los colores, los ecosistemas y la alimentaci\u00f3n saludable. Lo que m\u00e1s le gust\u00f3 fue el mago \u00abDani O&#8217;Magic\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dn9F-MSWkAAZ_mN.jpg\" alt=\"\" width=\"653\" height=\"392\" \/>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado martes de septiembre las clases de 4 y 5 a\u00f1os a\u00a0trav\u00e9s de juegos, canciones y talleres en ingl\u00e9s realziados por la empresa NaturEnglish repasaron los animales, los n\u00fameros, los colores, los ecosistemas y la alimentaci\u00f3n saludable. Lo que m\u00e1s le gust\u00f3 fue el mago \u00abDani O&#8217;Magic\u00bb. \u00a0 \u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"post_folder":[],"class_list":["post-2278","post","type-post","status-publish","format-standard","hentry","category-infantil"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/\" rel=\"category tag\">Infantil<\/a>","rttpg_excerpt":"El pasado martes de septiembre las clases de 4 y 5 a\u00f1os a\u00a0trav\u00e9s de juegos, canciones y talleres en ingl\u00e9s realziados por la empresa NaturEnglish repasaron los animales, los n\u00fameros, los colores, los ecosistemas y la alimentaci\u00f3n saludable. Lo que m\u00e1s le gust\u00f3 fue el mago \u00abDani O&#8217;Magic\u00bb. \u00a0 \u00a0","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2278"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2278\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2278"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}