{"id":2316,"date":"2018-10-18T11:55:41","date_gmt":"2018-10-18T11:55:41","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2316"},"modified":"2018-10-18T11:55:41","modified_gmt":"2018-10-18T11:55:41","slug":"primer-programa-de-radio-escolar-del-curso","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/10\/18\/primer-programa-de-radio-escolar-del-curso\/","title":{"rendered":"PRIMER PROGRAMA DE RADIO ESCOLAR DEL CURSO"},"content":{"rendered":"<p>Primer programa de Radio Escolar \u00abThe News of the Blue Girls and Boys\u00bb del\u00a0curso, adem\u00e1s de contar las noticias del Cole, los alumnos y alumnas de 6\u00ba de Primaria hemos\u00a0\u00a0entrevistado a nuestras auxiliares de conversaci\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/IAyhYkww1lQ\" width=\"425\" height=\"350\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primer programa de Radio Escolar \u00abThe News of the Blue Girls and Boys\u00bb del\u00a0curso, adem\u00e1s de contar las noticias del Cole, los alumnos y alumnas de 6\u00ba de Primaria hemos\u00a0\u00a0entrevistado a nuestras auxiliares de conversaci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"post_folder":[],"class_list":["post-2316","post","type-post","status-publish","format-standard","hentry","category-radio-y-periodico"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/radio-y-periodico\/\" rel=\"category tag\">Radio y Peri\u00f3dico<\/a>","rttpg_excerpt":"Primer programa de Radio Escolar \u00abThe News of the Blue Girls and Boys\u00bb del\u00a0curso, adem\u00e1s de contar las noticias del Cole, los alumnos y alumnas de 6\u00ba de Primaria hemos\u00a0\u00a0entrevistado a nuestras auxiliares de conversaci\u00f3n.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2316"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2316\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2316"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}