{"id":2344,"date":"2018-10-29T10:56:43","date_gmt":"2018-10-29T10:56:43","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2344"},"modified":"2018-10-29T10:56:43","modified_gmt":"2018-10-29T10:56:43","slug":"las-clases-de-6-de-primaria-descubren-toledo","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/10\/29\/las-clases-de-6-de-primaria-descubren-toledo\/","title":{"rendered":"LAS CLASES DE 6\u00ba DE PRIMARIA DESCUBREN TOLEDO"},"content":{"rendered":"<p>Las clases de 6\u00b0Primaria, con Charlie a\u00a0la cabeza visitan la ciudad de las tres culturas.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dqa9nw_XQAAMroh.jpg\" alt=\"\" width=\"199\" height=\"165\" \/>\u00a0El viernes 26 de octubre.<\/p>\n<p>Los gu\u00edas de Cu\u00e9ntame Toledo les dieron la bienvenida en la Plaza de Zocodover (les explicaron que es una palabra de origen \u00e1rabe y que su significado es \u00abla plaza de las bestias\u00bb, porque en aquel sitio se vend\u00eda ganado)\u00a0y comenzaron cont\u00e1ndoles la Historia de Toledo y de las distintos pueblos\/culturas que lo habitaron: visigodos, cristianos, romanos, carpetanos, musulmanes, jud\u00edos, &#8230;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbDdQgWsAA4Rsf.jpg\" alt=\"\" width=\"325\" height=\"184\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dqa9pfjWkAEDYD0.jpg\" alt=\"\" width=\"317\" height=\"179\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbF3rbW4AENGMM.jpg\" alt=\"\" width=\"313\" height=\"178\" \/><\/p>\n<p>Las clases de 6\u00b0Primaria visitaron muchos lugares, entre ellos la Mezquita del Cristo de la Luz\u00a0y descubrieron su leyenda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbF2WgWwAEhmrH.jpg\" alt=\"\" width=\"640\" height=\"363\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbF4_PW4AApJfq.jpg\" alt=\"\" width=\"226\" height=\"365\" \/><\/p>\n<p>\u00a0Descubrieron muchas cosas de Toledo, algunos s\u00edmbolos de sus fachadas, la esfera que vemos es una se\u00f1al que indica que hay agua para detener incendios, tambi\u00e9n vieron v\u00edtores de los estudiantes de la universidad, restos de Termas Romanas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbJVYEXgAE9kGY.jpg\" alt=\"\" width=\"128\" height=\"227\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbJWJ-XgAAFsa4.jpg\" alt=\"\" width=\"87\" height=\"222\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbJWhbWoAAZOEH.jpg\" alt=\"\" width=\"677\" height=\"227\" \/><\/p>\n<p>Los mayores del Colegio conocieron algunas de las edificaciones de los much\u00edsimos monumentos que tiene Toledo (Puerta del Sol, Museo de los Concilios, &#8230;).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbMAbaXcAAsLma.jpg\" alt=\"\" width=\"235\" height=\"416\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbMJrnX0AAbiZj.jpg\" alt=\"\" width=\"311\" height=\"415\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbMFUYX0AArdJ3.jpg\" alt=\"\" width=\"311\" height=\"415\" \/><\/p>\n<p>Se adentraron en el barrio jud\u00edo y buscaron los s\u00edmbolos caracter\u00edsticos de los jud\u00edos. Aprendieron como en Toledo se mezclaron culturas y como conviv\u00edan juntos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbR6R_XcAAJWNe.jpg\" alt=\"\" width=\"372\" height=\"210\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbR8wsXgAAz-1z.jpg\" alt=\"\" width=\"119\" height=\"212\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbR9sjWkAQtfYR.jpg\" alt=\"\" width=\"158\" height=\"211\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbR7zLX4AUf-eZ.jpg\" alt=\"\" width=\"371\" height=\"210\" \/><\/p>\n<p>Visitaron la plaza del Ayuntamiento de Toledo\u00a0o tambi\u00e9n llamada \u00abLa plaza de los 3 poderes\u00bb: judicial, religioso y pol\u00edtico. Representado en 3 edificios: Catedral, Ayuntamiento y Juzgados.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbX2UgXQAMrXZS.jpg\" alt=\"\" width=\"376\" height=\"213\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbX1LsXQAE28gD.jpg\" alt=\"\" width=\"377\" height=\"213\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbX3ZeXgAAr0p3.jpg\" alt=\"\" width=\"371\" height=\"210\" \/><\/p>\n<p>Descubrieron gracias a Cu\u00e9ntame Toledo (<a href=\"https:\/\/www.cuentametoledo.com\/\" target=\"_blank\" rel=\"alternate noopener noreferrer\">https:\/\/www.cuentametoledo.com\/<\/a>)\u00a0la arquitectura, historia, arte, costumbres, religiones,&#8230;. de Toledo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dqbd9FKXcAIOGUb.jpg\" alt=\"\" width=\"336\" height=\"253\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dqbd904WoAA_x7L.jpg\" alt=\"\" width=\"352\" height=\"255\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dqbd-d4XgAI6_1m.jpg\" alt=\"\" width=\"338\" height=\"254\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las clases de 6\u00b0Primaria, con Charlie a\u00a0la cabeza visitan la ciudad de las tres culturas.<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dqa9nw_XQAAMroh.jpg\" alt=\"\" width=\"199\" height=\"165\" \/>\u00a0El viernes 26 de octubre.<\/p>\n<p>Los gu\u00edas de Cu\u00e9ntame Toledo les dieron la bienvenida en la Plaza de Zocodover (les explicaron que es una palabra de origen \u00e1rabe y que su significado es \u00abla plaza de las bestias\u00bb, porque en aquel sitio se vend\u00eda ganado)\u00a0y comenzaron cont\u00e1ndoles la Historia de Toledo y de las distintos pueblos\/culturas que lo habitaron: visigodos, cristianos, romanos, carpetanos, musulmanes, jud\u00edos, &#8230;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbDdQgWsAA4Rsf.jpg\" alt=\"\" width=\"325\" height=\"184\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dqa9pfjWkAEDYD0.jpg\" alt=\"\" width=\"317\" height=\"179\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbF3rbW4AENGMM.jpg\" alt=\"\" width=\"313\" height=\"178\" \/><\/p>\n<p>Las clases de 6\u00b0Primaria visitaron muchos lugares, entre ellos la Mezquita del Cristo de la Luz\u00a0y descubrieron su leyenda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbF2WgWwAEhmrH.jpg\" alt=\"\" width=\"640\" height=\"363\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DqbF4_PW4AApJfq.jpg\" alt=\"\" width=\"226\" height=\"365\" \/><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-2344","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Las clases de 6\u00b0Primaria, con Charlie a\u00a0la cabeza visitan la ciudad de las tres culturas.\u00a0El viernes 26 de octubre. Los gu\u00edas de Cu\u00e9ntame Toledo les dieron la bienvenida en la Plaza de Zocodover (les explicaron que es una palabra de origen \u00e1rabe y que su significado es \"la plaza de las bestias\", porque en aquel&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2344"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2344\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2344"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}