{"id":2349,"date":"2018-10-31T11:08:46","date_gmt":"2018-10-31T11:08:46","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2349"},"modified":"2018-10-31T11:08:46","modified_gmt":"2018-10-31T11:08:46","slug":"comunicado-familia-dias-1-y-2-noviembre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/10\/31\/comunicado-familia-dias-1-y-2-noviembre\/","title":{"rendered":"COMUNICADO FAMILIA D\u00cdAS 1 Y 2 NOVIEMBRE."},"content":{"rendered":"<p style=\"text-align: right;\"><span style=\"font-size: 14pt; font-family: comic sans ms,sans-serif;\">Aranjuez, 31 de octubre de 2018.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: comic sans ms,sans-serif;\">Estimadas familias y equipo docente:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: comic sans ms,sans-serif;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Os comunicamos que de acuerdo con el calendario escolar 2018-2019, <strong>se establecen como festivo el jueves 01 de noviembre de 2018 y no lectivo el viernes 2 de noviembre de 2018<\/strong>, por lo que volveremos de nuevo al Centro, el lunes 5 de noviembre de 2018.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: comic sans ms,sans-serif;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Feliz puente.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt; font-family: comic sans ms,sans-serif;\">EQUIPO DIRECTIVO.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aranjuez, 31 de octubre de 2018. Estimadas familias y equipo docente: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Os comunicamos que de acuerdo con el calendario escolar 2018-2019, se establecen como festivo el jueves 01 de noviembre de 2018 y no lectivo el viernes 2 de noviembre de 2018, por lo que volveremos de nuevo al Centro, el lunes 5 de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/10\/31\/comunicado-familia-dias-1-y-2-noviembre\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO FAMILIA D\u00cdAS 1 Y 2 NOVIEMBRE.\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"post_folder":[],"class_list":["post-2349","post","type-post","status-publish","format-standard","hentry","category-menu"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/menu\/\" rel=\"category tag\">Menu Superior Central<\/a>","rttpg_excerpt":"Aranjuez, 31 de octubre de 2018. Estimadas familias y equipo docente: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Os comunicamos que de acuerdo con el calendario escolar 2018-2019, se establecen como festivo el jueves 01 de noviembre de 2018 y no lectivo el viernes 2 de noviembre de 2018, por lo que volveremos de nuevo al Centro, el lunes 5 de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2349"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2349\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2349"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}