{"id":2374,"date":"2018-11-09T10:40:27","date_gmt":"2018-11-09T10:40:27","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2374"},"modified":"2018-11-09T10:40:27","modified_gmt":"2018-11-09T10:40:27","slug":"informacion-dia-universal-de-la-infancia","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/11\/09\/informacion-dia-universal-de-la-infancia\/","title":{"rendered":"INFORMACI\u00d3N D\u00cdA UNIVERSAL DE LA INFANCIA"},"content":{"rendered":"<h1 class=\"article--title\">La Casa de Campo de Madrid se llena de actividades para celebrar el D\u00eda Universal de la Infancia<\/h1>\n<p class=\"article--summary\">El pr\u00f3ximo 20 de noviembre se conmemora el D\u00eda Universal de la Infancia y han organizado un gran evento de ocio infantil y familiar que llenar\u00e1 de vida la instalaciones del recinto ferial de la Casa de Campo de Madrid.<\/p>\n<p>El pr\u00f3ximo 20 de noviembre se conmemora el\u00a0<a class=\"textlink\" title=\"D\u00eda Universal del Ni\u00f1o\" href=\"https:\/\/www.serpadres.es\/familia\/derechos\/articulo\/dia-universal-del-nino-741447938039\">D\u00eda Universal de la Infancia<\/a>\u00a0y el XXIV aniversario de la Convenci\u00f3n sobre los Derechos del Ni\u00f1o. Y para celebrarlo, la Comunidad de Madrid ha programado para el\u00a0<strong>fin de semana del s\u00e1bado 24 y del domingo 25 de noviembre un gran evento de ocio infantil y familiar<\/strong>\u00a0que llenar\u00e1 de vida la instalaciones del recinto ferial de la Casa de Campo de Madrid.<\/p>\n<p>En el evento participar\u00e1n un centenar de instituciones, asociaciones, fundaciones y ongs, que llevar\u00e1n a cabo talleres, actuaciones y actividades para los ni\u00f1os, pero tambi\u00e9n para los padres y para disfrutar en familia.<\/p>\n<p>Las actividades, que se llevar\u00e1n a cabo tanto en el interior como en el exterior de las instalaciones, se agrupar\u00e1n en seis \u00e1mbitos seg\u00fan la tem\u00e1tica de las mismas (ecol\u00f3gica, salud y seguridad; cultural, ocio y manualidades; creativa, deportiva y tecnol\u00f3gica). Entre ellas destacan por ejemplo las de escalada, exhibici\u00f3n canina,\u00a0 pinball, robots, show improvisaci\u00f3n, las gincanas en familia, planetario y taller de Astronom\u00eda, los circuitos de seguridad vial o los talleres de reciclaje, de radio y de cocina.<\/p>\n<p>En el interior del<strong>\u00a0Palacio de Cristal de la Casa de Campo<\/strong>\u00a0habr\u00e1 tambi\u00e9n un escenario en el que se llevar\u00e1n a cabo cuentacuentos, obras teatrales y actuaciones musicales, de danza, magia o malabares. Adem\u00e1s, habr\u00e1 un espacio para descansar y reponer fuerzas con zona de lactancia, calienta biberones, cambiadores y zona para comer con microondas, mesas y sillas.<\/p>\n<p>Y como no pod\u00eda ser de otra forma en un evento solidario que busca dar a conocer los derechos de la infancia y concienciar a las personas de la importancia de trabajar d\u00eda a d\u00eda por su bienestar y desarrollo, tambi\u00e9n habr\u00e1 un mercadillo solidario as\u00ed como puestos para la entrega de alimentos no perecederos, de juguetes nuevos o seminuevos y de ropa de ni\u00f1os.<\/p>\n<p>La\u00a0<strong>entrada al evento y la participaci\u00f3n en los talleres y actividades es totalmente gratuita<\/strong>\u00a0y se celebrar\u00e1n en horario ininterrumpido. El s\u00e1bado entre las 11:00 de la ma\u00f1ana y las 20:00 horas de la tarde, y el domingo entre las 11:00 y las 15:00.\u00a0<\/p>\n<p>A pesar de ser gratuito, la Direcci\u00f3n General de la Familia y del Menor nos han dado invitaciones para las familias, que entregaremos a los ni\u00f1os y ni\u00f1as del Colegio.\u00a0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/culturayocio.org\/wp-content\/uploads\/2018\/10\/dia-universal-de-la-infancia-2018-paint.png\" alt=\"Imagen relacionada\" \/><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Casa de Campo de Madrid se llena de actividades para celebrar el D\u00eda Universal de la Infancia El pr\u00f3ximo 20 de noviembre se conmemora el D\u00eda Universal de la Infancia y han organizado un gran evento de ocio infantil y familiar que llenar\u00e1 de vida la instalaciones del recinto ferial de la Casa de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/11\/09\/informacion-dia-universal-de-la-infancia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abINFORMACI\u00d3N D\u00cdA UNIVERSAL DE LA INFANCIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-2374","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"La Casa de Campo de Madrid se llena de actividades para celebrar el D\u00eda Universal de la Infancia El pr\u00f3ximo 20 de noviembre se conmemora el D\u00eda Universal de la Infancia y han organizado un gran evento de ocio infantil y familiar que llenar\u00e1 de vida la instalaciones del recinto ferial de la Casa de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2374"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2374\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2374"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}