{"id":2388,"date":"2018-11-15T08:49:24","date_gmt":"2018-11-15T08:49:24","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2388"},"modified":"2018-11-15T08:49:24","modified_gmt":"2018-11-15T08:49:24","slug":"ahora-llega-de-la-navidad-22-de-noviembre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/11\/15\/ahora-llega-de-la-navidad-22-de-noviembre\/","title":{"rendered":"AHORA LLEGA DE LA NAVIDAD. 22 DE NOVIEMBRE"},"content":{"rendered":"<p>El d\u00eda 22 de noviembre, d\u00eda de Santa Cecilia, patrona de la m\u00fasica, presentaremos nuestro villancico: \u00abAhora llega Navidad\u00bb. No os lo pod\u00e9is perder, estad atentos porque iremos desvelando alguna cosa antes. AHORA LLEGA LA NAVIDAD, estreno el 22 de noviembre a las 12:00.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dr9yYcyWsAEMrrt.jpg\" alt=\"\" width=\"637\" height=\"360\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 22 de noviembre, d\u00eda de Santa Cecilia, patrona de la m\u00fasica, presentaremos nuestro villancico: \u00abAhora llega Navidad\u00bb. No os lo pod\u00e9is perder, estad atentos porque iremos desvelando alguna cosa antes. AHORA LLEGA LA NAVIDAD, estreno el 22 de noviembre a las 12:00.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"post_folder":[],"class_list":["post-2388","post","type-post","status-publish","format-standard","hentry","category-experiencias-educativas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/experiencias-educativas\/\" rel=\"category tag\">Proyectos Educativos<\/a>","rttpg_excerpt":"El d\u00eda 22 de noviembre, d\u00eda de Santa Cecilia, patrona de la m\u00fasica, presentaremos nuestro villancico: \u00abAhora llega Navidad\u00bb. No os lo pod\u00e9is perder, estad atentos porque iremos desvelando alguna cosa antes. AHORA LLEGA LA NAVIDAD, estreno el 22 de noviembre a las 12:00.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2388"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2388\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2388"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}