{"id":2396,"date":"2018-11-16T04:54:05","date_gmt":"2018-11-16T04:54:05","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2396"},"modified":"2018-11-16T04:54:05","modified_gmt":"2018-11-16T04:54:05","slug":"vengo-a-un-taller","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/11\/16\/vengo-a-un-taller\/","title":{"rendered":"VENGO A UN TALLER"},"content":{"rendered":"<p>Gracias a Rosa (administrativa del Colegio) y Luc\u00eda (enfermera escolar) ya tenemos preparada las chapas identificativas que vamos a prestar a todas aquellas personas (madres, padres, abuelos, abuelas, monitores, &#8230;.) que visitan el Cole para realizar alg\u00fan taller, dar alguna charla, colaborar con el centro&#8230;. Os recordamos que deb\u00e9is pasar antes del taller\/charla, para autorizaros y haceros entrega de la chapa y despu\u00e9s para firmar la salida y entregar el identificador.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dr9ZY0oXgAA2Q0Q.jpg\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a Rosa (administrativa del Colegio) y Luc\u00eda (enfermera escolar) ya tenemos preparada las chapas identificativas que vamos a prestar a todas aquellas personas (madres, padres, abuelos, abuelas, monitores, &#8230;.) que visitan el Cole para realizar alg\u00fan taller, dar alguna charla, colaborar con el centro&#8230;. Os recordamos que deb\u00e9is pasar antes del taller\/charla, para autorizaros &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/11\/16\/vengo-a-un-taller\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVENGO A UN TALLER\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"post_folder":[],"class_list":["post-2396","post","type-post","status-publish","format-standard","hentry","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Gracias a Rosa (administrativa del Colegio) y Luc\u00eda (enfermera escolar) ya tenemos preparada las chapas identificativas que vamos a prestar a todas aquellas personas (madres, padres, abuelos, abuelas, monitores, &#8230;.) que visitan el Cole para realizar alg\u00fan taller, dar alguna charla, colaborar con el centro&#8230;. Os recordamos que deb\u00e9is pasar antes del taller\/charla, para autorizaros&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2396"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2396\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2396"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}