{"id":2412,"date":"2018-11-20T13:57:34","date_gmt":"2018-11-20T13:57:34","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2412"},"modified":"2018-11-20T13:57:34","modified_gmt":"2018-11-20T13:57:34","slug":"jornada-pirata-en-el-comedor-escolar","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/11\/20\/jornada-pirata-en-el-comedor-escolar\/","title":{"rendered":"JORNADA PIRATA EN EL COMEDOR ESCOLAR"},"content":{"rendered":"<p>\u00abLa vida pirata la vida mejor\u00bb Serunion\u00a0ya ha preparado todo para la jornada pirata que van a disfrutar hoy los usuarios\/as del Comedor Escolar; comida, juegos, manualidades y bailes de tem\u00e1tica pirata.<\/p>\n<p>Las capitanas y el capit\u00e1n pirata de Serunion ya est\u00e1n dirigiendo a sus grumetes en esta jornada de piratas y bucaneros.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dscay5OWwAA6w3L.jpg\" alt=\"\" width=\"149\" height=\"235\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dsca0rdX4AEPw2N.jpg\" alt=\"\" width=\"414\" height=\"233\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DscwF55XQAAOW2_.jpg\" alt=\"\" width=\"412\" height=\"233\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DscwHAeWkAAFIoM.jpg\" alt=\"\" width=\"283\" height=\"160\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DscwIL1XoAInYxj.jpg\" alt=\"\" width=\"284\" height=\"160\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DscwJRsW0AMX-I0.jpg\" alt=\"\" width=\"282\" height=\"160\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa vida pirata la vida mejor\u00bb Serunion\u00a0ya ha preparado todo para la jornada pirata que van a disfrutar hoy los usuarios\/as del Comedor Escolar; comida, juegos, manualidades y bailes de tem\u00e1tica pirata. Las capitanas y el capit\u00e1n pirata de Serunion ya est\u00e1n dirigiendo a sus grumetes en esta jornada de piratas y bucaneros.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-2412","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"\u00abLa vida pirata la vida mejor\u00bb Serunion\u00a0ya ha preparado todo para la jornada pirata que van a disfrutar hoy los usuarios\/as del Comedor Escolar; comida, juegos, manualidades y bailes de tem\u00e1tica pirata. Las capitanas y el capit\u00e1n pirata de Serunion ya est\u00e1n dirigiendo a sus grumetes en esta jornada de piratas y bucaneros.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2412"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2412\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2412"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}