{"id":2484,"date":"2018-12-20T06:04:31","date_gmt":"2018-12-20T06:04:31","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2484"},"modified":"2018-12-20T06:04:31","modified_gmt":"2018-12-20T06:04:31","slug":"348-21-kilos-para-basida","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/12\/20\/348-21-kilos-para-basida\/","title":{"rendered":"348,21 KILOS PARA BASIDA"},"content":{"rendered":"<p>Las clases de 6\u00b0Primaria, durante toda la semana, han ido sumando y clasificando los productos que hemos ido trayendo para la Operaci\u00f3n Kilo, en resultado ha sido 348,21 Kg de cari\u00f1o y solidaridad, para la Casa de Acogida de Basida, aportados por toda la Comunidad Educativa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DuTI6cwWsAA6Nos.jpg\" alt=\"\" width=\"131\" height=\"209\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DuTI7lxWoAMlesk.jpg\" alt=\"\" width=\"237\" height=\"209\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DuTI-ijW4AUlhHa.jpg\" alt=\"\" width=\"323\" height=\"210\" \/><\/p>\n<p>Basida agradece el granito aportado por cada miembro del Colegio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las clases de 6\u00b0Primaria, durante toda la semana, han ido sumando y clasificando los productos que hemos ido trayendo para la Operaci\u00f3n Kilo, en resultado ha sido 348,21 Kg de cari\u00f1o y solidaridad, para la Casa de Acogida de Basida, aportados por toda la Comunidad Educativa. Basida agradece el granito aportado por cada miembro del &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2018\/12\/20\/348-21-kilos-para-basida\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab348,21 KILOS PARA BASIDA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"post_folder":[],"class_list":["post-2484","post","type-post","status-publish","format-standard","hentry","category-campanas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/campanas\/\" rel=\"category tag\">Campa\u00f1as<\/a>","rttpg_excerpt":"Las clases de 6\u00b0Primaria, durante toda la semana, han ido sumando y clasificando los productos que hemos ido trayendo para la Operaci\u00f3n Kilo, en resultado ha sido 348,21 Kg de cari\u00f1o y solidaridad, para la Casa de Acogida de Basida, aportados por toda la Comunidad Educativa. Basida agradece el granito aportado por cada miembro del&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2484"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2484\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2484"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}