{"id":2518,"date":"2019-01-22T13:13:28","date_gmt":"2019-01-22T13:13:28","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2518"},"modified":"2019-01-22T13:13:28","modified_gmt":"2019-01-22T13:13:28","slug":"charlie-de-excursion-al-teatro-con-1-a","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/01\/22\/charlie-de-excursion-al-teatro-con-1-a\/","title":{"rendered":"CHARLIE DE EXCURSI\u00d3N AL TEATRO CON 1\u00ba A"},"content":{"rendered":"<p>Charlie, nuestra mascota, acompa\u00f1\u00f3 el viernes a la clase de 1\u00b0A al teatro. Se lo pas\u00f3 genial al igual que todos los ni\u00f1os y ni\u00f1as de Primaria.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DxgZbZ0W0AAma_m.jpg\" alt=\"\" width=\"581\" height=\"436\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlie, nuestra mascota, acompa\u00f1\u00f3 el viernes a la clase de 1\u00b0A al teatro. Se lo pas\u00f3 genial al igual que todos los ni\u00f1os y ni\u00f1as de Primaria.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-2518","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Charlie, nuestra mascota, acompa\u00f1\u00f3 el viernes a la clase de 1\u00b0A al teatro. Se lo pas\u00f3 genial al igual que todos los ni\u00f1os y ni\u00f1as de Primaria.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2518"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2518\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2518"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}