{"id":2558,"date":"2019-02-13T10:51:19","date_gmt":"2019-02-13T10:51:19","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2558"},"modified":"2019-02-13T10:51:19","modified_gmt":"2019-02-13T10:51:19","slug":"rematch-en-the-news-of-the-blue-girls-and-boys-7-de-febrero","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/02\/13\/rematch-en-the-news-of-the-blue-girls-and-boys-7-de-febrero\/","title":{"rendered":"REMATCH EN THE NEWS OF THE BLUE GIRLS AND BOYS 7 DE FEBRERO"},"content":{"rendered":"<p>El jueves 7 de febrero en el programa de Radio Escolar \u00abThe News of Blue Girls and Boys\u00bb se celebr\u00f3 el \u00abREMATCH\u00bb (la revancha del Quiz, concurso de preguntas) entre los auxiliares de conversaci\u00f3n y los maestros en pr\u00e1cticas. Ni\u00f1os y ni\u00f1as de 6\u00baB fueron los encargados de preparar preguntas y pruebas para sus educadores, para los assistants en ingl\u00e9s y para las maestras en castellano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DyzTOyJX4AAij50.jpg\" alt=\"\" width=\"729\" height=\"412\" \/><\/p>\n<p>En el siguiente enlace os dejamos el Programa de Radio comleto.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/JPF74dSDtJA\" width=\"425\" height=\"350\"><\/iframe><\/p>\n<p>\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 7 de febrero en el programa de Radio Escolar \u00abThe News of Blue Girls and Boys\u00bb se celebr\u00f3 el \u00abREMATCH\u00bb (la revancha del Quiz, concurso de preguntas) entre los auxiliares de conversaci\u00f3n y los maestros en pr\u00e1cticas. Ni\u00f1os y ni\u00f1as de 6\u00baB fueron los encargados de preparar preguntas y pruebas para sus educadores, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/02\/13\/rematch-en-the-news-of-the-blue-girls-and-boys-7-de-febrero\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abREMATCH EN THE NEWS OF THE BLUE GIRLS AND BOYS 7 DE FEBRERO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"post_folder":[],"class_list":["post-2558","post","type-post","status-publish","format-standard","hentry","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"El jueves 7 de febrero en el programa de Radio Escolar \u00abThe News of Blue Girls and Boys\u00bb se celebr\u00f3 el \u00abREMATCH\u00bb (la revancha del Quiz, concurso de preguntas) entre los auxiliares de conversaci\u00f3n y los maestros en pr\u00e1cticas. Ni\u00f1os y ni\u00f1as de 6\u00baB fueron los encargados de preparar preguntas y pruebas para sus educadores,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2558"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2558\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2558"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}