{"id":2582,"date":"2019-02-18T10:44:31","date_gmt":"2019-02-18T10:44:31","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2582"},"modified":"2019-02-18T10:44:31","modified_gmt":"2019-02-18T10:44:31","slug":"dia-del-amor-y-la-amistad-en-el-cole","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/02\/18\/dia-del-amor-y-la-amistad-en-el-cole\/","title":{"rendered":"D\u00cdA DEL AMOR Y LA AMISTAD EN EL COLE"},"content":{"rendered":"<p>Un grupo de alumnos\/as de 6\u00baB prepararon, para el recreo del \u00abD\u00eda de San Valent\u00edn\u00bb (d\u00eda del amor, 14 de febrero), una gymkhana para las clases de 3\u00ba, 4\u00ba, 5\u00ba y 6\u00ba de Primaria, el juego era libre y participan los ni\u00f1os y ni\u00f1as que quer\u00edan, s\u00f3lo ten\u00eda que acercarse a una delas pizarras del patio y superar el reto que all\u00ed aparec\u00eda, el grupo de alumnos\/as responsables revisaba que lo hab\u00eda cumplido y les pon\u00eda un sello, con 3 sellos lograban Charlie Points para el marcador de su clase.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DzW5cXvWsAAKz4k.jpg\" alt=\"\" width=\"399\" height=\"299\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DzXWnYKXQAEDe31.jpg\" alt=\"\" width=\"494\" height=\"280\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DzXWoYwX0AEtMb_.jpg\" alt=\"\" width=\"446\" height=\"252\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DzXWpqMXQAEZ2N0.jpg\" alt=\"\" width=\"448\" height=\"253\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/DzW6_yZW0AAvjGG.jpg\" alt=\"\" width=\"895\" height=\"506\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de alumnos\/as de 6\u00baB prepararon, para el recreo del \u00abD\u00eda de San Valent\u00edn\u00bb (d\u00eda del amor, 14 de febrero), una gymkhana para las clases de 3\u00ba, 4\u00ba, 5\u00ba y 6\u00ba de Primaria, el juego era libre y participan los ni\u00f1os y ni\u00f1as que quer\u00edan, s\u00f3lo ten\u00eda que acercarse a una delas pizarras del &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/02\/18\/dia-del-amor-y-la-amistad-en-el-cole\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abD\u00cdA DEL AMOR Y LA AMISTAD EN EL COLE\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-2582","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Un grupo de alumnos\/as de 6\u00baB prepararon, para el recreo del \u00abD\u00eda de San Valent\u00edn\u00bb (d\u00eda del amor, 14 de febrero), una gymkhana para las clases de 3\u00ba, 4\u00ba, 5\u00ba y 6\u00ba de Primaria, el juego era libre y participan los ni\u00f1os y ni\u00f1as que quer\u00edan, s\u00f3lo ten\u00eda que acercarse a una delas pizarras del&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2582"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2582\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2582"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}