{"id":2590,"date":"2019-02-19T06:18:27","date_gmt":"2019-02-19T06:18:27","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2590"},"modified":"2019-02-19T06:18:27","modified_gmt":"2019-02-19T06:18:27","slug":"los-primeros-del-cole-construyen-el-taj-mahal","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/02\/19\/los-primeros-del-cole-construyen-el-taj-mahal\/","title":{"rendered":"LOS PRIMEROS DEL COLE CONSTRUYEN EL TAJ MAHAL"},"content":{"rendered":"<p>Los ni\u00f1os y ni\u00f1as que participan en la actividad extraescolar de Conciliaci\u00f3n Familiar de los \u00abLos Primeros del Cole\u00bb\u00a0est\u00e1n construyendo una r\u00e9plica del Taj Mahal, les est\u00e1 quedando igual de precioso que el original.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dzbz0xFWsAErxxw.jpg\" alt=\"\" width=\"266\" height=\"355\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dzbz2bbXcAAqpW7.jpg\" alt=\"\" width=\"625\" height=\"352\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ni\u00f1os y ni\u00f1as que participan en la actividad extraescolar de Conciliaci\u00f3n Familiar de los \u00abLos Primeros del Cole\u00bb\u00a0est\u00e1n construyendo una r\u00e9plica del Taj Mahal, les est\u00e1 quedando igual de precioso que el original.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"post_folder":[],"class_list":["post-2590","post","type-post","status-publish","format-standard","hentry","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"Los ni\u00f1os y ni\u00f1as que participan en la actividad extraescolar de Conciliaci\u00f3n Familiar de los \u00abLos Primeros del Cole\u00bb\u00a0est\u00e1n construyendo una r\u00e9plica del Taj Mahal, les est\u00e1 quedando igual de precioso que el original.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2590"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2590\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2590"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}