{"id":2620,"date":"2019-02-25T14:03:21","date_gmt":"2019-02-25T14:03:21","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2620"},"modified":"2019-02-25T14:03:21","modified_gmt":"2019-02-25T14:03:21","slug":"tapones-para-una-nueva-vida-para-marcos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/02\/25\/tapones-para-una-nueva-vida-para-marcos\/","title":{"rendered":"TAPONES PARA UNA NUEVA VIDA PARA MARCOS"},"content":{"rendered":"<p>Un a\u00f1o m\u00e1s somos Centro de Recogida de Tapones para una Nueva Vida\u00a0de la la Fundaci\u00f3n Seur, los tapones de pl\u00e1stico son llevados por Seur\u00a0a una planta de reciclaje y con el dinero logrado se financian tratamientos m\u00e9dicos y ortopedias para ni\u00f1os\/as con problemas de salud. En el hall principal, junto a secretar\u00eda, hemos colocado un contenedor de tapones, para poder dejarlos.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.fundacionseur.org\/wp-content\/uploads\/resultados-tapones_actualizados_2018.05.30-1024x639-1.jpg\" alt=\"\" \/><\/p>\n<p>Tapones para una nueva vida\u00a0es un proyecto de Fundaci\u00f3n SEUR, con el que ya han conseguido ayudar a m\u00e1s de 153 ni\u00f1os y ni\u00f1as a trav\u00e9s del reciclaje de los tapones de pl\u00e1stico. Tapones para una nueva vida\u00a0\u00a0ya ha sobrepasado el<strong>\u00a0mill\u00f3n de \u20ac<\/strong>\u00a0para ayudar a financiar tratamientos m\u00e9dicos y ortopedias.<\/p>\n<p>Sirven todos los tapones de pl\u00e1stico. En ocasiones, los tapones de pl\u00e1stico van marcados con la clase a la que pertenecen. Son v\u00e1lidos los tapones de las siguientes clases:<\/p>\n<p>N\u00ba5 (PP): polipropileno \u2013 es el m\u00e1s valioso.<br \/>N\u00ba2 (PEHD o PEAD): polietileno de alta densidad<br \/>N\u00ba4 (PELD o PEBD): polietileno de baja densidad<\/p>\n<h2 class=\"entry-title fusion-post-title\" data-fontsize=\"18\" data-lineheight=\"27\">NUEVA CAMPA\u00d1A DE TAPONES: MARCOS<\/h2>\n<h2 class=\"entry-title fusion-post-title\" data-fontsize=\"18\" data-lineheight=\"27\"><img decoding=\"async\" src=\"http:\/\/www.fundacionseur.org\/wp-content\/uploads\/MARCOS-600x594.jpg\" alt=\"\" \/><\/h2>\n<h2 class=\"entry-title fusion-post-title\" data-fontsize=\"18\" data-lineheight=\"27\">\u00a1\u00a1NUEVO RETO, MARCOS AY\u00daDANOS!!<\/h2>\n<div class=\"post-content\">\n<p>Desde muy peque\u00f1o, Marcos ha luchado con todas sus fuerzas contra los inconvenientes que se encontr\u00f3 al nacer. Es preciso que le ayudemos, para poder superar los varios diagn\u00f3sticos que le afectan.<\/p>\n<p>Para conseguir esto, necesita nuestro impulso para recaudar las toneladas de tapones necesarias, al objeto de poder mejorar su calidad de vida y apoyar su rehabilitaci\u00f3n.<\/p>\n<\/p><\/div>\n<h2 class=\"entry-title fusion-post-title\" data-fontsize=\"18\" data-lineheight=\"27\">\u00a0<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o m\u00e1s somos Centro de Recogida de Tapones para una Nueva Vida\u00a0de la la Fundaci\u00f3n Seur, los tapones de pl\u00e1stico son llevados por Seur\u00a0a una planta de reciclaje y con el dinero logrado se financian tratamientos m\u00e9dicos y ortopedias para ni\u00f1os\/as con problemas de salud. En el hall principal, junto a secretar\u00eda, hemos colocado &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/02\/25\/tapones-para-una-nueva-vida-para-marcos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abTAPONES PARA UNA NUEVA VIDA PARA MARCOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"post_folder":[],"class_list":["post-2620","post","type-post","status-publish","format-standard","hentry","category-campanas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/campanas\/\" rel=\"category tag\">Campa\u00f1as<\/a>","rttpg_excerpt":"Un a\u00f1o m\u00e1s somos Centro de Recogida de Tapones para una Nueva Vida\u00a0de la la Fundaci\u00f3n Seur, los tapones de pl\u00e1stico son llevados por Seur\u00a0a una planta de reciclaje y con el dinero logrado se financian tratamientos m\u00e9dicos y ortopedias para ni\u00f1os\/as con problemas de salud. En el hall principal, junto a secretar\u00eda, hemos colocado&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2620"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2620\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2620"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}