{"id":2669,"date":"2019-03-21T06:42:12","date_gmt":"2019-03-21T06:42:12","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2669"},"modified":"2019-03-21T06:42:12","modified_gmt":"2019-03-21T06:42:12","slug":"los-miedos-de-6-de-primaria","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/03\/21\/los-miedos-de-6-de-primaria\/","title":{"rendered":"LOS MIEDOS DE 6\u00ba DE PRIMARIA"},"content":{"rendered":"<p>Las clases de 6\u00ba de Primaria ya est\u00e1n dise\u00f1ando y preparando el musical de su graduaci\u00f3n, el tema este a\u00f1o son \u00abLos Miedos\u00bb. Hemos conseguido colarnos en su ensayo, para poder mostraros un adelanto.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/S00A7pXH9wc\" width=\"425\" height=\"350\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las clases de 6\u00ba de Primaria ya est\u00e1n dise\u00f1ando y preparando el musical de su graduaci\u00f3n, el tema este a\u00f1o son \u00abLos Miedos\u00bb. Hemos conseguido colarnos en su ensayo, para poder mostraros un adelanto.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"post_folder":[],"class_list":["post-2669","post","type-post","status-publish","format-standard","hentry","category-6-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/6-primaria\/\" rel=\"category tag\">6\u00ba Primaria<\/a>","rttpg_excerpt":"Las clases de 6\u00ba de Primaria ya est\u00e1n dise\u00f1ando y preparando el musical de su graduaci\u00f3n, el tema este a\u00f1o son \u00abLos Miedos\u00bb. Hemos conseguido colarnos en su ensayo, para poder mostraros un adelanto.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2669"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2669\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2669"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}