{"id":2718,"date":"2019-04-03T12:33:12","date_gmt":"2019-04-03T12:33:12","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2718"},"modified":"2019-04-03T12:33:12","modified_gmt":"2019-04-03T12:33:12","slug":"comunicado-cam-pruebas-3-e-primaria","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/04\/03\/comunicado-cam-pruebas-3-e-primaria\/","title":{"rendered":"COMUNICADO CAM PRUEBAS 3\u00ba E.PRIMARIA"},"content":{"rendered":"<p>Estimados padres, madres o tutores:<\/p>\n<p>\u00a0<\/p>\n<p>Nos dirigimos a ustedes para informarles de que su hijo o hija, al igual que todos los alumnos de 3\u00ba de Educaci\u00f3n Primaria, est\u00e1 participando en estos d\u00edas en la Evaluaci\u00f3n Individualizada de Tercero de Primaria del curso 2018-2019. La finalidad de esta prueba es comprobar el grado de dominio de las destrezas, capacidades y habilidades en expresi\u00f3n y comprensi\u00f3n oral y escrita, c\u00e1lculo y resoluci\u00f3n de problemas en relaci\u00f3n con el grado de adquisici\u00f3n de la competencia en comunicaci\u00f3n ling\u00fc\u00edstica y de la competencia matem\u00e1tica, tal como establece la normativa vigente.<\/p>\n<p>\u00a0<\/p>\n<p>Se completar\u00e1 el estudio con los cuestionarios de contexto, dirigidos a las familias, profesores y director del centro, que proporcionar\u00e1n informaci\u00f3n sobre las condiciones socioecon\u00f3micas y culturales de los centros para la contextualizaci\u00f3n de los resultados obtenidos, asociados a la adquisici\u00f3n de las competencias evaluadas. Por ello, las familias que tengan alumnos en 3\u00ba de Primaria cumplimentar\u00e1n dicho cuestionario, mediante procedimiento on-line. El centro les proporcionar\u00e1 la clave junto con las instrucciones de acceso a la plataforma de grabaci\u00f3n (cuya direcci\u00f3n web es: <a href=\"http:\/\/cuestionariofamilia.complet.es\">http:\/\/cuestionariofamilia.complet.es<\/a>). Si la familia no dispone de los medios inform\u00e1ticos adecuados para su cumplimentaci\u00f3n, el director le facilitar\u00e1 su uso desde el centro. El plazo para cumplimentar y enviar el cuestionario finalizar\u00e1 el 10 de mayo.<\/p>\n<p>\u00a0<\/p>\n<p>Para garantizar la confidencialidad de las respuestas, el sistema no permite una grabaci\u00f3n parcial de los datos, debe cumplimentarse en una \u00fanica sesi\u00f3n y <strong>ENVIAR <\/strong>para que las respuestas queden grabadas. Si se abandona la plataforma sin terminar, se borrar\u00e1n sus respuestas y deber\u00e1 comenzar de nuevo el proceso. Como modo de preservar la confidencialidad de las respuestas, una vez enviado el cuestionario, nadie podr\u00e1 acceder al mismo con dicha clave.<\/p>\n<p>\u00a0<\/p>\n<p>Las claves de cada familia podr\u00e1n ser tambi\u00e9n utilizadas por esas familias para descargarse el informe con los resultados del alumno, una vez corregidas las pruebas, en la siguiente direcci\u00f3n web: <a href=\"http:\/\/informealumno.complet.es\">http:\/\/informealumno.complet.es<\/a>. Los resultados de esta evaluaci\u00f3n de 3\u00ba de Educaci\u00f3n Primaria ofrecer\u00e1n a las familias informaci\u00f3n sobre el progreso de sus hijos en el sistema educativo. Esta informaci\u00f3n no condicionar\u00e1 la promoci\u00f3n al curso siguiente. Asimismo, estos resultados proporcionar\u00e1n al centro docente, a sus profesores, y a la Administraci\u00f3n educativa, elementos clave para la reflexi\u00f3n y toma de decisiones orientadas a la mejora de la educaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p>A trav\u00e9s de la presente carta les agradecemos su participaci\u00f3n en estas evaluaciones.<\/p>\n<p>\u00a0<\/p>\n<p>Reciban un cordial saludo<\/p>\n<p>\u00a0<\/p>\n<p>El Director\/a \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Aranjuez, 03 de abril de 2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimados padres, madres o tutores: \u00a0 Nos dirigimos a ustedes para informarles de que su hijo o hija, al igual que todos los alumnos de 3\u00ba de Educaci\u00f3n Primaria, est\u00e1 participando en estos d\u00edas en la Evaluaci\u00f3n Individualizada de Tercero de Primaria del curso 2018-2019. La finalidad de esta prueba es comprobar el grado de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/04\/03\/comunicado-cam-pruebas-3-e-primaria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abCOMUNICADO CAM PRUEBAS 3\u00ba E.PRIMARIA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"post_folder":[],"class_list":["post-2718","post","type-post","status-publish","format-standard","hentry","category-menu"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/menu\/\" rel=\"category tag\">Menu Superior Central<\/a>","rttpg_excerpt":"Estimados padres, madres o tutores: \u00a0 Nos dirigimos a ustedes para informarles de que su hijo o hija, al igual que todos los alumnos de 3\u00ba de Educaci\u00f3n Primaria, est\u00e1 participando en estos d\u00edas en la Evaluaci\u00f3n Individualizada de Tercero de Primaria del curso 2018-2019. La finalidad de esta prueba es comprobar el grado de&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2718"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2718\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2718"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}