{"id":2728,"date":"2019-04-16T09:55:43","date_gmt":"2019-04-16T09:55:43","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2728"},"modified":"2019-04-16T09:55:43","modified_gmt":"2019-04-16T09:55:43","slug":"el-flautista-de-hamelin-interpretado-por-show-musical","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/04\/16\/el-flautista-de-hamelin-interpretado-por-show-musical\/","title":{"rendered":"EL FLAUTISTA DE HAMELIN INTERPRETADO POR SHOW MUSICAL"},"content":{"rendered":"<p>El mi\u00e9rcoles 10 de abril, antes de la Panto de los maestros\/as de Colegio, los ni\u00f1os y ni\u00f1as de la actividad extraescolar Show Musical, dirigidos por Ana Hidalgo de Tel\u00f3n Aparte y Vidas de Fuego, interpretaron el cuento del Flautista de Hamelin, en el sal\u00f3n de actos del IES Domenico Scarlatti de Aranjuez.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/AJ9hBfUHO_0\" width=\"425\" height=\"350\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mi\u00e9rcoles 10 de abril, antes de la Panto de los maestros\/as de Colegio, los ni\u00f1os y ni\u00f1as de la actividad extraescolar Show Musical, dirigidos por Ana Hidalgo de Tel\u00f3n Aparte y Vidas de Fuego, interpretaron el cuento del Flautista de Hamelin, en el sal\u00f3n de actos del IES Domenico Scarlatti de Aranjuez.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"post_folder":[],"class_list":["post-2728","post","type-post","status-publish","format-standard","hentry","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"El mi\u00e9rcoles 10 de abril, antes de la Panto de los maestros\/as de Colegio, los ni\u00f1os y ni\u00f1as de la actividad extraescolar Show Musical, dirigidos por Ana Hidalgo de Tel\u00f3n Aparte y Vidas de Fuego, interpretaron el cuento del Flautista de Hamelin, en el sal\u00f3n de actos del IES Domenico Scarlatti de Aranjuez.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2728"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2728\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2728"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}