{"id":2770,"date":"2019-05-15T12:53:13","date_gmt":"2019-05-15T12:53:13","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2770"},"modified":"2019-05-15T12:53:13","modified_gmt":"2019-05-15T12:53:13","slug":"acta-xvi-asamblea-de-pitufos-14-de-mayo","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/05\/15\/acta-xvi-asamblea-de-pitufos-14-de-mayo\/","title":{"rendered":"ACTA XVI ASAMBLEA DE PITUFOS 14 DE MAYO"},"content":{"rendered":"<p><strong>\u00a0<\/strong><strong>Faltan: 4\u00baA, 3\u00baB, 3\u00baC y 2\u00baC<\/strong><\/p>\n<p><strong>TEMAS Y ACUERDOS<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>1) Revisi\u00f3n X Cross Carlos III y recuento de alumnos\/as de cada clase que han participado (cada alumnos\/a que haya corrido recibe 1 Charlie Point).<\/strong><\/p>\n<p><strong>Se valora muy positivamente la actividad, en esta edici\u00f3n ha habido m\u00e1s participaci\u00f3n de los ni\u00f1os y ni\u00f1as del Colegio.<\/strong><\/p>\n<p><strong>Se da un Charlie Point a cada clase por alumno\/a o familiar que haya participado y otro extra por posici\u00f3n destacada en el Cross (entre los 3 primeros).<\/strong><\/p>\n<p><strong>6\u00baA=9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 6\u00bab=1\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 6\u00baC=0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00baA=6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00baB=5\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00baC=13<\/strong><\/p>\n<p><strong>4\u00baB=3\u00a0 \u00a0 \u00a0 \u00a0 4\u00baC=6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3\u00baA=5\u00a0 \u00a0 \u00a0 3\u00baC=6\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2\u00baA=14\u00a0\u00a0\u00a0\u00a0 2\u00baB=10\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/qhC1xriR6_Y\" width=\"425\" height=\"350\"><\/iframe><\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>2) Actividades extraescolares (revisi\u00f3n y propuestas para el curso que viene) Valorar en clase las actividades extraescolares en las que participe alg\u00fan miembro de cada clase, para compartirlo en la Asamblea y trasladarlo al AMPA, equipo directivo, claustro de profesores, Ayuntamiento y resto de la Comunidad Educativa.<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>Se valora muy positivamente la mayor\u00eda de actividades, sobre toda las nuevas que se propusieron desde la Asamblea de Pitufos el curso pasado (cocinillas, dibujo y musical), la actividad de costura creativa se propuso al AMPA y al Ayuntamiento pero no la ofertaron. Este a\u00f1o se volver\u00e1 a proponer desde la Asamblea de Pitufos, adem\u00e1s creamos que mejorar\u00eda nuestra oferta de actividades extraescolares una propuesta de deportes m\u00e1s amplia, nuestra idea es que haya una actividad de deportes alternativos, que durante el curso se \u00a0practiquen varias modalidades deportivas (b\u00e9isbol, pin-pong, voleybol, \u2026.).<\/strong><\/p>\n<p><strong>La actividad de los Primeros del Cole, es la peor valorada, falta de material, falta de actividades, solicitan que haya m\u00e1s d\u00edas gimnasio y patio, se transmitir\u00e1 a la empresa (Getting Better) que realiza el servicio.<\/strong><\/p>\n<p><strong>\u00a03)\u00a0<\/strong><strong>Ruegos y preguntas<\/strong><\/p>\n<p><strong>Se proponen m\u00e1s juegos para Divertipatio (twistter, bal\u00f3n de baloncesto, borrador de pizarras, dooble, letra a letra); sobre los juegos de mesa se les explica que el AMPA y un grupo de familias del Colegio son los encargados de adecuar las mesas para los patio. Tambi\u00e9n se les explica que est\u00e1 pendiente que los padres\/madres contin\u00faen pintando juegos en las zonas asfaltadas de los recreos, sobre todo en el patio de los mayores, que no hay nada.<\/strong><\/p>\n<p><strong>Otra idea que surge es hacer otra Semana de la Convivencia, se les comenta que en las actividades de Centro se intenta que haya momentos conjuntos.<\/strong><\/p>\n<p><strong>Solicitan venir todos los viernes sin uniforme, hablamos de la necesidad de no hacer por hacer, que todo tiene que tener un objetivo y un motivo, que las veces que se ha venido vestidos distintos era por alguna circunstancia, se les explica que hay clases que viene vestidos cuando son los encargados del d\u00eda o tienen el show and tell, \u2026.<\/strong><\/p>\n<p><strong>Debatimos sobre la posibilidad de hacer las mini-disco tem\u00e1ticas y poder venir con adornos relativos.<\/strong><\/p>\n<p><strong>Piden m\u00e1s convivencia con otros Colegios.<\/strong><\/p>\n<p><strong>Solicitan realizar Noche y Tarde M\u00e1gicas en Primaria.<\/strong><\/p>\n<p><b>PR\u00d3XIMA ASAMBLEA MARTES 28 DE MAYO<\/b><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>\u00a0<\/strong><strong>Faltan: 4\u00baA, 3\u00baB, 3\u00baC y 2\u00baC<\/strong><\/p>\n<p><strong>TEMAS Y ACUERDOS<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>1) Revisi\u00f3n X Cross Carlos III y recuento de alumnos\/as de cada clase que han participado (cada alumnos\/a que haya corrido recibe 1 Charlie Point).<\/strong><\/p>\n<p><strong>Se valora muy positivamente la actividad, en esta edici\u00f3n ha habido m\u00e1s participaci\u00f3n de los ni\u00f1os y ni\u00f1as del Colegio.<\/strong><\/p>\n<p><strong>Se da un Charlie Point a cada clase por alumno\/a o familiar que haya participado y otro extra por posici\u00f3n destacada en el Cross (entre los 3 primeros).<\/strong><\/p>\n<p><strong>6\u00baA=9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 6\u00bab=1\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 6\u00baC=0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00baA=6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00baB=5\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5\u00baC=13<\/strong><\/p>\n<p><strong>4\u00baB=3\u00a0 \u00a0 \u00a0 \u00a0 4\u00baC=6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3\u00baA=5\u00a0 \u00a0 \u00a0 3\u00baC=6\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 2\u00baA=14\u00a0\u00a0\u00a0\u00a0 2\u00baB=10\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/qhC1xriR6_Y\" width=\"425\" height=\"350\"><\/iframe><\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>2) Actividades extraescolares (revisi\u00f3n y propuestas para el curso que viene) Valorar en clase las actividades extraescolares en las que participe alg\u00fan miembro de cada clase, para compartirlo en la Asamblea y trasladarlo al AMPA, equipo directivo, claustro de profesores, Ayuntamiento y resto de la Comunidad Educativa.<\/strong><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"post_folder":[],"class_list":["post-2770","post","type-post","status-publish","format-standard","hentry","category-actas-y-convocatorias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/pitufos-asamblea-de-alumnos-2\/actas-y-convocatorias\/\" rel=\"category tag\">Actas y Convocatorias<\/a>","rttpg_excerpt":"\u00a0Faltan: 4\u00baA, 3\u00baB, 3\u00baC y 2\u00baC TEMAS Y ACUERDOS \u00a0 1) Revisi\u00f3n X Cross Carlos III y recuento de alumnos\/as de cada clase que han participado (cada alumnos\/a que haya corrido recibe 1 Charlie Point). Se valora muy positivamente la actividad, en esta edici\u00f3n ha habido m\u00e1s participaci\u00f3n de los ni\u00f1os y ni\u00f1as del Colegio.&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2770"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2770\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2770"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}