{"id":2880,"date":"2019-09-09T09:27:11","date_gmt":"2019-09-09T09:27:11","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2880"},"modified":"2019-09-09T09:27:11","modified_gmt":"2019-09-09T09:27:11","slug":"listado-material-3-de-primaria-curso-2019-20","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/09\/09\/listado-material-3-de-primaria-curso-2019-20\/","title":{"rendered":"LISTADO MATERIAL 3\u00ba DE PRIMARIA CURSO 2019\/20"},"content":{"rendered":"<p>+ Estuche (no de metal) marcado con su nombre:<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; L\u00e1piz<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; Goma de borrar<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; Tijera de punta roma<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; Regla peque\u00f1a transparente r\u00edgida (de estuche)<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; Sacapuntas<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; Bol\u00edgrafos rojo y azul tipo Bic (no Pilot)<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; 1 transportador transparente peque\u00f1o<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; Rotuladores<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; Pinturas de madera<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; 1 pegamento en barra<\/p>\n<p>\u00a0 \u00a0 \u00a0&#8211; 1 comp\u00e1s (para ser utilizado en 3\u00ba pero sobre todo en 4\u00ba de Primaria)<\/p>\n<p>+ 3 carpetas de gomas de tama\u00f1o folio con solapas (una roja, otra azul y otra amarilla)<\/p>\n<p>+ 5 cuadernos grandes de 100 hojas con espiral (tama\u00f1o folio, con margen, que no tengan hojas perforadas y de cuadritos de 4 mm)<\/p>\n<p>+ Un diccionario de espa\u00f1ol<\/p>\n<p>+ Un diccionario de ingl\u00e9s-espa\u00f1ol<\/p>\n<p>+ 3 fotos recientes tama\u00f1o carnet<\/p>\n<p>+ 1 agenda con p\u00e1gina completa por d\u00eda<\/p>\n<p>+ 10 fundas de pl\u00e1stico metidas en las carpetas (3 fundillas+3+4) con el nombre puesto en el margen inferior derecho.<\/p>\n<p>\u00a0<\/p>\n<p>*El comp\u00e1s y el transportador se deber\u00e1n traer cuando lo indique la tutora, para evitar que se extrav\u00eden o deterioren.<\/p>\n<p>Ingl\u00e9s: no comprar activity book.<\/p>\n<p>\u00a0<\/p>\n<p>IMPORTANTE: Todo el material tiene que venir marcado con su nombre (los libros, una vez que sean comprobados).<\/p>\n<p>Traer los libros de texto de todos los trimestres antes del\u00a0<strong>jueves 19 de septiembre<\/strong>. Una vez comprobados, los ni\u00f1os\/as se llevar\u00e1n a casa los que no vayan a ser utilizados en el trimestre.<\/p>\n<p>\u00a0<\/p>\n<p>Muchas gracias por su colaboraci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Las tutoras de 3\u00ba de Primaria.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>+ Estuche (no de metal) marcado con su nombre: \u00a0 \u00a0 \u00a0&#8211; L\u00e1piz \u00a0 \u00a0 \u00a0&#8211; Goma de borrar \u00a0 \u00a0 \u00a0&#8211; Tijera de punta roma \u00a0 \u00a0 \u00a0&#8211; Regla peque\u00f1a transparente r\u00edgida (de estuche) \u00a0 \u00a0 \u00a0&#8211; Sacapuntas \u00a0 \u00a0 \u00a0&#8211; Bol\u00edgrafos rojo y azul tipo Bic (no Pilot) \u00a0 \u00a0 \u00a0&#8211; 1 transportador &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/09\/09\/listado-material-3-de-primaria-curso-2019-20\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLISTADO MATERIAL 3\u00ba DE PRIMARIA CURSO 2019\/20\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"post_folder":[],"class_list":["post-2880","post","type-post","status-publish","format-standard","hentry","category-3-primaria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/3-primaria\/\" rel=\"category tag\">3\u00ba Primaria<\/a>","rttpg_excerpt":"+ Estuche (no de metal) marcado con su nombre: \u00a0 \u00a0 \u00a0&#8211; L\u00e1piz \u00a0 \u00a0 \u00a0&#8211; Goma de borrar \u00a0 \u00a0 \u00a0&#8211; Tijera de punta roma \u00a0 \u00a0 \u00a0&#8211; Regla peque\u00f1a transparente r\u00edgida (de estuche) \u00a0 \u00a0 \u00a0&#8211; Sacapuntas \u00a0 \u00a0 \u00a0&#8211; Bol\u00edgrafos rojo y azul tipo Bic (no Pilot) \u00a0 \u00a0 \u00a0&#8211; 1 transportador&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2880"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2880\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2880"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}