{"id":2947,"date":"2019-10-11T12:46:46","date_gmt":"2019-10-11T12:46:46","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2947"},"modified":"2019-10-11T12:46:46","modified_gmt":"2019-10-11T12:46:46","slug":"acto-de-clausura-del-proyecto-de-bienvenida-2019","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/10\/11\/acto-de-clausura-del-proyecto-de-bienvenida-2019\/","title":{"rendered":"ACTO DE CLAUSURA DEL PROYECTO DE BIENVENIDA 2019"},"content":{"rendered":"<p>El acto del Clausura del Proyecto de Bienvenida es el broche final al Inicio de Curso, cuya finalidad era crear un buen clima de convivencia para constituir unos buenos cimientos que favorezcan el aprendizaje.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/9RGAdRLf4Y4\" width=\"425\" height=\"350\"><\/iframe><\/p>\n<p>Comenzamos todos juntos, en el patio de 1\u00ba y 2\u00ba de Primaria, Alejandra, Jaime y Mariana, alumnos\/as de las 3 clases de 6\u00ba de Primaria, fueron los maestros ceremonias y se encargaron de ir explicando el Acto de Clausura del Proyecto de Bienvenida del Curso. Tras una breve explicaci\u00f3n inicial y la entrada triunfal de Charlie, cantamos todos juntos el lema del inicio del curso \u00abAl otro lado\u00bb, Iz\u00e1n miembro de \u00abThe Carlos III Rock and Roll Band\u00bb nos gu\u00edo con su guitarra. Tras este primer paso un representante de cada clase sali\u00f3 a leer el pr\u00f3posito\/deseo de su grupo y a compartirlo con los dem\u00e1s, tras la lectura Charlie le entregamos nuestros deseos a Charlie, que fue el encargado de trepar al \u00ab\u00c1rbol de la Amistad\u00bb y colgarlos para que los tengamos presentes.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EGln_mHW4AAx7Yj?format=jpg&amp;name=240x240\" alt=\"Imagen\" \/><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EGln-fgXUAEYDm5?format=jpg&amp;name=240x240\" alt=\"Imagen\" \/><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EGloAhoX4AE2K_E?format=jpg&amp;name=240x240\" alt=\"Imagen\" \/><\/p>\n<p>Tras esta primera parte, todos juntos cantamos y bailamos nuestra canci\u00f3n de la amistas \u00abLa Amista que Quiero\u00bb. Para terminar nos despedimos cantando nuestro himno \u00abYou are always on my mind\u00bb.<\/p>\n<p>Los alumnos y alumnas de 6\u00ba de Primaria fueron los encargados de repartir al azar el marcap\u00e1ginas realizado por cada ni\u00f1o y ni\u00f1a del Colegio.\u00a0<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EGvi-3OXUAA1K-7?format=jpg&amp;name=small\" alt=\"Imagen\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acto del Clausura del Proyecto de Bienvenida es el broche final al Inicio de Curso, cuya finalidad era crear un buen clima de convivencia para constituir unos buenos cimientos que favorezcan el aprendizaje. Comenzamos todos juntos, en el patio de 1\u00ba y 2\u00ba de Primaria, Alejandra, Jaime y Mariana, alumnos\/as de las 3 clases &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/10\/11\/acto-de-clausura-del-proyecto-de-bienvenida-2019\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abACTO DE CLAUSURA DEL PROYECTO DE BIENVENIDA 2019\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-2947","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"El acto del Clausura del Proyecto de Bienvenida es el broche final al Inicio de Curso, cuya finalidad era crear un buen clima de convivencia para constituir unos buenos cimientos que favorezcan el aprendizaje. Comenzamos todos juntos, en el patio de 1\u00ba y 2\u00ba de Primaria, Alejandra, Jaime y Mariana, alumnos\/as de las 3 clases&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2947"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2947\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2947"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}