{"id":2949,"date":"2019-10-13T07:04:21","date_gmt":"2019-10-13T07:04:21","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2949"},"modified":"2019-10-13T07:04:21","modified_gmt":"2019-10-13T07:04:21","slug":"iniciacion-al-deporte-para-5-anos-2","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/10\/13\/iniciacion-al-deporte-para-5-anos-2\/","title":{"rendered":"INICIACI\u00d3N AL DEPORTE PARA 5 A\u00d1OS (CURSO 2019-2020)"},"content":{"rendered":"<p>Con el prop\u00f3sito de que nuestros ni\u00f1os\/as se inicien el deporte, se va a llevar a cabo la actividad de I<strong>niciaci\u00f3n al Deporte<\/strong> donde\u00a0 vamos a iniciarnos en diferentes modalidades deportivas (f\u00fatbol , baloncesto, balonmano, atletismo\u2026).<\/p>\n<p>Est\u00e1 actividad va dirigida a los alumnos \/as de 3\u00ba de Educaci\u00f3n Infantil (clases de 5 a\u00f1os) y ser\u00e1n los lunes de 16.00 A 17.00 y los jueves de 17.00 A 18.00 <strong>, empezando el pr\u00f3ximo 28 de OCTUBRE.<\/strong><\/p>\n<p>Para apuntarse rellenar la hoja de inscripci\u00f3n y entregarla en el caj\u00f3n del AMPA (en secretar\u00eda) o darla al monitor deportivo (Samuel).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el prop\u00f3sito de que nuestros ni\u00f1os\/as se inicien el deporte, se va a llevar a cabo la actividad de Iniciaci\u00f3n al Deporte donde\u00a0 vamos a iniciarnos en diferentes modalidades deportivas (f\u00fatbol , baloncesto, balonmano, atletismo\u2026). Est\u00e1 actividad va dirigida a los alumnos \/as de 3\u00ba de Educaci\u00f3n Infantil (clases de 5 a\u00f1os) y ser\u00e1n &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/10\/13\/iniciacion-al-deporte-para-5-anos-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abINICIACI\u00d3N AL DEPORTE PARA 5 A\u00d1OS (CURSO 2019-2020)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"post_folder":[],"class_list":["post-2949","post","type-post","status-publish","format-standard","hentry","category-5-anos"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/alumnos\/infantil\/5-anos\/\" rel=\"category tag\">5 A\u00f1os<\/a>","rttpg_excerpt":"Con el prop\u00f3sito de que nuestros ni\u00f1os\/as se inicien el deporte, se va a llevar a cabo la actividad de Iniciaci\u00f3n al Deporte donde\u00a0 vamos a iniciarnos en diferentes modalidades deportivas (f\u00fatbol , baloncesto, balonmano, atletismo\u2026). Est\u00e1 actividad va dirigida a los alumnos \/as de 3\u00ba de Educaci\u00f3n Infantil (clases de 5 a\u00f1os) y ser\u00e1n&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2949"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2949\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2949"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}