{"id":2974,"date":"2019-10-22T12:44:07","date_gmt":"2019-10-22T12:44:07","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=2974"},"modified":"2019-10-22T12:44:07","modified_gmt":"2019-10-22T12:44:07","slug":"formacion-aprendizaje-basado-en-proyectos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/10\/22\/formacion-aprendizaje-basado-en-proyectos\/","title":{"rendered":"FORMACI\u00d3N: APRENDIZAJE BASADO EN PROYECTOS"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">En el curso \u00abDesarrollo de Proyecto Steam\u00bb en el Centro Territorial de Formaci\u00f3n de Madrid Oeste\u00bb\u00a0<\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">tras ver los pilares b\u00e1sicos (M\u00e9todo cient\u00edfico, Creatividad y\u00a0Aprendizaje basado en el pensamiento)\u00a0tratan la metodolog\u00eda\u00a0<span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Aprendizaje Basado en Proyectos.<\/span><\/span><\/p>\n<p>En este curso, estamos aprendiendo a:<\/p>\n<p>1. Desarrollar estrategias did\u00e1cticas que favorezcan el pensamiento cient\u00edfico en el entorno sociocultural.<br \/>2. Conocer y practicar din\u00e1micas que fomenten el aprendizaje activo y creativo.<br \/>3. Aprender a poner en marcha un proyecto STEM \u2013 STEAM.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EHaxs3uWwAAJeWO?format=jpg&amp;name=240x240\" alt=\"Imagen\" width=\"509\" height=\"382\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EHaxtZgWwAELANt?format=jpg&amp;name=small\" alt=\"Imagen\" width=\"215\" height=\"382\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EHaxt4ZW4AE5p1K?format=jpg&amp;name=small\" alt=\"Imagen\" width=\"364\" height=\"646\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EHaxuV5X0AAKAGY?format=jpg&amp;name=small\" alt=\"Imagen\" width=\"364\" height=\"648\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el curso \u00abDesarrollo de Proyecto Steam\u00bb en el Centro Territorial de Formaci\u00f3n de Madrid Oeste\u00bb\u00a0tras ver los pilares b\u00e1sicos (M\u00e9todo cient\u00edfico, Creatividad y\u00a0Aprendizaje basado en el pensamiento)\u00a0tratan la metodolog\u00eda\u00a0Aprendizaje Basado en Proyectos. En este curso, estamos aprendiendo a: 1. Desarrollar estrategias did\u00e1cticas que favorezcan el pensamiento cient\u00edfico en el entorno sociocultural.2. Conocer y practicar &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/10\/22\/formacion-aprendizaje-basado-en-proyectos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFORMACI\u00d3N: APRENDIZAJE BASADO EN PROYECTOS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"post_folder":[],"class_list":["post-2974","post","type-post","status-publish","format-standard","hentry","category-stem-destacado"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/stem-destacado\/\" rel=\"category tag\">STEM<\/a>","rttpg_excerpt":"En el curso \u00abDesarrollo de Proyecto Steam\u00bb en el Centro Territorial de Formaci\u00f3n de Madrid Oeste\u00bb\u00a0tras ver los pilares b\u00e1sicos (M\u00e9todo cient\u00edfico, Creatividad y\u00a0Aprendizaje basado en el pensamiento)\u00a0tratan la metodolog\u00eda\u00a0Aprendizaje Basado en Proyectos. En este curso, estamos aprendiendo a: 1. Desarrollar estrategias did\u00e1cticas que favorezcan el pensamiento cient\u00edfico en el entorno sociocultural.2. Conocer y practicar&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=2974"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/2974\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=2974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=2974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=2974"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=2974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}