{"id":3016,"date":"2019-11-10T09:49:36","date_gmt":"2019-11-10T09:49:36","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=3016"},"modified":"2019-11-10T09:49:36","modified_gmt":"2019-11-10T09:49:36","slug":"pequenas-grandes-costureros","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/11\/10\/pequenas-grandes-costureros\/","title":{"rendered":"PEQUE\u00d1AS GRANDES COSTUREROS"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Esta semana en Costura Creativa con Mar\u00eda (Mis Cositas)\u00a0<\/span>algunos ni\u00f1os y ni\u00f1as terminaron murci\u00e9lagos, todos los peque\u00f1os\/as costureros comenzaron a recordar la cadeneta en ganchillo y aprendieron el siguiente punto el punto bajo o enano para hacer nuestro marcap\u00e1ginas.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EIwY-imWsAEgUJi?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EIwY_BqWkAAyqxT?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EIwY_XRWoAI8nh0?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EIwY_1xWoAA4KAR?format=jpg&amp;name=360x360\" alt=\"Imagen\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana en Costura Creativa con Mar\u00eda (Mis Cositas)\u00a0algunos ni\u00f1os y ni\u00f1as terminaron murci\u00e9lagos, todos los peque\u00f1os\/as costureros comenzaron a recordar la cadeneta en ganchillo y aprendieron el siguiente punto el punto bajo o enano para hacer nuestro marcap\u00e1ginas.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"post_folder":[],"class_list":["post-3016","post","type-post","status-publish","format-standard","hentry","category-extraescolares"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/extraescolares\/\" rel=\"category tag\">NUESTRAS ACTIVIDADES EXTRAESCOLARES<\/a>","rttpg_excerpt":"Esta semana en Costura Creativa con Mar\u00eda (Mis Cositas)\u00a0algunos ni\u00f1os y ni\u00f1as terminaron murci\u00e9lagos, todos los peque\u00f1os\/as costureros comenzaron a recordar la cadeneta en ganchillo y aprendieron el siguiente punto el punto bajo o enano para hacer nuestro marcap\u00e1ginas.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=3016"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3016\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=3016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=3016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=3016"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=3016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}