{"id":3062,"date":"2019-11-24T09:19:33","date_gmt":"2019-11-24T09:19:33","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=3062"},"modified":"2019-11-24T09:19:33","modified_gmt":"2019-11-24T09:19:33","slug":"practicas-de-ket-y-pet-2","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/11\/24\/practicas-de-ket-y-pet-2\/","title":{"rendered":"PR\u00c1CTICAS DE KET Y PET"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>Con motivo de la preparaci\u00f3n de las pruebas de nivel de ingl\u00e9s de 6\u00ba (KET\/A2 y PET\/B1) y para que vuestros hijos\/as puedan ya ir practicando on-line desde casa, os adjuntamos un listado de webs desde d\u00f3nde podr\u00e1n practicar los distintos tipos de ejercicios de los que se componen las pruebas:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.cambridgeenglish.org\/learning-english\/exam-preparation\/\">https:\/\/www.cambridgeenglish.org\/learning-english\/exam-preparation\/<\/a><\/li>\n<li><a href=\"https:\/\/www.examenglish.com\/PET\/PET_for_schools.html\">https:\/\/www.examenglish.com\/PET\/PET_for_schools.html#<\/a><\/li>\n<li><a href=\"https:\/\/www.flo-joe.co.uk\/\">https:\/\/www.flo-joe.co.uk\/<\/a><\/li>\n<li><a href=\"https:\/\/www.englishaula.com\/en\/english-exam-preparation\/\">https:\/\/www.englishaula.com\/en\/english-exam-preparation\/<\/a><\/li>\n<li><a href=\"https:\/\/cambridgemb.com\/recursos-ejemplos-modelos-examenes\/#petfs\">https:\/\/cambridgemb.com\/recursos-ejemplos-modelos-examenes\/#petfs<\/a><\/li>\n<li><a href=\"https:\/\/cambridgemb.com\/recursos-ejemplos-modelos-examenes\/#a2-keyfs\">https:\/\/cambridgemb.com\/recursos-ejemplos-modelos-examenes\/#a2-keyfs<\/a>\u00a0<\/li>\n<\/ul>\n<p>Gracias por vuestra colaboraci\u00f3n.<\/p>\n<p>Un saludo.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Maestros de 6\u00ba de Primaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Con motivo de la preparaci\u00f3n de las pruebas de nivel de ingl\u00e9s de 6\u00ba (KET\/A2 y PET\/B1) y para que vuestros hijos\/as puedan ya ir practicando on-line desde casa, os adjuntamos un listado de webs desde d\u00f3nde podr\u00e1n practicar los distintos tipos de ejercicios de los que se componen las pruebas: https:\/\/www.cambridgeenglish.org\/learning-english\/exam-preparation\/ https:\/\/www.examenglish.com\/PET\/PET_for_schools.html# &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/11\/24\/practicas-de-ket-y-pet-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPR\u00c1CTICAS DE KET Y PET\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"post_folder":[],"class_list":["post-3062","post","type-post","status-publish","format-standard","hentry","category-pruebas-externas"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/bilingueismo\/pruebas-externas\/\" rel=\"category tag\">Pruebas externas<\/a>","rttpg_excerpt":"Estimadas familias: Con motivo de la preparaci\u00f3n de las pruebas de nivel de ingl\u00e9s de 6\u00ba (KET\/A2 y PET\/B1) y para que vuestros hijos\/as puedan ya ir practicando on-line desde casa, os adjuntamos un listado de webs desde d\u00f3nde podr\u00e1n practicar los distintos tipos de ejercicios de los que se componen las pruebas: https:\/\/www.cambridgeenglish.org\/learning-english\/exam-preparation\/ https:\/\/www.examenglish.com\/PET\/PET_for_schools.html#&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=3062"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3062\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=3062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=3062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=3062"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=3062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}