{"id":3065,"date":"2019-11-25T12:46:50","date_gmt":"2019-11-25T12:46:50","guid":{"rendered":"http:\/\/quieropaginaweb.es\/wp\/?p=3065"},"modified":"2019-11-25T12:46:50","modified_gmt":"2019-11-25T12:46:50","slug":"iv-semana-de-la-convivencia-colegio-carlos-iii","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/2019\/11\/25\/iv-semana-de-la-convivencia-colegio-carlos-iii\/","title":{"rendered":"IV SEMANA DE LA CONVIVENCIA COLEGIO CARLOS III"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Estamos ultimando las actividades para la IV Semana de la Convivencia Colegio Carlos III \u00abJuntos Convivimos para aprender y disfrutar\u00bb<\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">, para fomentar, desde la experiencia, la mejora de la convivencia escolar, social. Desarrollar los valores del respeto, la cooperaci\u00f3n, la solidaridad y la empat\u00eda.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/EKNnwR8XUAAE3xU?format=jpg&amp;name=medium\" alt=\"Imagen\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos ultimando las actividades para la IV Semana de la Convivencia Colegio Carlos III \u00abJuntos Convivimos para aprender y disfrutar\u00bb, para fomentar, desde la experiencia, la mejora de la convivencia escolar, social. Desarrollar los valores del respeto, la cooperaci\u00f3n, la solidaridad y la empat\u00eda. \u00a0 \u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"post_folder":[],"class_list":["post-3065","post","type-post","status-publish","format-standard","hentry","category-actividades-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cp.carlostercero.aranjuez","author_link":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/author\/cuenta_cp-carlostercero-aranjuez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/category\/noticias\/actividades-noticias\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"Estamos ultimando las actividades para la IV Semana de la Convivencia Colegio Carlos III \u00abJuntos Convivimos para aprender y disfrutar\u00bb, para fomentar, desde la experiencia, la mejora de la convivencia escolar, social. Desarrollar los valores del respeto, la cooperaci\u00f3n, la solidaridad y la empat\u00eda. \u00a0 \u00a0","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/comments?post=3065"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/posts\/3065\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/media?parent=3065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/categories?post=3065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/tags?post=3065"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.carlostercero.aranjuez\/index.php\/wp-json\/wp\/v2\/post_folder?post=3065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}